{"id":8510,"date":"2015-12-21T10:30:56","date_gmt":"2015-12-21T08:30:56","guid":{"rendered":"http:\/\/www.ensembleinter.com\/accents-online\/?p=8510"},"modified":"2015-12-21T10:30:56","modified_gmt":"2015-12-21T08:30:56","slug":"grand-entretien-avec-jerrold-levinson-philosophe","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/","title":{"rendered":"Grand entretien avec Jerrold Levinson, philosophe."},"content":{"rendered":"<p><a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/12\/Levinson-NB.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8511\" alt=\"Levinson-NB\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/12\/Levinson-NB.jpg\" width=\"492\" height=\"392\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/12\/Levinson-NB.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/12\/Levinson-NB-300x239.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><br \/>\n<span style=\"color: #000080;\"><em><span style=\"font-size: large;\">P<\/span>rofesseur de philosophie \u00e0 l\u2019universit\u00e9 du Maryland aux \u00c9tats-Unis, Jerrold Levinson est l\u2019auteur de plusieurs ouvrages et de nombreux articles sur l\u2019esth\u00e9tique, la m\u00e9taphysique, l\u2019\u00e9thique et la philosophie de l\u2019esprit. Connu en France pour ses textes sur la nature de l\u2019art et des propri\u00e9t\u00e9s esth\u00e9tiques, deux importantes traductions ont r\u00e9cemment d\u00e9voil\u00e9 l\u2019\u00e9tendue et la vari\u00e9t\u00e9 de ses travaux sur la musique\u00a0: <\/em>Essais de philosophie de la musique. D\u00e9finition, ontologie, interpr\u00e9tation<em> (\u00e9ditions Vrin) et <\/em>La musique sur le vif. La nature de l\u2019exp\u00e9rience musicale <em>(Presses Universitaires de Rennes). Les questions abord\u00e9es vont de la d\u00e9finition de la musique \u00e0 l\u2019ontologie des \u0153uvres en passant par les probl\u00e8mes plus sp\u00e9cifiques que posent l\u2019interpr\u00e9tation et l\u2019\u00e9coute musicale. C\u2019est autour de cette derni\u00e8re que tourne l\u2019entretien qu\u2019il a bien voulu nous accorder.<\/em><\/span><br \/>\n<b><\/b><b>Dans <i>La musique sur le vif<\/i>, un livre que vous avez publi\u00e9 en 1998, vous d\u00e9fendez l\u2019id\u00e9e selon laquelle la compr\u00e9hension d\u2019une \u0153uvre musicale passe par une \u00e9coute au pr\u00e9sent, attentive \u00e0 ses moments successifs plus qu\u2019\u00e0 sa structure ou \u00e0 sa forme globale. Comprendre la musique, expliquez-vous, c\u2019est la d\u00e9couvrir au fur et \u00e0 mesure qu\u2019elle se donne \u00e0 entendre, avancer et se perdre avec elle jusqu\u2019\u00e0 ce que, une \u00e9coute apr\u00e8s l\u2019autre, son cheminement s\u2019\u00e9claircisse. Cette th\u00e8se que vous appelez \u00ab\u00a0concat\u00e9nationniste\u00a0\u00bb, par opposition \u00e0 l\u2019approche \u00ab\u00a0structurelle\u00a0\u00bb (ou \u00ab\u00a0architectoniciste\u00a0\u00bb) qu\u2019ont pu th\u00e9oriser par exemple Carl Dalhaus et Theodor Adorno, vous a \u00e9t\u00e9 inspir\u00e9 par les travaux d\u2019Edmund Gurney, th\u00e9oricien anglais de la fin du XIXe si\u00e8cle. Cette \u00e9coute bout-\u00e0-bout (\u00ab\u00a0<i>moment-by-moment\u00a0<\/i>\u00bb \u00e9crivez-vous) est pr\u00e9cis\u00e9ment celle que requiert une grande part de la musique dite contemporaine depuis les \u0153uvres atonales d\u2019Arnold Sch\u00f6nberg. Non directionnelle, ath\u00e9matique, sans tonalit\u00e9 ni forme\u00a0identifiable, cette musique oblige l\u2019auditeur \u00e0 s\u2019immerger dans le flux musical, \u00e0 construire son \u00e9coute pas \u00e0 pas, presque note \u00e0 note. Vous faites cependant peu r\u00e9f\u00e9rence aux \u0153uvres contemporaines, privil\u00e9giant les p\u00e9riodes classique et romantique. Cette musique vous int\u00e9resse-t-elle\u00a0? Et pensez-vous que la th\u00e9orie \u00ab\u00a0concat\u00e9nationniste\u00a0\u00bb serait susceptible de rendre compte de la relation que nous entretenons avec ces \u0153uvres\u00a0?<\/b><br \/>\nPour r\u00e9pondre sans attendre \u00e0 vos deux questions\u00a0: oui et encore oui. Il ne faut pas attribuer trop d&rsquo;importance au fait que je me suis pench\u00e9 dans ce livre presque exclusivement sur le r\u00e9pertoire de la musique savante, du baroque jusqu&rsquo;au d\u00e9but du XXe si\u00e8cle. Il est vrai que cette musique repr\u00e9sente le c\u0153ur de ce qui est jou\u00e9 dans nos salles de concert m\u00eame de nos jours, mais il y a, en dehors de \u00e7a, deux choses qui ont d\u00e9termin\u00e9 le champ musical de mon \u00e9tude. D\u2019abord, c&rsquo;est la musique que je connais le mieux, devenu m\u00e9lomane et collectionneur de disques acharn\u00e9 depuis l&rsquo;\u00e2ge de douze ans. Ensuite, pour des raisons strat\u00e9giques et (pour ainsi dire) politiques, je tenais \u00e0 m&rsquo;attaquer au schibboleth de l\u2019appr\u00e9ciation musicale\u00a0: parce qu\u2019elle repose sur ce r\u00e9pertoire, la forme globale ou architecturale d&rsquo;une \u0153uvre est pour elle d&rsquo;une importance supr\u00eame. C\u2019est donc \u00e0 cette forme globale-architecturale que l\u2019auditeur qui cherche une exp\u00e9rience compr\u00e9hensive et satisfaisante de la musique doit porter son attention. Tout le livre vise \u00e0 d\u00e9montrer que ce n&rsquo;est pas le cas, m\u00eame quand il s&rsquo;agit d&rsquo;une esp\u00e8ce de musique, comme dans ce r\u00e9pertoire, dont les \u0153uvres poss\u00e8dent manifestement une forme globale ou architecturale tr\u00e8s prononc\u00e9e. Apr\u00e8s-coup cependant, je me suis rendu compte que les musiques d\u2019autres genres \u2013 comme la musique atonale, le jazz, la musique indienne classique, la musique improvis\u00e9e en g\u00e9n\u00e9ral, etc. \u2013 se pr\u00eataient plus clairement encore \u00e0 l\u2019\u00e9coute concat\u00e9nationniste que la musique de r\u00e9pertoire sur laquelle j\u2019avais concentr\u00e9 mon attention et qu\u2019elles venaient confirmer de mani\u00e8re sans doute plus \u00e9vidente cette approche de l\u2019\u00e9coute et de la compr\u00e9hension musicale.<br \/>\nDans <i>La musique sur le vif<\/i>, j\u2019ai sugg\u00e9r\u00e9 que la musique al\u00e9atoire, notamment celle qu\u2019ont compos\u00e9 Cage, Stockhausen, Feldman et d\u2019autres, par diff\u00e9rence avec la musique t\u00e9l\u00e9ologique ou orient\u00e9e vers un but \u2013 qui repr\u00e9sente la musique de presque toutes les traditions musicales \u2013 demandait une \u00e9coute d\u2019une esp\u00e8ce anti-concat\u00e9nationniste*. Mais c\u2019\u00e9tait une erreur. Il va de soi qu\u2019une telle musique ne requiert pas une \u00e9coute achitectoniciste dans la mesure o\u00f9 elle ne donne par principe rien de tel \u00e0 entendre. Ce qu\u2019une telle musique r\u00e9clame serait peut-\u00eatre bien plut\u00f4t une \u00e9coute ultra-concat\u00e9nationniste\u00a0: autrement dit une \u00e9coute qui serait plus intimement concentr\u00e9e sur la fugacit\u00e9 du moment que l\u2019\u00e9coute que demande la musique t\u00e9l\u00e9ologique de l\u2019esp\u00e8ce standard. Chaque son y est consid\u00e9r\u00e9 pour lui-m\u00eame, hors de tout esprit de continuit\u00e9, de connexion ou d\u2019implication. Je cite dans <i>La musique sur le vif<\/i> un texte de Pierre Boulez commentant <i>Jeux <\/i>de Debussy** que j\u2019interpr\u00e8te comme un concat\u00e9nationnisme appliqu\u00e9 \u00e0 une musique dans laquelle le dessin architectonique, s\u2019il est pr\u00e9sent, est loin d\u2019\u00eatre pr\u00e9gnant.<br \/>\nQuant \u00e0 la musique contemporaine, et je pense tout particuli\u00e8rement \u00e0 ces musiques qui ne r\u00e9clament pas d\u2019\u00e9coute architectonique ou synoptique, et m\u00eame s\u2019y opposent express\u00e9ment, je citerais les noms de Xenakis, Reich, Boulez, Ligeti et Kurtag, ainsi que celui de leur pr\u00e9d\u00e9cesseur Anton Webern. Je trouve la plupart de cette musique fascinante et s\u00e9duisante, bien qu\u2019elle ne repr\u00e9sente qu\u2019une petite proportion de mon \u00e9coute quotidienne.<br \/>\n<b>Karlheinz Stockhausen n\u2019a-t-il pas, dans une certaine mesure, th\u00e9oris\u00e9 cet \u00ab\u00a0ultra-concat\u00e9nationnisme\u00a0\u00bb sous l\u2019expression de \u00ab\u00a0<i>Momentform\u00a0<\/i>\u00bb, qui ne d\u00e9crit pas seulement un certain mode d\u2019attention \u00e0 la musique mais aussi et surtout le processus compositionnel lui-m\u00eame\u00a0? Une \u0153uvre est ainsi pens\u00e9e comme un ensemble de \u00ab\u00a0moments\u00a0\u00bb autonomes reli\u00e9s les uns aux autres par des propri\u00e9t\u00e9s communes. Cette pens\u00e9e de la forme musicale est aux antipodes de l\u2019id\u00e9e de d\u00e9veloppement, \u00e0 tel point que Theodor Adorno a pu parler \u00e0 son propos de \u00ab\u00a0musique informelle\u00a0\u00bb\u00a0: \u00ab\u00a0une musique qui se serait affranchie de toutes les formes abstraites et fig\u00e9es qui lui \u00e9taient impos\u00e9es du dehors\u00a0\u00bb \u00e9crit-il dans \u00ab\u00a0Vers une musique informelle\u00a0\u00bb. Il ajoute quelques pages plus loin\u00a0: \u00ab\u00a0il faut que dans le processus de composition elle [la musique informelle] demeure impr\u00e9visible\u00a0\u00bb. Sous quelles conditions pourrait-on utiliser le mod\u00e8le concat\u00e9nationniste pour penser la cr\u00e9ation musicale en tant que telle\u00a0?<\/b><br \/>\nCommen\u00e7ons par Stockhausen. Je pense qu\u2019il peut \u00eatre utile de distinguer, entre moments ou \u00ab\u00a0morcettes\u00a0\u00bb*** (<i>\u00ab\u00a0bits\u00a0\u00bb<\/i>) de musique, deux types de lien. Un premier type, proche de ce qu\u2019\u00e9voque Stockhausen, correspond \u00e0 la relation \u2013 qu\u2019elle soit de similarit\u00e9, de contraste ou de chevauchement \u2013 qui existe dans la musique en dehors et ind\u00e9pendamment de la perception. Un autre type de lien est celui \u00a0qui se produit dans l\u2019esprit de l\u2019auditeur quand il essaye de percevoir ces \u00ab\u00a0morcettes\u00a0\u00bb en relation les unes avec les autres\u00a0: la tentative quasi-automatique de constitution d\u2019une ligne musicale \u00e0 partir des bouts que l\u2019oreille rencontre (dans le but de produire une \u00ab\u00a0quasi-\u00e9coute\u00a0\u00bb). Cette quasi-\u00e9coute est certainement rendue possible par les liens du premier type\u00a0 (les \u00ab\u00a0propri\u00e9t\u00e9s communes\u00a0\u00bb), mais elle ne leur est pas r\u00e9ductible.<br \/>\nPour en venir \u00e0 la notion de \u00ab\u00a0musique informelle\u00a0\u00bb, ou de musique sans forme, je pense qu\u2019elle peut \u00eatre comprise au moins de deux mani\u00e8res. Soit comme une musique qui n\u2019a pas de forme globale planifi\u00e9e ou pr\u00e9\u00e9tablie \u2013 nous pourrions l\u2019appeler \u00ab\u00a0musique <i>in<\/i>forme\u00a0\u00bb en pensant \u00ab\u00a0forme\u00a0\u00bb en tant que verbe ou action (\u00ab\u00a0former\u00a0\u00bb). Soit comme une musique qui n\u2019a pas de forme globale perceptible ou identifiable, que cette musique ait \u00e9t\u00e9 ou non compos\u00e9e avec une telle forme \u00e0 l\u2019esprit \u2013 nous l\u2019appellerions \u00ab\u00a0musique <i>sans<\/i> forme\u00a0\u00bb en pensant \u00ab\u00a0forme\u00a0\u00bb comme nom ou propri\u00e9t\u00e9. Nous pourrions dire, en partant de ces deux sens, qu\u2019une musique qui est <i>in<\/i>forme n\u2019est pas forc\u00e9ment <i>sans<\/i> forme dans la mesure o\u00f9 la pr\u00e9sence d\u2019un forme discernable est tout \u00e0 fait compatible avec l\u2019absence d\u2019une forme planifi\u00e9e. On peut tr\u00e8s bien concevoir une musique sans forme au sens susdit\u00a0: une musique paradoxalement <i>form\u00e9e<\/i> pour \u00eatre sans forme. Mais il me semble qu\u2019une absence de forme plus radicale serait presque impossible \u00e0 produire, que ce soit par dessein ou par accident.<br \/>\nQuoi qu\u2019il en soit, une approche concat\u00e9nationniste de la composition serait, semble-t-il, aussi viable qu\u2019une approche concat\u00e9nationniste de l\u2019\u00e9coute. Il suffit de consid\u00e9rer la mani\u00e8re dont la musique trouve \u00ab\u00a0bout \u00e0 bout\u00a0\u00bb sa coh\u00e9sion ou bien comment elle propose une succession pertinente de moments en vertu de relations de divers types entre ses \u00ab\u00a0morcettes\u00a0\u00bb, des relations qui peuvent \u00eatre d\u2019absolue contraste ou diff\u00e9rence.<br \/>\n<b>Pourriez-vous donner un exemple d\u2019une telle exp\u00e9rience d\u2019\u00e9coute, qui se ferait \u00ab\u00a0bout-\u00e0-bout\u00a0\u00bb (une traduction possible de \u00ab\u00a0from bit to bit\u00a0\u00bb)\u00a0?<\/b><br \/>\nForce est de constater que l&rsquo;exp\u00e9rience d&rsquo;\u00e9coute d&rsquo;un morceau atonal typique ne peut pas avoir le m\u00eame caract\u00e8re que l&rsquo;exp\u00e9rience d&rsquo;\u00e9coute d&rsquo;un morceau tonal typique\u00a0: avec cette continuit\u00e9 propre aux m\u00e9lodies \u00e9tendues, aux progressions harmoniques, aux s\u00e9quences motiviques et aux relations phrasales ant\u00e9c\u00e9dent-cons\u00e9quent que la musique tonale fournit en abondance. Et que dire de l&rsquo;exp\u00e9rience d&rsquo;\u00e9coute d&rsquo;un morceau r\u00e9solument anti-t\u00e9l\u00e9ologique, comme ceux des musiques \u00a0al\u00e9atoires ou stochastiques\u00a0? Cette exp\u00e9rience se distingue encore plus nettement de l&rsquo;exp\u00e9rience d&rsquo;\u00e9coute propre \u00e0 la musique tonale.<br \/>\nPrenons l\u2019exemple d&rsquo;un morceau atonal classique, la troisi\u00e8me et la plus courte des <i>Six pi\u00e8ces pour orchestre <\/i>op. 6 du compositeur autrichien Anton Webern. J&rsquo;essaierai de mettre en relief le caract\u00e8re concat\u00e9nationniste de l\u2019\u00e9coute d&rsquo;un tel morceau\u00a0: notamment la mani\u00e8re dont l&rsquo;esprit tisse des liens de diff\u00e9rentes sortes entre les \u00ab\u00a0bouts\u00a0\u00bb de musique qu\u2019il appr\u00e9hende. Il s&rsquo;agira, si l\u2019on veut, d&rsquo;un exercice ph\u00e9nom\u00e9nologique, mais au sens d\u2019une reconstruction, dans la mesure o\u00f9 ce processus de tissage mental se produit en g\u00e9n\u00e9ral de mani\u00e8re inconsciente ou inaper\u00e7ue.<br \/>\nBien qu&rsquo;un moment de musique puisse \u00eatre per\u00e7u comme comprenant deux voire trois \u00e9v\u00e9nements sonores distincts, que l\u2019esprit rapportera mentalement l\u2019un \u00e0 l\u2019autre, je me bornerai presque exclusivement, dans la reconstruction de l&rsquo;exp\u00e9rience d&rsquo;\u00e9coute que j\u2019entreprends ici, au caract\u00e8re successif ou horizontal de la cha\u00eene musicale \u2013 j\u2019ignorerai donc sa dimension simultan\u00e9e ou verticale.<br \/>\nSi Y est un moment (ou \u00ab\u00a0bout\u00a0\u00bb) qui suit imm\u00e9diatement un moment (ou \u00ab\u00a0bout\u00a0\u00bb) X, il existe entre eux toute une gamme de relations que l&rsquo;oreille peut entendre, mais rarement de mani\u00e8re consciente. Par exemple\u00a0: entendre Y comme <i>continuant<\/i> X\u00a0; <i>prolongeant<\/i>\u00a0 X\u00a0; <i>rejetant<\/i> X\u00a0; <i>interrompant<\/i> X\u00a0; <i>amplifiant<\/i> X\u00a0; <i>confirmant<\/i> X\u00a0; <i>divergeant<\/i> de X\u00a0; <i>contrastant<\/i> avec X\u00a0: <i>r\u00e9pondant<\/i> \u00e0 X\u00a0; <i>faisant \u00e9cho<\/i> de X\u00a0; et ainsi de suite.<br \/>\nLe morceau de Webern est constitu\u00e9 de 11 mesures, porte la notation de tempo <i>moderato<\/i> et comprend sept moments ou \u00ab\u00a0bouts\u00a0\u00bb de musique, qui correspondent \u00e0 peu pr\u00e8s aux mesures suivantes\u00a0: 1-2, 3, 4, 5-6, 7-8, 9, 10-11.\u00a0 Le premier, relativement long, consiste en trois motifs \u00e9troitement li\u00e9s \u00e0 l\u2019alto, sept notes ponctu\u00e9es d\u00e8s la troisi\u00e8me par un accord divergeant aux trompettes. Un deuxi\u00e8me moment consiste en un seul motif descendant \u00e0 la clarinette, entendu comme une continuation plus vigoureuse du geste de l\u2019alto. Le troisi\u00e8me moment est un motif descendant pour contrebasse, qui\u00a0 confirme plus discr\u00e8tement ce que la clarinette a prononc\u00e9. Avec le quatri\u00e8me moment arrive, pour ainsi dire, le point fort m\u00e9lodique du morceau\u00a0: un motif sautillant en rythme r\u00e9gulier confi\u00e9 \u00e0 la flute et au glockenspiel \u00e0 l\u2019unisson avec le cor en inversion, et qui se pr\u00e9sente comme contrastant nettement avec le sobre moment pr\u00e9c\u00e9dent. Le cinqui\u00e8me moment nous offre un motif en arc gracieux au basson qui diff\u00e8re poliment du motif un peu trop gai qui le pr\u00e9c\u00e8de et qui est rejoint, avant de prendre fin, par un motif descendant au violon rappelant le geste de la clarinette du deuxi\u00e8me moment. S&rsquo;ensuit le sixi\u00e8me moment, encore un motif descendant qui rappelle les deux pr\u00e9c\u00e9dents, \u00e0 la clarinette et au violon, mais port\u00e9 cette fois par la c\u00e9lesta. Et, pour finir, un motif sourd de trois notes \u00e0 la trompette, \u00e9tay\u00e9 par une oscillation en demi-croches accord\u00e9e \u00e0 la harpe, qui semble une sorte de jugement sobre sur ce qui s&rsquo;est pass\u00e9 jusque-l\u00e0.<br \/>\nDans cette reconstruction, j\u2019esp\u00e8re pas trop farfelue, d&rsquo;une exp\u00e9rience concat\u00e9nationniste de ce morceau bref et exquis, la conscience de sa forme globale ne joue aucun r\u00f4le. Toute l&rsquo;attention de l&rsquo;auditeur se porte sur les moments individuels eux-m\u00eames et les rapports imm\u00e9diats que chaque moment entretient avec ceux qui le voisinent.<br \/>\n<b>Une des belles cons\u00e9quences de la th\u00e9orie concat\u00e9nationniste est qu\u2019elle fait de l\u2019\u00e9coute de l\u2019amateur une \u00e9coute aussi juste et profonde que celle de l&rsquo;expert. Ce qui veut dire que n\u2019importe qui peut pr\u00e9tendre \u00e0 une \u00e9coute authentiquement musicale, m\u00eame d\u2019\u0153uvres complexes et r\u00e9put\u00e9es d\u2019acc\u00e8s difficile. Mais cela suffit-il \u00e0 donner aux auditeurs le d\u00e9sir de les entendre? Que diriez-vous \u00e0 un amateur de heavy metal ou de drone music qui puisse le convaincre de se rendre \u00e0 un concert de musique contemporaine?<\/b><br \/>\nPermettez-moi une pr\u00e9cision. Comme le montre clairement le dernier chapitre de <i>La musique sur le vif, <\/i>la conception de l\u2019\u00e9coute musicale que je d\u00e9fends ne nie pas que l\u2019\u00e9coute synoptique ou architectonique, impliquant une attention \u00e0 la forme globale, puisse contribuer \u00e0 l\u2019appr\u00e9ciation pleine et enti\u00e8re d\u2019une morceau de musique ni m\u00eame qu\u2019elle soit \u00e0 m\u00eame de faciliter l\u2019implication de l\u2019auditeur dans son \u00e9coute \u00ab\u00a0bout \u00e0 bout\u00a0\u00bb. Cela ne veut pas dire non plus qu\u2019une connaissance articul\u00e9e du style et du genre ne puisse am\u00e9liorer l\u2019appr\u00e9ciation d\u2019une \u0153uvre qu\u2019on appr\u00e9hende par ailleurs de mani\u00e8re concat\u00e9nationniste. Il n\u2019est donc pas tout \u00e0 fait vrai que la conception que je d\u00e9fends mette au m\u00eame niveau l\u2019\u00e9coute de l\u2019expert \u2013 qui peut plus facilement d\u00e9velopper une approche synoptique et articuler une connaissance de la forme musicale \u2013 et celle de l\u2019amateur. Il s\u2019agit seulement de montrer qu\u2019une compr\u00e9hension musicale basique, qui suit le proc\u00e8s musical dans son \u00e9volution moment apr\u00e8s moment et n\u2019est attentive de connexions entre les bouts musicaux qu\u2019\u00e0 une petite \u00e9chelle, ne demande ni une \u00e9coute synoptique ni une connaissance musicale sp\u00e9cifique, et qu\u2019elle d\u00e9livre, autant \u00e0 l\u2019amateur qu\u2019\u00e0 l\u2019expert, l\u2019essentiel de ce que la plupart des musiques ont \u00e0 offrir \u00e0 l\u2019auditeur.<br \/>\nLa principale cl\u00e9 pour parvenir \u00e0 la compr\u00e9hension d\u2019une \u0153uvre musicale quelle qu\u2019elle soit est son \u00e9coute attentive et r\u00e9p\u00e9t\u00e9e \u2013\u00a0 id\u00e9alement accompagn\u00e9e par l\u2019\u00e9coute assidue des autres \u0153uvres du genre et des musiques qui forment son arri\u00e8re-plan culturel, de mani\u00e8re \u00e0 faciliter l\u2019internalisation des normes de cette musique au niveau intuitif. Mais c\u2019est ici qu\u2019une certaine diff\u00e9rence se fait jour entre les genres de musique. Il semble \u00e9vident que les \u0153uvres de certains genres soient plus imm\u00e9diatement accessibles que d\u2019autres et qu\u2019elles encouragent donc la r\u00e9p\u00e9tition de l\u2019\u00e9coute. Par exemple, il est probablement plus facile d\u2019amener quelqu\u2019un qui n\u2019est pas familier avec Mozart \u00e0 \u00e9couter une de ses \u0153uvres plusieurs fois que d\u2019amener quelqu\u2019un qui n\u2019est pas familier avec Webern \u00e0 \u00e9couter une des ses \u0153uvres une seconde ou un troisi\u00e8me fois, m\u00eame si cette derni\u00e8re, malheureusement, demande plus que deux ou trois \u00e9coutes pour laisser une trace significative dans l\u2019esprit de l\u2019auditeur. (L\u2019habitude dans certains concerts de musique contemporaine de rejouer les \u0153uvres est de ce point de vue une tr\u00e8s bonne chose.) Il y a toujours une sorte de \u00ab\u00a0saut de la foi\u00a0\u00bb kierkegaardien quand quelqu\u2019un d\u00e9cide de donner une chance \u00e0 un genre de musique non familier et il est ind\u00e9niable que ce saut soit dans certains cas plus important que dans d\u2019autres. Mais une perspective concat\u00e9nationniste rend ce saut moins intimidant qu\u2019il ne le serait autrement, dans la mesure o\u00f9 la seule chose que l\u2019on demande \u00e0 l\u2019auditeur est qu\u2019il \u00e9coute la musique attentivement et de mani\u00e8re r\u00e9p\u00e9t\u00e9e telle qu\u2019elle \u00e9volue \u00ab\u00a0sur le vif\u00a0\u00bb.<br \/>\n* <i>La musique sur le vif. La nature de l\u2019exp\u00e9rience musicale, <\/i>traduction de Sandrine Darsel, Presses Universitaires de Rennes, 2013<i>, <\/i>pp. 62-63.<br \/>\n** <i>Ibid.<\/i>, note 16, p.\u00a063.<br \/>\n***<b> <\/b>Il me semble qu\u2019il n\u2019existe en fran\u00e7ais aucun mot qui permettrait de traduire le mot anglais \u00ab\u00a0<i>bit\u00a0<\/i>\u00bb, surtout dans son sens musical. \u00ab\u00a0Morceau\u00a0\u00bb ne convient pas, un morceau de musique peut \u00eatre immense (pensons a la <i>Huiti\u00e8me Symphonie<\/i> de Bruckner) et \u00ab\u00a0moment\u00a0\u00bb sugg\u00e8re un peu trop l&rsquo;id\u00e9e d&rsquo;instantan\u00e9it\u00e9. C\u2019est pour cette raison que j&rsquo;ai propos\u00e9 \u00e0 plusieurs reprises (\u00e0 l\u2019occasion de conf\u00e9rences sur le concat\u00e9nationnisme) le n\u00e9ologisme \u00ab\u00a0morcette\u00a0\u00bb comme traduction de \u00ab\u00a0<i>bit\u00a0<\/i>\u00bb.\u00a0<b style=\"line-height: 1.5em;\">\u00a0<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Professeur de philosophie \u00e0 l\u2019universit\u00e9 du Maryland aux \u00c9tats-Unis, Jerrold Levinson est l\u2019auteur de plusieurs ouvrages et de nombreux articles sur l\u2019esth\u00e9tique. Dans son essai \u00a0<em>La musique sur le vif. La nature de l\u2019exp\u00e9rience musicale, <\/em>il aborde des questions allant\u00a0\u00a0de la d\u00e9finition de la musique \u00e0 l\u2019ontologie des \u0153uvres en passant par les probl\u00e8mes plus sp\u00e9cifiques que posent l\u2019interpr\u00e9tation et l\u2019\u00e9coute musicale. C\u2019est autour de cette derni\u00e8re que tourne l\u2019entretien qu\u2019il a bien voulu nous accorder.<\/p>\n","protected":false},"author":77,"featured_media":8512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[702,703],"class_list":["post-8510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-jerrold-levinson","tag-theorie-de-la-musique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grand entretien avec Jerrold Levinson, philosophe. - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grand entretien avec Jerrold Levinson, philosophe. - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"Professeur de philosophie \u00e0 l\u2019universit\u00e9 du Maryland aux \u00c9tats-Unis, Jerrold Levinson est l\u2019auteur de plusieurs ouvrages et de nombreux articles sur l\u2019esth\u00e9tique. Dans son essai \u00a0La musique sur le vif. La nature de l\u2019exp\u00e9rience musicale, il aborde des questions allant\u00a0\u00a0de la d\u00e9finition de la musique \u00e0 l\u2019ontologie des \u0153uvres en passant par les probl\u00e8mes plus sp\u00e9cifiques que posent l\u2019interpr\u00e9tation et l\u2019\u00e9coute musicale. C\u2019est autour de cette derni\u00e8re que tourne l\u2019entretien qu\u2019il a bien voulu nous accorder.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-21T08:30:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/12\/Levinson-NB-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"464\" \/>\n\t<meta property=\"og:image:height\" content=\"237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bastien Gallet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bastien Gallet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2015\\\/12\\\/grand-entretien-avec-jerrold-levinson-philosophe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2015\\\/12\\\/grand-entretien-avec-jerrold-levinson-philosophe\\\/\"},\"author\":{\"name\":\"Bastien Gallet\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/dcec9165be78adbc6185726fb0217b30\"},\"headline\":\"Grand entretien avec Jerrold Levinson, philosophe.\",\"datePublished\":\"2015-12-21T08:30:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2015\\\/12\\\/grand-entretien-avec-jerrold-levinson-philosophe\\\/\"},\"wordCount\":2975,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2015\\\/12\\\/grand-entretien-avec-jerrold-levinson-philosophe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2015\\\/12\\\/Levinson-NB-header.jpg\",\"keywords\":[\"Jerrold Levinson\",\"Th\u00e9orie de la musique\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2015\\\/12\\\/grand-entretien-avec-jerrold-levinson-philosophe\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2015\\\/12\\\/grand-entretien-avec-jerrold-levinson-philosophe\\\/\",\"name\":\"Grand entretien avec Jerrold Levinson, philosophe. - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2015\\\/12\\\/grand-entretien-avec-jerrold-levinson-philosophe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2015\\\/12\\\/grand-entretien-avec-jerrold-levinson-philosophe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2015\\\/12\\\/Levinson-NB-header.jpg\",\"datePublished\":\"2015-12-21T08:30:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/dcec9165be78adbc6185726fb0217b30\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2015\\\/12\\\/grand-entretien-avec-jerrold-levinson-philosophe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2015\\\/12\\\/grand-entretien-avec-jerrold-levinson-philosophe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2015\\\/12\\\/grand-entretien-avec-jerrold-levinson-philosophe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2015\\\/12\\\/Levinson-NB-header.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2015\\\/12\\\/Levinson-NB-header.jpg\",\"width\":464,\"height\":237},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2015\\\/12\\\/grand-entretien-avec-jerrold-levinson-philosophe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grand entretien avec Jerrold Levinson, philosophe.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/dcec9165be78adbc6185726fb0217b30\",\"name\":\"Bastien Gallet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebdfd18ad699c14b86dd7cb91afa7426f72a4a2217bc30a292406d99b2c1e66e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebdfd18ad699c14b86dd7cb91afa7426f72a4a2217bc30a292406d99b2c1e66e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ebdfd18ad699c14b86dd7cb91afa7426f72a4a2217bc30a292406d99b2c1e66e?s=96&d=mm&r=g\",\"caption\":\"Bastien Gallet\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/author\\\/bastien-gallet\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grand entretien avec Jerrold Levinson, philosophe. - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/","og_locale":"fr_FR","og_type":"article","og_title":"Grand entretien avec Jerrold Levinson, philosophe. - Ensemble intercontemporain","og_description":"Professeur de philosophie \u00e0 l\u2019universit\u00e9 du Maryland aux \u00c9tats-Unis, Jerrold Levinson est l\u2019auteur de plusieurs ouvrages et de nombreux articles sur l\u2019esth\u00e9tique. Dans son essai \u00a0La musique sur le vif. La nature de l\u2019exp\u00e9rience musicale, il aborde des questions allant\u00a0\u00a0de la d\u00e9finition de la musique \u00e0 l\u2019ontologie des \u0153uvres en passant par les probl\u00e8mes plus sp\u00e9cifiques que posent l\u2019interpr\u00e9tation et l\u2019\u00e9coute musicale. C\u2019est autour de cette derni\u00e8re que tourne l\u2019entretien qu\u2019il a bien voulu nous accorder.","og_url":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2015-12-21T08:30:56+00:00","og_image":[{"width":464,"height":237,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/12\/Levinson-NB-header.jpg","type":"image\/jpeg"}],"author":"Bastien Gallet","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Bastien Gallet","Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/"},"author":{"name":"Bastien Gallet","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/dcec9165be78adbc6185726fb0217b30"},"headline":"Grand entretien avec Jerrold Levinson, philosophe.","datePublished":"2015-12-21T08:30:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/"},"wordCount":2975,"commentCount":0,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/12\/Levinson-NB-header.jpg","keywords":["Jerrold Levinson","Th\u00e9orie de la musique"],"articleSection":["Entretien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/","url":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/","name":"Grand entretien avec Jerrold Levinson, philosophe. - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/12\/Levinson-NB-header.jpg","datePublished":"2015-12-21T08:30:56+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/dcec9165be78adbc6185726fb0217b30"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/12\/Levinson-NB-header.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/12\/Levinson-NB-header.jpg","width":464,"height":237},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/12\/grand-entretien-avec-jerrold-levinson-philosophe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Grand entretien avec Jerrold Levinson, philosophe."}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/dcec9165be78adbc6185726fb0217b30","name":"Bastien Gallet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ebdfd18ad699c14b86dd7cb91afa7426f72a4a2217bc30a292406d99b2c1e66e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ebdfd18ad699c14b86dd7cb91afa7426f72a4a2217bc30a292406d99b2c1e66e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ebdfd18ad699c14b86dd7cb91afa7426f72a4a2217bc30a292406d99b2c1e66e?s=96&d=mm&r=g","caption":"Bastien Gallet"},"url":"https:\/\/www.ensembleintercontemporain.com\/fr\/author\/bastien-gallet\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/8510\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/users\/77\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/comments\/?post=8510"}],"version-history":[{"count":0,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/8510\/revisions\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/media\/8512\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/media\/?parent=8510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/categories\/?post=8510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/tags\/?post=8510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}