{"id":4196,"date":"2012-01-16T13:18:52","date_gmt":"2012-01-16T11:18:52","guid":{"rendered":"http:\/\/www.ensembleinter.com\/accents-online\/?p=4196"},"modified":"2012-01-16T13:18:52","modified_gmt":"2012-01-16T11:18:52","slug":"inori-interview-avec-karlheinz-stockhausen","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/","title":{"rendered":"Inori : interview avec Karlheinz Stockhausen"},"content":{"rendered":"<p><a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2012\/01\/Stockhausen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4198\" title=\"Karlheinz Stockhausen\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2012\/01\/Stockhausen.jpg\" alt=\"\" width=\"492\" height=\"314\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2012\/01\/Stockhausen.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2012\/01\/Stockhausen-300x191.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a>A l\u2019occasion de la repr\u00e9sentation exceptionnelle\u00a0 d\u2019<em>Inori <\/em>le 10 f\u00e9vrier \u00e0 la Cit\u00e9 de la musique, <em>accents on line<\/em> publie une interview avec Karlheinz Stockhausen sur la cr\u00e9ation de cette \u0153uvre, r\u00e9alis\u00e9e en 1974 par Claude Samuel pour la revue <em>Panorama de la musique et des instruments<\/em>.<br \/>\n<a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2012\/01\/Inori.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4197\" title=\"Inori\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2012\/01\/Inori.jpg\" alt=\"\" width=\"492\" height=\"330\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2012\/01\/Inori.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2012\/01\/Inori-300x201.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><br \/>\n<strong>Comme vous le savez, certains critiques ont qualifi\u00e9 <em>Inori <\/em>d\u2019\u0153uvre r\u00e9p\u00e9titive et simpliste. Qu\u2019en dites-vous\u00a0?<\/strong><br \/>\nJe crois que ceux qui ont vu dans <em>Inori<\/em> une \u0153uvre r\u00e9p\u00e9titive et simpliste ne savent pas \u00e9couter la polyphonie. <em>Inori<\/em> est polyphonique d\u00e8s le d\u00e9but. Certains y ont entendu des accords\u00a0: il n\u2019y en a pas, il y a un seul son. Avant que la m\u00e9lodie ne commence \u00e0 se d\u00e9velopper, j\u2019ai bloqu\u00e9 les hauteurs pour travailler sur le tempo. Pour la premi\u00e8re fois dans l\u2019histoire de la musique, j\u2019ai introduit une gamme de <em>tempi<\/em>, et pendant douze minutes, je ne travaille que sur le d\u00e9veloppement de diff\u00e9rents <em>tempi<\/em> avec une \u00e9chelle chromatique.<br \/>\nLe public est accoutum\u00e9 \u00e0 \u00e9couter des m\u00e9lodies, mais d\u00e9j\u00e0, les premi\u00e8res m\u00e9lodies de timbres n\u2019avaient pas \u00e9t\u00e9 comprises. Dans <em>Inori,<\/em> j\u2019ai d\u00e9velopp\u00e9 pendant douze minutes une nouvelle gamme de <em>tempi<\/em> \u2013 douze valeurs entre 60 et 120, en cinq \u00ab\u00a0octaves\u00a0\u00bb de tempo. Chaque note a un tempo diff\u00e9rent, indiqu\u00e9 par une pulsation tr\u00e8s pr\u00e9cise. Et la deuxi\u00e8me section de l\u2019\u0153uvre d\u00e9veloppe une gamme chromatique de soixante degr\u00e9s dynamiques diff\u00e9rents, compos\u00e9s avec diff\u00e9rentes densit\u00e9s d\u2019instruments jouant le m\u00eame son. Si le public ne fait pas attention au degr\u00e9 dynamique, le ph\u00e9nom\u00e8ne lui \u00e9chappe. Mais il y viendra. Dans quelques ann\u00e9es, <em>Inori<\/em> sera l\u2019\u0153uvre cl\u00e9 d\u2019un nouveau d\u00e9veloppement de la composition des <em>tempi <\/em>et d\u2019une nouvelle fonction des timbres, gr\u00e2ce \u00e0 ce principe de l\u2019\u00e9chelle chromatique des intensit\u00e9s.<br \/>\n<strong> <\/strong><br \/>\n<strong>Que pensez-vous du reproche que l\u2019on vous fait de prendre une autre direction \u00e0 chaque nouvelle \u0153uvre\u00a0?<\/strong><br \/>\nJe d\u00e9concerte parce que je prends une autre direction avec chaque nouvelle \u0153uvre. <em>Stimmung<\/em>, <em>Hymnen<\/em>, <em>Alphabet.<\/em> Nous vivons les d\u00e9buts d\u2019une nouvelle \u00e9poque de la conscience musicale, et pour \u00e9tablir un nouveau langage qui puisse se d\u00e9velopper en plusieurs si\u00e8cles, je suis oblig\u00e9 de prendre un maximum de directions. Il m\u2019est impossible de suivre une seule direction\u00a0: ce n\u2019est pas ma fonction dans l\u2019histoire de la musique. Je vois toutes les portes qui s\u2019ouvrent devant moi et j\u2019indique chaque direction. Si je passe trop de temps sur un probl\u00e8me, je n\u2019arriverai jamais \u00e0 indiquer toutes les autres directions.<br \/>\nChaque direction explor\u00e9e m\u2019aide pour les directions futures. On ne peut jamais commencer \u00e0 z\u00e9ro. Chaque \u0153uvre laisse certains probl\u00e8mes \u00e0 l\u2019\u00e9tat vierge. Ainsi de la composition avec une \u00e9chelle dynamique, qui est aussi souple, aussi riche que l\u2019\u00e9chelle des hauteurs. Dans un piano, il y a 85 touches bien mesur\u00e9es au point de vue de l\u2019\u00e9chelle chromatique et logarithmique. J\u2019ai tent\u00e9 d\u2019\u00e9tablir la m\u00eame chose pour la dynamique, et je l\u2019ai annonc\u00e9 depuis des ann\u00e9es. Mais la r\u00e9alisation de cette \u0153uvre a n\u00e9cessit\u00e9 cinq mois de travail avec une \u00e9quipe de six collaborateurs, chaque degr\u00e9 demandant parfois plusieurs heures pour \u00eatre mis en partition. Il faut donc d\u2019\u00e9normes ressources de temps et de moyens.<br \/>\nEn outre, <em>Inori<\/em> pose tellement de probl\u00e8mes\u00a0\u00e0 la fois qu\u2019on ne peut jamais s\u2019attendre \u00e0 une r\u00e9action positive de la part d\u2019un public qui n&rsquo;est pas religieux, par exemple. La direction d\u2019<em>Inori<\/em> est clairement indiqu\u00e9e\u00a0: cette \u0153uvre ne laisse pas le choix entre l&rsquo;esth\u00e9tique s\u00e9cularis\u00e9e ou le fonctionnalisme religieux, parce qu\u2019elle est une pri\u00e8re, parce que chaque intervalle musical devient un geste de pri\u00e8re et doit \u00eatre re\u00e7u comme tel.<br \/>\n<strong>Beaucoup de personnes parmi celles qui s\u2019int\u00e9ressent \u00e0 votre \u0153uvre sont d\u00e9sorient\u00e9es parce qu\u2019elles ne distinguent pas de ligne claire dans votre \u00e9volution.<\/strong><br \/>\nToute mon \u00e9volution refl\u00e8te une\u00a0logique vectorielle. La logique peut \u00eatre lin\u00e9aire ou vectorielle. Avec un vecteur, chaque\u00a0point auquel on arrive permet d\u2019aller dans\u00a0toutes les directions possibles, dans un espace quadridimensionnel. En ce sens\u00a0c\u2019est bien d\u2019une logique qu\u2019il s\u2019agit. Mais\u00a0il se peut que, comme dans une spirale, je\u00a0fasse une \u0153uvre compl\u00e8tement d\u00e9termin\u00e9e\u00a0comme <em>Inori<\/em>, \u00e0 l\u2019exception de quelques parties que j\u2019appelle parties d\u2019\u00e9cho, o\u00f9 plusieurs musiciens ont le choix de jouer librement avec de\u00a0petites formules m\u00e9lodiques, la dynamique \u00e9tant relativement libre, ce qui cr\u00e9e un \u00e9l\u00e9ment\u00a0al\u00e9atoire Il n\u2019emp\u00eache qu\u2019en ce qui\u00a0concerne les \u00e9chelles et les param\u00e8tres\u00a0s\u00e9iels, tout l\u2019\u0153uvre est d\u00e9termin\u00e9e.<br \/>\nAinsi m\u2019a-t-on reproch\u00e9 d\u2019\u00eatre\u00a0revenu au d\u00e9terminisme. Les gens sont\u00a0comme des endants\u00a0: vous indiquez une direction\u00a0et ils croient que vous allez toujours continuer dans ce sens. Ils n\u2019arrivent pas \u00e0\u00a0 imaginer que l&rsquo;univers est une bulle de\u00a0conscience, que les directions sont innombrables\u00a0et qu\u2019il faut les prendre toutes\u00a0: mais on\u00a0ne peut en suivre qu\u2019une seule \u00e0 la fois.\u00a0Quand j\u2019emprunte une direction, il ne faut pas\u00a0croire que je vais continuer en ligne droite. A c\u00f4t\u00e9 de la droite\u00a0, il y a le vecteur et la\u00a0spirale. J\u2019oscille donc entre le d\u00e9terminisme et un ind\u00e9terminisme extr\u00eame, tr\u00e8s intuitif. Et l\u2019\u00e2ge et le m\u00e9tier aidant, la spirale acc\u00e9l\u00e8re de plus en plus.<br \/>\n<em>Inori <\/em>n\u2019est pas seulement\u00a0important pour moi\u00a0: c\u2019est une d\u00e9couverte capitale pour les musiciens, et cela dans plusieurs sens. D\u2019abord, c\u2019est le premier\u00a0exemple de l\u2019histoire de la musique dans lequel\u00a0on ait trouv\u00e9 une notation musicale parfaite pour d\u00e9crire exactement chaque geste\u00a0d\u2019un corps humain. \u00c0 ce titre, <em>Inori <\/em>est\u00a0l\u2019\u0153uvre cl\u00e9 pour tout un nouveau d\u00e9veloppement\u00a0de l\u2019\u00e9criture et de la danse. Ce principe\u00a0peut faire la part plus ou moins grande\u00a0\u00e0 l\u2019al\u00e9atoire, mais il d\u00e9termine une liaison entre structure musicale et structure\u00a0visuelle. Pour la prochaine \u0153uvre, en\u00a0ajoutant seulement un param\u00e8tre, je\u00a0cr\u00e9erai un espace tridimensionnel, et les gens\u00a0bougeront\u00a0: ils ne seront plus assis ou \u00e0\u00a0genoux, ils bougeront vers le haut, vers le bas, sur sc\u00e8ne, dans la salle, etc. Deuxi\u00e8mement,\u00a0il y a dans <em>Inori<\/em>, comme je l\u2019ai dit, une\u00a0recherche dynamique, et un nouveau fonctionnalisme des timbres qui lib\u00e8re ce que j\u2019appelle l\u2019\u00e9nergie, laquelle est une combinaison de timbre et de dynamique. Cela aboutit \u00e0 un\u00a0v\u00e9ritable renouvellement de l\u2019acoustique musicale \u00a0et c\u2019est pourquoi je travaille maintenant avec des\u00a0\u00e9chelles d\u2019\u00e9nergie. Cette innovation, qui devra \u00eatre d\u00e9velopp\u00e9e et exploit\u00e9e, sera lourde de cons\u00e9quences au regard de l\u2019histoire. Enfin, troisi\u00e8mement, <em>Inori <\/em>introduit \u00e0 une nouvelle conception de la composition du temps, un travail sur diff\u00e9rentes couches de <em>tempi<\/em>, avec des <em>tempi<\/em> chromatiques.<br \/>\nComme tout autre domaine, celui de la musique est un champ d\u2019activit\u00e9 pour beaucoup de gens, et chacun y a son r\u00f4le, qu\u2019il n\u2019a pas choisi. Certains sont de grands planificateurs, comme en architecture ou en math\u00e9matique. Ceux-l\u00e0 ont les plus fortes antennes. Cela d\u00e9pend des watts qui sont dans un syst\u00e8me. On ne s\u2019est pas fait soi-m\u00eame, on doit veiller \u00e0 ne pas casser son syst\u00e8me. Un homme est une constellation. Il a y une production humaine et, de temps en temps, cette production suscite un \u00e9l\u00e9ment qui est comme une station extr\u00eamement forte, capable de recevoir des informations nouvelles qui permettent \u00e0 leur tour de contacter des couches de conscience inconnues jusqu\u2019alors. C\u2019est pourquoi il ne sert \u00e0 rien de porter des jugements de valeur sur la qualit\u00e9 personnelle, de dire que certains compositeurs sont mauvais. Quelques-uns ont un talent qui va jusqu\u2019\u00e0 un certain point, d\u2019autres ont un talent plus vaste. L\u2019important, c\u2019est que chacun fasse le maximum avec ce qu\u2019il a re\u00e7u en partage, en travaillant et en s\u2019\u00e9duquant constamment. Nous travaillons tous ensemble, et on ne pourrait jamais percevoir ce que je fais s\u2019il n\u2019y avait pas de points de comparaison.<br \/>\n<strong>On entend sans cesse dire qu\u2019\u00e0 notre \u00e9poque il y aurait moins de grands artistes qu\u2019autrefois parce que la soci\u00e9t\u00e9 s\u2019int\u00e9resserait moins \u00e0 l\u2019art. Etes-vous de cet avis\u00a0?<\/strong><br \/>\nNous devons \u00eatre reconnaissants qu\u2019il y ait encore quelques artistes\u00a0; quel que soit leur degr\u00e9 de talent, il faut les faire travailler tout le temps, c\u2019est \u00e7a qui importe. Il faut que la soci\u00e9t\u00e9 demande \u00e0 ceux qui ont un talent sp\u00e9cial de travailler \u00e0 plein-temps pour elle, qui est tellement pauvre au niveau de l\u2019imagination. En musique, tous ceux qui sont des multiplicateurs et des transformateurs sont tr\u00e8s utiles. Il y a tr\u00e8s peu de g\u00e9n\u00e9rateurs, et il n\u2019est pas n\u00e9cessaire qu\u2019il y en ait beaucoup. Toutes les deux g\u00e9n\u00e9rations, on n\u2019a besoin dans la musique que de trois ou quatre g\u00e9n\u00e9rateurs. C\u2019est largement suffisant. Imaginons une \u00e9poque avec vingt Mozart, ce serait la catastrophe. Que pourrait-on faire d\u2019eux, sinon les \u00e9craser\u00a0? Il n\u2019y a pas de place pour vingt Mozart. Dans un grand studio, il y a tout juste la place pour trois ou quatre g\u00e9n\u00e9rateurs de base. Le reste est affaire de transformateurs, de filtres, de modulateurs, de haut-parleurs et de multiplicateurs.<br \/>\n<strong>On dit et on \u00e9crit sans cesse que votre musique est trop exigeante, qu\u2019elle est trop difficile pour le grand public.<\/strong><br \/>\nDe nos jours, si l\u2019on veut prendre l\u2019air frais, on doit marcher pendant une heure ou deux. De m\u00eame, la musique \u00e9volue trop vite pour le public, et il faut s\u2019imposer plus de travail pour l\u2019appr\u00e9cier. Le public des concerts est d\u00e9concert\u00e9. Le p\u00e8re de ma femme, qui \u00e9tait ing\u00e9nieur, se pr\u00e9parait une fois par semaine dans un quatuor d\u2019hommes, en chantant Schubert. Il jouait du piano, connaissait tous les th\u00e8mes des op\u00e9ras qu\u2019il allait voir, \u00e9tait familiaris\u00e9 avec les \u0153uvres, m\u00eame celles de Schoenberg, et Hindemith venait jouer chez lui. Dans les ann\u00e9es 20 et 30, \u00e0 Francfort, de nombreuses familles accueillaient des quatuors, des chanteurs, des pianistes pour des concerts priv\u00e9s. Tout cela est en train de d\u00e9g\u00e9n\u00e9rer. Il faut absolument imposer au public une pr\u00e9paration pour le concert, sinon la perception musicale deviendra compl\u00e8tement superficielle. Tout le monde s\u2019attend \u00e0 des chocs de plus en plus forts, et presque personne ne s\u2019y pr\u00e9pare.<br \/>\nJe ne suis pas pessimiste. Je crois simplement aux pr\u00e9dictions de certains, tel Aphonse Rosenberg qui, dans son livre <em>Durchbruch zur Zukunft<\/em>*(La Perc\u00e9e vers l\u2019avenir) annonce l&rsquo;\u00e8re du Verseau (Aquarius), le temps o\u00f9 la science deviendra religion et o\u00f9 les pers\u00e9cutions seront encore plus terribles qu\u2019au Moyen \u00c2ge. Les hommes attach\u00e9s au transcendantal, qui sont des \u00eatres profond\u00e9ment orient\u00e9s sur le divin, seront pers\u00e9cut\u00e9s avec des m\u00e9thodes atroces. Il est clair que l\u2019art deviendra dans quelques si\u00e8cles un pur divertissement, et que l\u2019art v\u00e9ritable, qui est la pr\u00e9paration de l\u2019homme \u00e0 une vie sup\u00e9rieure, sera alors le propre d\u2019un petit groupe \u00e9sot\u00e9rique r\u00e9fugi\u00e9 dans l\u2019<em>underground<\/em>.<br \/>\n<strong><em>Karlheinz Stockhausen<\/em><\/strong><br \/>\nArticle paru dans la revue <em>Panorama de la musique et des instruments<\/em>, d\u00e9cembre 1974. Les questions de Claude Samuel, auteur de l\u2019article, ont \u00e9t\u00e9 r\u00e9tablies gr\u00e2ce \u00e0 la collaboration de Kathinka Pasveer.<br \/>\n* M\u00fcnchen-Planczg\u00a0, 1958<br \/>\nPhotographies : Karlheinz Stockhausen<strong>\u00a9<\/strong>Philippe Gontier \/ <em>Inori<\/em>, r\u00e9p\u00e9tition\u00a9Myr Muratet<strong><br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A l\u2019occasion de la repr\u00e9sentation exceptionnelle\u00a0 d\u2019Inori le 10 f\u00e9vrier \u00e0 la Cit\u00e9 de la musique, accents on line publie une interview avec Karlheinz Stockhausen sur la cr\u00e9ation de cette \u0153uvre, r\u00e9alis\u00e9e en 1974 par Claude Samuel pour la revue Panorama de la musique et des instruments. Comme vous le savez, certains critiques ont qualifi\u00e9 [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":4199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[492,493,72],"class_list":["post-4196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-claude-samuel","tag-inori","tag-karlheinz-stockhausen","concert-gruppen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inori : interview avec Karlheinz Stockhausen - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inori : interview avec Karlheinz Stockhausen - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"A l\u2019occasion de la repr\u00e9sentation exceptionnelle\u00a0 d\u2019Inori le 10 f\u00e9vrier \u00e0 la Cit\u00e9 de la musique, accents on line publie une interview avec Karlheinz Stockhausen sur la cr\u00e9ation de cette \u0153uvre, r\u00e9alis\u00e9e en 1974 par Claude Samuel pour la revue Panorama de la musique et des instruments. Comme vous le savez, certains critiques ont qualifi\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-16T11:18:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2012\/01\/Inori_une.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"464\" \/>\n\t<meta property=\"og:image:height\" content=\"237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Claude Samuel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claude Samuel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2012\\\/01\\\/inori-interview-avec-karlheinz-stockhausen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2012\\\/01\\\/inori-interview-avec-karlheinz-stockhausen\\\/\"},\"author\":{\"name\":\"Claude Samuel\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/b90ba611e7b88b341392832913a62892\"},\"headline\":\"Inori : interview avec Karlheinz Stockhausen\",\"datePublished\":\"2012-01-16T11:18:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2012\\\/01\\\/inori-interview-avec-karlheinz-stockhausen\\\/\"},\"wordCount\":2016,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2012\\\/01\\\/inori-interview-avec-karlheinz-stockhausen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2012\\\/01\\\/Inori_une.jpg\",\"keywords\":[\"claude samuel\",\"Inori\",\"Karlheinz Stockhausen\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2012\\\/01\\\/inori-interview-avec-karlheinz-stockhausen\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2012\\\/01\\\/inori-interview-avec-karlheinz-stockhausen\\\/\",\"name\":\"Inori : interview avec Karlheinz Stockhausen - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2012\\\/01\\\/inori-interview-avec-karlheinz-stockhausen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2012\\\/01\\\/inori-interview-avec-karlheinz-stockhausen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2012\\\/01\\\/Inori_une.jpg\",\"datePublished\":\"2012-01-16T11:18:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/b90ba611e7b88b341392832913a62892\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2012\\\/01\\\/inori-interview-avec-karlheinz-stockhausen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2012\\\/01\\\/inori-interview-avec-karlheinz-stockhausen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2012\\\/01\\\/inori-interview-avec-karlheinz-stockhausen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2012\\\/01\\\/Inori_une.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2012\\\/01\\\/Inori_une.jpg\",\"width\":464,\"height\":237},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2012\\\/01\\\/inori-interview-avec-karlheinz-stockhausen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inori : interview avec Karlheinz Stockhausen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/b90ba611e7b88b341392832913a62892\",\"name\":\"Claude Samuel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cf65d26fc2092ade484c5e889299f4f7c3eb9919a7c08c819bf551affa7d1eb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cf65d26fc2092ade484c5e889299f4f7c3eb9919a7c08c819bf551affa7d1eb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6cf65d26fc2092ade484c5e889299f4f7c3eb9919a7c08c819bf551affa7d1eb?s=96&d=mm&r=g\",\"caption\":\"Claude Samuel\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/author\\\/claude-samuel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inori : interview avec Karlheinz Stockhausen - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/","og_locale":"fr_FR","og_type":"article","og_title":"Inori : interview avec Karlheinz Stockhausen - Ensemble intercontemporain","og_description":"A l\u2019occasion de la repr\u00e9sentation exceptionnelle\u00a0 d\u2019Inori le 10 f\u00e9vrier \u00e0 la Cit\u00e9 de la musique, accents on line publie une interview avec Karlheinz Stockhausen sur la cr\u00e9ation de cette \u0153uvre, r\u00e9alis\u00e9e en 1974 par Claude Samuel pour la revue Panorama de la musique et des instruments. Comme vous le savez, certains critiques ont qualifi\u00e9 [&hellip;]","og_url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2012-01-16T11:18:52+00:00","og_image":[{"width":464,"height":237,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2012\/01\/Inori_une.jpg","type":"image\/jpeg"}],"author":"Claude Samuel","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Claude Samuel","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/"},"author":{"name":"Claude Samuel","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/b90ba611e7b88b341392832913a62892"},"headline":"Inori : interview avec Karlheinz Stockhausen","datePublished":"2012-01-16T11:18:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/"},"wordCount":2016,"commentCount":2,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2012\/01\/Inori_une.jpg","keywords":["claude samuel","Inori","Karlheinz Stockhausen"],"articleSection":["Entretien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/","url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/","name":"Inori : interview avec Karlheinz Stockhausen - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2012\/01\/Inori_une.jpg","datePublished":"2012-01-16T11:18:52+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/b90ba611e7b88b341392832913a62892"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2012\/01\/Inori_une.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2012\/01\/Inori_une.jpg","width":464,"height":237},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2012\/01\/inori-interview-avec-karlheinz-stockhausen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Inori : interview avec Karlheinz Stockhausen"}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/b90ba611e7b88b341392832913a62892","name":"Claude Samuel","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6cf65d26fc2092ade484c5e889299f4f7c3eb9919a7c08c819bf551affa7d1eb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6cf65d26fc2092ade484c5e889299f4f7c3eb9919a7c08c819bf551affa7d1eb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6cf65d26fc2092ade484c5e889299f4f7c3eb9919a7c08c819bf551affa7d1eb?s=96&d=mm&r=g","caption":"Claude Samuel"},"url":"https:\/\/www.ensembleintercontemporain.com\/fr\/author\/claude-samuel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/4196\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/users\/61\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/comments\/?post=4196"}],"version-history":[{"count":0,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/4196\/revisions\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/media\/4199\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/media\/?parent=4196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/categories\/?post=4196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/tags\/?post=4196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}