{"id":29821,"date":"2025-10-30T16:03:22","date_gmt":"2025-10-30T15:03:22","guid":{"rendered":"https:\/\/www.ensembleintercontemporain.com\/?p=29821"},"modified":"2025-11-21T11:51:53","modified_gmt":"2025-11-21T10:51:53","slug":"la-langue-du-corps-orgia-un-opera-dhector-parra","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/","title":{"rendered":"La langue du corps : \u00ab\u00a0Orgia\u00a0\u00bb, un op\u00e9ra d&rsquo;H\u00e8ctor Parra."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-23170\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/07\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd.jpg\" alt=\"\" width=\"1920\" height=\"1277\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/07\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd.jpg 1920w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/07\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd-300x200.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/07\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd-1024x681.jpg 1024w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/07\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd-768x511.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/07\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd-1536x1022.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p><span style=\"font-size: 12pt;\"><strong><span style=\"font-size: 18pt;\">D<\/span><span style=\"color: #003366;\">e la premi\u00e8re pi\u00e8ce \u00e9crite par Pier Paolo Pasolini pour le th\u00e9\u00e2tre, <em>Orgia\u00a0<\/em>(1968), le compositeur catalan H\u00e8ctor Parra tire un op\u00e9ra bouleversant, \u00e9crit pour trois chanteurs et ensemble, que Calixto Bieito mettra en sc\u00e8ne le <a href=\"https:\/\/www.ensembleintercontemporain.com\/fr\/concert\/eic-friends-orgia-2025-11-22-20h00-paris\/\">samedi 22 novembre 2025 \u00e0 la Cit\u00e9 de la musique<\/a>. Une virulente d\u00e9nonciation des rapports de domination de genre et de classe, qu&rsquo;H\u00e8ctor Parra d\u00e9taille \u00e0 travers l&rsquo;analyse de sa partition.\u00a0<\/span><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em>Eh bien, je vais te confier, avant de te quitter,<br \/>\n<\/em><em>que je voudrais \u00eatre compositeur de musique,<br \/>\n<\/em><em>vivre avec des instruments<br \/>\n<\/em><em>dans la tour de Viterbe que je n\u2019arrive pas \u00e0 acheter,<br \/>\n<\/em><em>dans le plus beau paysage du monde, o\u00f9 l\u2019Arioste<br \/>\n<\/em><em>serait fou de joie de se voir recr\u00e9\u00e9 avec toute<br \/>\n<\/em><em>l\u2019innocence des ch\u00eanes, collines, eaux et foss\u00e9s,<br \/>\n<\/em><em>et l\u00e0, composer de la musique,<br \/>\n<\/em><em>la seule action expressive<br \/>\n<\/em><em>peut-\u00eatre, haute, et ind\u00e9finissable comme les actions de la r\u00e9alit\u00e9. <\/em><\/p>\n<p style=\"text-align: center;\">Pier Paolo Pasolini,<br \/>\n<em>Qui je suis<\/em> (1966-67). Arl\u00e9a, Paris 2015<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">Cinq ans se sont \u00e9coul\u00e9s depuis que j\u2019ai termin\u00e9 <em>Les Bienveillantes<\/em>, un op\u00e9ra bas\u00e9 sur le roman \u00e9ponyme de Jonathan Littell, sur un livret de H\u00e4ndl Klaus et dans une mise en sc\u00e8ne de Calixto Bieito. Cet op\u00e9ra, ma sixi\u00e8me \u0153uvre sc\u00e9nique, \u00e9crit pour vingt solistes, ch\u0153ur et grand orchestre, pr\u00e9sente, comme le roman, un portrait intime et terrifiant du nazisme, de ses m\u00e9canismes de croissance et de d\u00e9ploiement id\u00e9ologique, social et militaire, jusqu&rsquo;\u00e0 l&rsquo;apog\u00e9e de ses crimes inimaginables.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Quatre ans plus tard, la composition de l&rsquo;op\u00e9ra <em>Orgia<\/em> avec Calixto Bieito, responsable du livret et de la mise en sc\u00e8ne, a marqu\u00e9 la poursuite d&rsquo;un engagement artistique centr\u00e9 sur les pr\u00e9occupations humaines, fondamentales dans l&rsquo;\u0153uvre de Pasolini. Le cr\u00e9ateur italien aux multiples facettes a d\u00e9nonc\u00e9 avec clairvoyance la fa\u00e7on dont le fascisme survit dans la soci\u00e9t\u00e9 moderne \u00e0 travers la culture de consommation. Ainsi, dans son dernier film <em>Sal\u00f3 ou les 120 jours de Sodome<\/em>, il met en sc\u00e8ne un univers concentrationnaire parfaitement organis\u00e9, fond\u00e9 sur les principes d&rsquo;ob\u00e9issance et de soumission.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Apr\u00e8s une douloureuse p\u00e9riode de convalescence en 1966 due \u00e0 un ulc\u00e8re, la seule maladie de sa vie, Pasolini esquisse les six trag\u00e9dies qui constituent l&rsquo;essentiel de son \u0153uvre th\u00e9\u00e2trale. Les deux th\u00e8mes qui unissent ces six trag\u00e9dies sont le r\u00eave et le sacrifice. L&rsquo;action th\u00e9\u00e2trale est remplac\u00e9e par l&rsquo;action mentale que les mots stimulent. La renaissance du th\u00e9\u00e2tre, selon Pasolini, passe donc par la revalorisation du mot et de l&rsquo;acteur en tant qu&rsquo;\u00e9metteur d&rsquo;id\u00e9es. L&rsquo;acteur doit \u00eatre un artiste beaucoup plus libre, car il ne d\u00e9pend pas tant du metteur en sc\u00e8ne, il a plus d&rsquo;autonomie et est conscient, devant le public, de son r\u00f4le de t\u00e9moin de la soci\u00e9t\u00e9 dans laquelle il vit.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Le th\u00e9\u00e2tre de Pasolini est essentiellement &#8211; et selon l&rsquo;expression m\u00eame de l&rsquo;auteur &#8211; un th\u00e9\u00e2tre de la parole : la parole est tout, la langue et la musique. Alors pourquoi faire un op\u00e9ra \u00e0 partir de ce th\u00e9\u00e2tre ? Pr\u00e9cis\u00e9ment parce qu&rsquo;en explorant les limites de la voix chant\u00e9e, o\u00f9 coexistent des formes de vocalit\u00e9 presque oppos\u00e9es, on peut s&rsquo;approcher de l&rsquo;id\u00e9al pasolinien, et rendre ainsi au langage sa capacit\u00e9 expressive \u00e0 travers une parole qui passe par la physiologie du corps lui-m\u00eame. Selon le phoniatre fran\u00e7ais Jean Albitbol, le bruit vocal est constitu\u00e9 par notre propre respiration, qui entre en collision avec les \u00e9l\u00e9ments de notre espace interne situ\u00e9s entre les cordes vocales et les l\u00e8vres. C&rsquo;est le chaos organis\u00e9 de la toile de fond de notre timbre vocal. Ce timbre se transforme en verbe, et le bruit devient la sc\u00e8ne \u00e0 travers laquelle se jouent les personnages que notre voix incarne.<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a> Avec la voix humaine, nous pouvons produire une multitude de timbres transitoires. Le contraste expressif est \u00e0 son maximum lorsqu&rsquo;une voix granuleuse ou semi-parl\u00e9e (partie centrale de la Fig. 1) coexiste avec un lyrisme qui permet la vibration de la voix chant\u00e9e dans toute sa puissance au d\u00e9but et \u00e0 la fin de cette phrase de l&rsquo;Uomo :<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29822 \" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-1.png\" alt=\"\" width=\"763\" height=\"110\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-1.png 881w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-1-300x43.png 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-1-768x111.png 768w\" sizes=\"auto, (max-width: 763px) 100vw, 763px\" \/><\/p>\n<p style=\"text-align: center;\"><em style=\"font-size: 12pt;\">Orgia, II Episode, m. 27-28. Partition vocale. Durand, 2024.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">Le contraste est plus d\u00e9licat lorsqu&rsquo;on explore les diff\u00e9rentes vocalit\u00e9s (voix de fausset, voix de t\u00eate, voix de poitrine, voix semi-parl\u00e9e, voix parl\u00e9e, voix a\u00e9rienne, etc.) associ\u00e9es \u00e0 des indications de caract\u00e8re et\/ou \u00e0 des d\u00e9formations rythmiques qui p\u00e9n\u00e8trent \u00e0 la fois les caract\u00e9ristiques de la langue elle-m\u00eame et la psychologie du personnage. La Donna commence son premier grand solo dans l&rsquo;op\u00e9ra avec le souvenir des abus inflig\u00e9s par son propre p\u00e8re (une attitude h\u00e9rit\u00e9e de son grand-p\u00e8re) et qui la conduisent \u00e0 un chant d\u00e9sesp\u00e9r\u00e9, exprim\u00e9 avec un lyrisme m\u00e9lancolique. Dans la Fig. 2, nous percevons d\u00e9j\u00e0 le malaise qu&rsquo;elle \u00e9prouve \u00e0 se rem\u00e9morer son pass\u00e9 traumatique :<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29824\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-2.png\" alt=\"\" width=\"519\" height=\"156\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-2.png 602w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-2-300x90.png 300w\" sizes=\"auto, (max-width: 519px) 100vw, 519px\" \/><\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><em style=\"font-size: 12pt;\">Orgia, I Episode, m. 196. Partition vocale. Durand, 2024.<\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><em>\u00a0<\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Selon Davide Bertel\u00e8<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>, le corps est consid\u00e9r\u00e9 par les personnages d&rsquo;<em>Orgia<\/em> comme une \u00e9manation directe de la pens\u00e9e de l&rsquo;auteur, \u00ab\u00a0le plus expressif des langages\u00a0\u00bb. Le mot est totalement incapable d&rsquo;exprimer l&rsquo;\u00e9nigme de la chair : les deux protagonistes d&rsquo;<em>Orgia<\/em> tentent, \u00e0 travers l&rsquo;acte sexuel, de conserver un rapport visc\u00e9ral avec la r\u00e9alit\u00e9, afin de surmonter l&rsquo;\u00e9tat d&rsquo;ali\u00e9nation caus\u00e9 par la rationalit\u00e9 du mot ali\u00e9n\u00e9. Ainsi, ils ne s&rsquo;expriment pleinement que lorsque ce sont des actions physiques qui \u00ab\u00a0parlent\u00a0\u00bb.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">Le frottement entre la po\u00e9sie de Pasolini et une \u00e9criture vocale capable de l&rsquo;exprimer est in\u00e9vitable. Selon l&rsquo;historien de l&rsquo;art Abdelkader Damani, dans l&rsquo;op\u00e9ra <em>Orgia<\/em>, la cruaut\u00e9 des mots se m\u00eale \u00e0 la fragilit\u00e9 des personnages, pour finalement s&rsquo;exprimer \u00e0 travers une musique dont l&rsquo;\u00e9criture est n\u00e9e de la rencontre du compositeur avec la sculpture hell\u00e9nistique.<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a> Ainsi, lors de ma r\u00e9sidence \u00e0 la Villa M\u00e9dicis \/ Acad\u00e9mie de France \u00e0 Rome entre septembre 2021 et ao\u00fbt 2022, j&rsquo;ai dessin\u00e9 une s\u00e9rie de torses antiques. Mon but \u00e9tait d&rsquo;\u00e9couter leurs voix, de ressentir leurs tensions internes et leurs rythmes externes afin de stimuler l&rsquo;imagination lyrique qui donnerait vie aux deux protagonistes d&rsquo;<em>Orgia<\/em>. Inspir\u00e9e par la mani\u00e8re particuli\u00e8re et radicale de Pasolini d&rsquo;explorer le pass\u00e9 pour \u00e9clairer le pr\u00e9sent d&rsquo;une lumi\u00e8re nouvelle, capable de nous projeter dans l&rsquo;avenir, j&rsquo;ai \u00e9tudi\u00e9 attentivement cette \u00ab\u00a0lingua del corpo\u00a0\u00bb qui est \u00e0 la base de notre culture, afin de l&rsquo;exprimer plastiquement de mani\u00e8re directe et gestuellement palpable. Chaque coup de pinceau r\u00e9v\u00e8le sa direction, l&rsquo;\u00e9nergie avec laquelle il a \u00e9t\u00e9 r\u00e9alis\u00e9, sa relation avec les autres, ainsi que sa fonction structurelle au sein de l&rsquo;ensemble.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29826 size-medium\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-3-246x300.png\" alt=\"\" width=\"246\" height=\"300\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-3-246x300.png 246w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-3.png 410w\" sizes=\"auto, (max-width: 246px) 100vw, 246px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><em>H\u00e8ctor Parra, encre de Chine sur papier 200 g\/m2. Satiro Combattente (marbre, 120-140 av. J.-C., Rome, Galleria Borghese). Photographie : Th\u00e9odora Barat.<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">Apr\u00e8s chaque s\u00e9ance de dessin dans les mus\u00e9es romains, j&rsquo;ai rev\u00e9cu dans l&rsquo;atelier de composition les \u00e9tats psychologiques exp\u00e9riment\u00e9s devant les originaux grecs et romains et, devant le texte pasolinien adapt\u00e9 par Calixto Bieito, j&rsquo;ai donn\u00e9 naissance \u00e0 la partition vocale d&rsquo;<em>Orgia<\/em>.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Comme me l&rsquo;a dit Damani, il ne s&rsquo;agit pas seulement d&rsquo;un travail pluridisciplinaire, mais plut\u00f4t d&rsquo;une \u00ab\u00a0migration des disciplines\u00a0\u00bb, d&rsquo;un art de la mort et de la r\u00e9surrection permanente des diff\u00e9rents champs disciplinaires lorsqu&rsquo;ils se confrontent. Il ne s&rsquo;agissait pas seulement de s&rsquo;inspirer du texte de Pasolini, mais d&rsquo;en renouveler la lecture et la musicalit\u00e9, en ramenant \u00e0 la r\u00e9alit\u00e9 les voix de ses protagonistes et de leurs anc\u00eatres. D&rsquo;une certaine mani\u00e8re, dans chaque phrase musicale, dans chaque geste vocal exprim\u00e9 dans la partition d&rsquo;<em>Orgia<\/em>, nous retrouvons les traces de leurs corps.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">Cette exp\u00e9rience plastique et esth\u00e9tique m&rsquo;a permis de d\u00e9velopper un lyrisme fluide, organique et prot\u00e9iforme qui, selon la nature du texte, prend diff\u00e9rentes formes. L\u00e0 o\u00f9 le flux de la parole est plus rapide et les dialogues plus vifs et tranchants, les lignes m\u00e9lodiques suivent de pr\u00e8s les profils sinueux et rythmiques de la langue italienne originale. Ainsi, les principales couleurs phon\u00e9tiques de chaque phrase sont accentu\u00e9es par des dynamiques et des registres plus extr\u00eames, tandis que les passages transitoires sont exprim\u00e9s d&rsquo;une voix presque parl\u00e9e. \u00c0 certains moments pr\u00e9cis, en accord avec les caract\u00e9ristiques du texte de pasolinien, le chant lyrique c\u00e8de la place \u00e0 une voix purement parl\u00e9e, d\u00e9pouill\u00e9e de tout lyrisme. Dans le passage suivant, en prol\u00e9gom\u00e8nes \u00e0 l&rsquo;acte sexuel sadomasochiste, l&rsquo;Uomo dit \u00e0 la Donna que la raison pour laquelle il la d\u00e9shumanise et la punira est sa passivit\u00e9 : \u00ab\u00a0Pour ta passivit\u00e9, si inhumaine qu&rsquo;elle te prive de toute dignit\u00e9\u00a0\u00bb. Au milieu de la mesure 48 du IIe \u00e9pisode, le baryton atteint son point culminant (<em>mi<\/em> b\u00e9mol), mais descend rapidement pour terminer la phrase d&rsquo;une voix purement parl\u00e9e, accentuant ainsi le caract\u00e8re brutal et pas du tout lyrique de son propos. Son geste vocal est doubl\u00e9 par le hautbois. Bien que de tessiture plus \u00e9lev\u00e9e, le hautbois incarnera tout au long de l&rsquo;op\u00e9ra \u00ab\u00a0la chose double\u00a0\u00bb qu&rsquo;est l&rsquo;Uomo d&rsquo;<em>Orgia<\/em>. Sur l&rsquo;expression parl\u00e9e \u00ab\u00a0qui te d\u00e9pouille de toute dignit\u00e9\u00a0\u00bb, l&rsquo;harmonie orchestrale est paradoxalement stabilis\u00e9e sur un accord parfait majeur sur sol naturel, dans le but de rendre les intentions sadiques de l&rsquo;Uomo plus terrifiantes et incompr\u00e9hensibles :<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29830\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-5.png\" alt=\"\" width=\"412\" height=\"310\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-5.png 564w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-5-300x226.png 300w\" sizes=\"auto, (max-width: 412px) 100vw, 412px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><em>Orgia, II Episode, c. 48. Partition vocale. Durand, 2024.<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">Les quatre premiers \u00e9pisodes d&rsquo;<em>Orgia<\/em> se d\u00e9roulent dans la chambre conjugale d&rsquo;un homme et d&rsquo;une femme de la classe moyenne, \u00e2g\u00e9s d&rsquo;une trentaine d&rsquo;ann\u00e9es. Un couple d&rsquo;enseignants avec deux enfants, profond\u00e9ment divis\u00e9s, embl\u00e9matiquement oppos\u00e9s, unis exclusivement par un lien sadomasochiste. Pour eux, la soci\u00e9t\u00e9 est une prison insupportable, \u00e0 l&rsquo;int\u00e9rieur de laquelle ils d\u00e9couvrent une nouvelle libert\u00e9. Georgios Katsantonis observe que, selon l&rsquo;esth\u00e9tique sadienne, dans <em>Orgia<\/em>, le mot seul devient source de plaisir. La description minutieuse et le d\u00e9tail avec lesquels l&rsquo;Uomo d\u00e9crit \u00e0 la femme ce qu&rsquo;il va lui faire est pour eux une source de jouissance. Le mot \u00e9voque quelque chose d&rsquo;\u00e9rotique, comme s&rsquo;il se faisait chair. \u00c0 la recherche d&rsquo;une nouvelle r\u00e9alit\u00e9 \u00e0 travers le langage exasp\u00e9r\u00e9 et d\u00e9form\u00e9 de la chair, Uomo et Donna s&rsquo;appuient sur la violence sadomasochiste pour se lib\u00e9rer de la captivit\u00e9 de la r\u00e9alit\u00e9 du pr\u00e9sent : en se blessant et en se d\u00e9chirant l&rsquo;un l&rsquo;autre, les deux personnages en viennent finalement \u00e0 violer non seulement leur corps, mais aussi le pass\u00e9, qui doit \u00eatre continuellement pr\u00e9serv\u00e9, d\u00e9sarticul\u00e9, pleur\u00e9 et blasph\u00e9m\u00e9. Ainsi, dans <em>Orgia<\/em>, le sadisme est mis en pratique comme un d\u00e9fi \u00e0 la soci\u00e9t\u00e9.<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">La projection mentale du rituel sadomasochiste de l&rsquo;\u00e9pisode II est d\u00e9velopp\u00e9e musicalement en combinant l&rsquo;expression vocale calme, sensuelle, pleine d&rsquo;attente et parfois m\u00eame flirteuse de Donna avec la voix plus dure, plus s\u00e8che et plus violente de l&rsquo;homme, comme le montre la figure ci-dessous :<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29832\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-6.png\" alt=\"\" width=\"797\" height=\"362\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-6.png 885w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-6-300x136.png 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-6-768x349.png 768w\" sizes=\"auto, (max-width: 797px) 100vw, 797px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><em>Orgia, Episode II, c. 50-51. <\/em><em>Partition vocale. Durand, 2024.<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">Sur une texture orchestrale inqui\u00e9tante et de plus en plus agit\u00e9e, l&rsquo;Uomo interpelle la Donna avec une voix de fausset pleine de tendresse et d&rsquo;apparente innocence, pour ensuite exprimer sa violence et son d\u00e9sir de domination, ext\u00e9rioris\u00e9s vocalement \u00e0 travers un langage musical hi\u00e9ratique et dur, \u00e0 la vocalit\u00e9 puissante et aux intervalles harmoniques purs de 5\u00e8me, 4\u00e8me ou tierce majeure combin\u00e9s \u00e0 des tritons, qui agissent comme des \u00ab\u00a0figures\u00a0\u00bb d&rsquo;une \u00e9nigme musicale ancestrale. Ainsi, dans la figure ci-dessous, la quinte initiale Mib-Sib est suivie de la tierce majeure La-Do# plus le Sol naturel qui forme un triton avec le Do#, et qui agit en m\u00eame temps comme la septi\u00e8me du La) :<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29834 size-medium\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-7-300x137.png\" alt=\"\" width=\"300\" height=\"137\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-7-300x137.png 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-7-768x351.png 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-7.png 885w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><em>Orgia, Episode II, c. 58-59. <\/em><em>Partition vocale. Durand, 2024.<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">Pasolini ressent un fort besoin d&rsquo;\u00e9voquer le pass\u00e9 pour trouver l&rsquo;origine des obsessions du pr\u00e9sent, inspir\u00e9 par les trag\u00e9dies grecques con\u00e7ues comme porteuses de la sagesse de l&rsquo;ancien monde pr\u00e9industriel. La prise en compte du pass\u00e9 le conduit, \u00e0 travers les id\u00e9es de totem et de tabou, \u00e0 la g\u00e9n\u00e9ration de la violence sacrificielle, \u00e0 la n\u00e9cessit\u00e9 d&rsquo;une victime pour racheter la soci\u00e9t\u00e9. Cette violence corporelle, physique et po\u00e9tique \u00e0 la fois, est exprim\u00e9e musicalement de mani\u00e8re extr\u00eame dans certaines parties orchestrales, en particulier dans les deux passages culminants des \u00c9pisodes II et V. La figure ci-dessous montre comment la sensualit\u00e9 insinuante de l&rsquo;\u201ceffet de baiser\u201d du hautbois (<em>kissing effect<\/em>), les gestes sonores \u00e9nergiques et progressivement stridents de la clarinette basse, les \u00ab\u00a0souffles sonores\u00a0\u00bb de la trompette et du trombone, ainsi que l&rsquo;utilisation du fouet dans la percussion, sont combin\u00e9s sur le plan rythmique :<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29836\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-8.png\" alt=\"\" width=\"760\" height=\"407\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-8.png 885w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-8-300x161.png 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-8-768x411.png 768w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><em>Orgia, Episode V, c. 85-88. <\/em><em>Partition d\u2019orchestre. Durand, 2024.<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">Selon Davide Bertel\u00e8, dans le caract\u00e8re phonique du mot, il est possible de trouver cette trace primordiale que Pasolini d\u00e9finit comme le \u00ab\u00a0moment purement oral du langage\u00a0\u00bb, identifiable dans le \u00ab\u00a0cri de la b\u00eate et des besoins physiques, des instincts\u00a0\u00bb, et qui s&rsquo;av\u00e8re \u00eatre le principal responsable du rapport authentique, et donc sacr\u00e9, avec la r\u00e9alit\u00e9.<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a> Un archa\u00efsme que l&rsquo;on retrouve d&rsquo;une certaine mani\u00e8re dans les sons physiologiques mis en \u0153uvre dans l&rsquo;exemple instrumental ci-dessus.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Dans les passages o\u00f9 les personnages d&rsquo;<em>Orgia<\/em> expriment le contraste, si typique de Pasolini, entre le pr\u00e9sent consum\u00e9riste et d\u00e9shumanisant et un pass\u00e9 pr\u00e9industriel id\u00e9alis\u00e9 par lui, la musique orchestrale, \u00e0 travers les sons de l&rsquo;archiluth et de la harpe, se transforme pour nous ramener aux origines du genre op\u00e9ratique, en citant des passages cl\u00e9s de l&rsquo;<em>Euridice<\/em> de Peri et de l&rsquo;<em>Orfeo<\/em> de Monteverdi. Dans l&rsquo;\u00e9pisode III, les deux personnages et les bois de l&rsquo;orchestre chantent, en citant librement et en se transformant constamment, le passage dans lequel la messag\u00e8re de l&rsquo;op\u00e9ra <em>Orfeo<\/em> de Monteverdi annonce au demi-dieu la mort de sa bien-aim\u00e9e. Ce fragment lyrique inoubliable de l&rsquo;\u0153uvre fondatrice du genre op\u00e9ratique, avec ses m\u00e9lismes archa\u00efques, sa modalit\u00e9 \u00e9nigmatique et son pathos triste, se constitue ainsi en paradigme de la mort et du malheur exprim\u00e9s en musique, conf\u00e9rant \u00e0 <em>Orgia<\/em> une tonalit\u00e9 ancestrale.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Mais l&rsquo;apog\u00e9e lyrique de l&rsquo;op\u00e9ra se trouve au moment o\u00f9 la protagoniste f\u00e9minine, \u00e0 la fin de l&rsquo;\u00e9pisode IV, planifie et ex\u00e9cute l&rsquo;acte terrible de M\u00e9d\u00e9e, \u00e0 travers une sarabande de douze minutes, inspir\u00e9e et bas\u00e9e sur la <em>Suite fran\u00e7aise n\u00b0 6<\/em> de Bach. L&rsquo;infanticide, dans le cas d&rsquo;<em>Orgia<\/em>, n&rsquo;est pas une arme que la m\u00e8re utilise pour se venger de son conjoint, le p\u00e8re de ses enfants. Alors que M\u00e9d\u00e9e joue un r\u00f4le actif et se venge de Jason, la Donna est d\u00e9pass\u00e9e par la situation et abandonne le combat.<\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: 14pt;\"><em>\u00c0 pr\u00e9sent quelque chose a boug\u00e9 dans la chambre,<br \/>\n<\/em><\/span><span style=\"font-size: 14pt;\"><em>comme dans un corps un battement de c\u0153ur, je l\u2019ai entendu.<br \/>\n<\/em><\/span><span style=\"font-size: 14pt;\"><em>L\u2019air dans l\u2019air a remu\u00e9.<br \/>\n<\/em><\/span><span style=\"font-size: 14pt;\"><em>Une esp\u00e8ce de coup dans la profondeur du ciel !<br \/>\n<\/em><\/span><span style=\"font-size: 14pt;\"><em>Et le contrecoup est arriv\u00e9 jusqu\u2019ici,<br \/>\n<\/em><\/span><span style=\"font-size: 14pt;\"><em>Souffle d\u00e9risoire de l\u2019air,<br \/>\n<\/em><\/span><span style=\"font-size: 14pt;\"><em>qui donne une \u00e9motion m\u00e9connaissable. <\/em><\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: 14pt;\"><em>\u00a0<\/em><\/span><span style=\"font-size: 14pt;\">Pier Paolo Pasolini<br \/>\n<em>Orgia<\/em>, \u00c9pisode IV, 1968 Actes Sud<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">Selon Herv\u00e9 Joubert-Laurencin, la premi\u00e8re et peut-\u00eatre la seule tradition po\u00e9tique \u00e0 laquelle Pasolini explicite d\u00e9lib\u00e9r\u00e9ment son appartenance est celle de la po\u00e9sie proven\u00e7ale des XIIe et XIIIe si\u00e8cles. Impr\u00e9gn\u00e9 de l&rsquo;\u201cAb joi\u201d troubadour, chez Pasolini \u00ab\u00a0un mouvement minimal imprim\u00e9 dans l&rsquo;air\u00a0\u00bb se communique \u00e0 chaque mol\u00e9cule de l&rsquo;atmosph\u00e8re terrestre, et donc \u00e0 chaque mot.<a href=\"#_ftn6\" name=\"_ftnref6\">[6]<\/a> Ce souffle d&rsquo;air poss\u00e8de une puissance capable de pousser la Donna \u00e0 commettre le crime inimaginable de tuer ses deux enfants puis de se suicider. C&rsquo;est ici que le chant lyrique s&rsquo;\u00e9l\u00e8ve au-dessus de l&rsquo;orchestre. Les lignes m\u00e9lodiques, inspir\u00e9es par la voix expressive au registre large et au legato sublime de la soprano Ausrine Stundyte (qui a cr\u00e9\u00e9 l&rsquo;op\u00e9ra en juin 2023 avec le baryton Leigh Melrose et la soprano Jone Mart\u00ednez) s&rsquo;\u00e9largissent, explorant des couleurs et des registres op\u00e9ratiques marqu\u00e9s, proches de la tradition italienne :<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29838\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-9.png\" alt=\"\" width=\"742\" height=\"101\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-9.png 881w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-9-300x41.png 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/figure-9-768x105.png 768w\" sizes=\"auto, (max-width: 742px) 100vw, 742px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\"><em>Orgia, Episode IV, c. 141-143. <\/em><em>Partition vocale. Durand, 2024.<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">L&rsquo;orchestre contrebalance ce lyrisme de la Donna par des sonorit\u00e9s au spectre strident et aux textures instables, soulignant la fragilit\u00e9 et la beaut\u00e9 \u00e9ph\u00e9m\u00e8re de la condition humaine, tandis que l&rsquo;archiluth, accompagnant la voix, d\u00e9veloppe le chant harmonique de la sarabande dans toute sa pl\u00e9nitude.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Mais <em>Orgia<\/em> commence et se termine par le suicide de l&rsquo;Uomo. Pour exposer et d\u00e9noncer son drame personnel, celui de ne pas avoir pu vivre pleinement son homosexualit\u00e9, qu&rsquo;il a r\u00e9prim\u00e9e toute sa vie sous le couvert d&rsquo;un mariage bourgeois, il se pend. Il le fait v\u00eatu des v\u00eatements laiss\u00e9s \u00e0 la maison par la prostitu\u00e9e qu&rsquo;il voulait tuer, quelques semaines apr\u00e8s la mort de sa femme et de ses enfants, dans un nouveau paroxysme sadique. En effet, dans les derniers moments de sa vie, conscient de sa diff\u00e9rence, de son homosexualit\u00e9, il accomplit l&rsquo;acte le plus puissant qu&rsquo;il soit capable de concevoir : un suicide accusateur qui d\u00e9nonce une soci\u00e9t\u00e9 pleine d&rsquo;incompr\u00e9hension, d&rsquo;hypocrisie, de cruaut\u00e9 et de m\u00e9pris pour toute forme de minorit\u00e9.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Avec la r\u00e9alisation de l&rsquo;op\u00e9ra <em>Orgia<\/em>, dans lequel interagissent fortement les contradictions des \u00eatres humains dans la soci\u00e9t\u00e9, et qui nous rendent fragiles, h\u00e9sitants ou violents, notre objectif est de promouvoir un dialogue entre la litt\u00e9rature de Pasolini et la musique, en contribuant \u00e0 une \u201caction hautement expressive, et ind\u00e9finissable comme les actions de la r\u00e9alit\u00e9\u201d.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">H\u00e8ctor Parra, avril 2024<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Abitbol, Jean. <em>L&rsquo;Odyss\u00e9e de la voix<\/em>. Champs (n\u00b0 1078) &#8211; Champs sciences. Flammarion, 15\/05\/2013.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Bertel\u00e8, Davide. <em>Pasolini alla prova di Orgia: Dal laboratorio drammaturgico alla regia torinese del 1968.<\/em> Pg. 98. Ianieri Edizioni srls (25 f\u00e9vrier 2021).<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> Damani, Abdelkader (collectif). <em>\u00c9tincelles \/ Scintille.<\/em> Pg. 96-103. Villa M\u00e9dicis, Rome, 2022.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Katsantonis, Georgios.<em> Anatomia del potere. Orgia, Porcile, Calder\u00f3n. Pasolini drammaturgo vs. Pasolini filosofo.<\/em> Pg. 32-33. Metauro Edizioni (28 juillet 2021).<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> Bertel\u00e8, Davide. <em>Pasolini alla prova di Orgia: Dal laboratorio drammaturgico alla regia torinese del 1968.<\/em> Pg. 108. Ianieri Edizioni srls (25 f\u00e9vrier 2021).<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a> Joubert-Laurencin, Herv\u00e9. <em>Le grand chant: Pasolini &#8211; Po\u00e8te et cin\u00e9aste.<\/em> Pg. 83-87. \u00c9ditions Macula (19 ao\u00fbt 2022, Paris).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Photos (de haut en bas) : \u00a9 Amandine Lauriol<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De la premi\u00e8re pi\u00e8ce \u00e9crite par Pier Paolo Pasolini pour le th\u00e9\u00e2tre, \u00ab\u00a0Orgia\u00a0\u00bb\u00a0(1968), le compositeur catalan H\u00e8ctor Parra tire un op\u00e9ra bouleversant, \u00e9crit pour trois chanteurs et ensemble, que Calixto Bieito mettra en sc\u00e8ne le samedi 22 novembre 2025 \u00e0 la Cit\u00e9 de la musique. Une virulente d\u00e9nonciation des rapports de domination de genre et de classe, qu&rsquo;H\u00e8ctor Parra d\u00e9taille \u00e0 travers l&rsquo;analyse de sa partition.\u00a0<\/p>\n","protected":false},"author":241,"featured_media":23170,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[102],"tags":[],"class_list":["post-29821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eclairage","concert-eic-friends-orgia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La langue du corps : &quot;Orgia&quot;, un op\u00e9ra d&#039;H\u00e8ctor Parra. - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La langue du corps : &quot;Orgia&quot;, un op\u00e9ra d&#039;H\u00e8ctor Parra. - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"De la premi\u00e8re pi\u00e8ce \u00e9crite par Pier Paolo Pasolini pour le th\u00e9\u00e2tre, &quot;Orgia&quot;\u00a0(1968), le compositeur catalan H\u00e8ctor Parra tire un op\u00e9ra bouleversant, \u00e9crit pour trois chanteurs et ensemble, que Calixto Bieito mettra en sc\u00e8ne le samedi 22 novembre 2025 \u00e0 la Cit\u00e9 de la musique. Une virulente d\u00e9nonciation des rapports de domination de genre et de classe, qu&#039;H\u00e8ctor Parra d\u00e9taille \u00e0 travers l&#039;analyse de sa partition.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-30T15:03:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T10:51:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/07\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"H\u00e8ctor Parra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"H\u00e8ctor Parra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2025\\\/10\\\/la-langue-du-corps-orgia-un-opera-dhector-parra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2025\\\/10\\\/la-langue-du-corps-orgia-un-opera-dhector-parra\\\/\"},\"author\":{\"name\":\"H\u00e8ctor Parra\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/37e4ba43a15488149bccee91529c3e32\"},\"headline\":\"La langue du corps : \u00ab\u00a0Orgia\u00a0\u00bb, un op\u00e9ra d&rsquo;H\u00e8ctor Parra.\",\"datePublished\":\"2025-10-30T15:03:22+00:00\",\"dateModified\":\"2025-11-21T10:51:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2025\\\/10\\\/la-langue-du-corps-orgia-un-opera-dhector-parra\\\/\"},\"wordCount\":3130,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2025\\\/10\\\/la-langue-du-corps-orgia-un-opera-dhector-parra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2022\\\/07\\\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd.jpg\",\"articleSection\":[\"\u00c9clairage\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2025\\\/10\\\/la-langue-du-corps-orgia-un-opera-dhector-parra\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2025\\\/10\\\/la-langue-du-corps-orgia-un-opera-dhector-parra\\\/\",\"name\":\"La langue du corps : \\\"Orgia\\\", un op\u00e9ra d'H\u00e8ctor Parra. - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2025\\\/10\\\/la-langue-du-corps-orgia-un-opera-dhector-parra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2025\\\/10\\\/la-langue-du-corps-orgia-un-opera-dhector-parra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2022\\\/07\\\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd.jpg\",\"datePublished\":\"2025-10-30T15:03:22+00:00\",\"dateModified\":\"2025-11-21T10:51:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/37e4ba43a15488149bccee91529c3e32\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2025\\\/10\\\/la-langue-du-corps-orgia-un-opera-dhector-parra\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2025\\\/10\\\/la-langue-du-corps-orgia-un-opera-dhector-parra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2025\\\/10\\\/la-langue-du-corps-orgia-un-opera-dhector-parra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2022\\\/07\\\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2022\\\/07\\\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd.jpg\",\"width\":1920,\"height\":1277,\"caption\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2025\\\/10\\\/la-langue-du-corps-orgia-un-opera-dhector-parra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La langue du corps : \u00ab\u00a0Orgia\u00a0\u00bb, un op\u00e9ra d&rsquo;H\u00e8ctor Parra.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/37e4ba43a15488149bccee91529c3e32\",\"name\":\"H\u00e8ctor Parra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f52b9bdb650b6fd7715d17c00b95af5889a6c9454fdf624b872d849f50465ffc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f52b9bdb650b6fd7715d17c00b95af5889a6c9454fdf624b872d849f50465ffc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f52b9bdb650b6fd7715d17c00b95af5889a6c9454fdf624b872d849f50465ffc?s=96&d=mm&r=g\",\"caption\":\"H\u00e8ctor Parra\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/author\\\/hector-parra\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La langue du corps : \"Orgia\", un op\u00e9ra d'H\u00e8ctor Parra. - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/","og_locale":"fr_FR","og_type":"article","og_title":"La langue du corps : \"Orgia\", un op\u00e9ra d'H\u00e8ctor Parra. - Ensemble intercontemporain","og_description":"De la premi\u00e8re pi\u00e8ce \u00e9crite par Pier Paolo Pasolini pour le th\u00e9\u00e2tre, \"Orgia\"\u00a0(1968), le compositeur catalan H\u00e8ctor Parra tire un op\u00e9ra bouleversant, \u00e9crit pour trois chanteurs et ensemble, que Calixto Bieito mettra en sc\u00e8ne le samedi 22 novembre 2025 \u00e0 la Cit\u00e9 de la musique. Une virulente d\u00e9nonciation des rapports de domination de genre et de classe, qu'H\u00e8ctor Parra d\u00e9taille \u00e0 travers l'analyse de sa partition.\u00a0","og_url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2025-10-30T15:03:22+00:00","article_modified_time":"2025-11-21T10:51:53+00:00","og_image":[{"width":1920,"height":1277,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/07\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd.jpg","type":"image\/jpeg"}],"author":"H\u00e8ctor Parra","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"H\u00e8ctor Parra","Dur\u00e9e de lecture estim\u00e9e":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/"},"author":{"name":"H\u00e8ctor Parra","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/37e4ba43a15488149bccee91529c3e32"},"headline":"La langue du corps : \u00ab\u00a0Orgia\u00a0\u00bb, un op\u00e9ra d&rsquo;H\u00e8ctor Parra.","datePublished":"2025-10-30T15:03:22+00:00","dateModified":"2025-11-21T10:51:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/"},"wordCount":3130,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/07\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd.jpg","articleSection":["\u00c9clairage"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/","url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/","name":"La langue du corps : \"Orgia\", un op\u00e9ra d'H\u00e8ctor Parra. - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/07\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd.jpg","datePublished":"2025-10-30T15:03:22+00:00","dateModified":"2025-11-21T10:51:53+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/37e4ba43a15488149bccee91529c3e32"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/07\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/07\/2021-04-19-concert-intercontemporain-hector-parra-alauriol-7-bd.jpg","width":1920,"height":1277,"caption":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2025\/10\/la-langue-du-corps-orgia-un-opera-dhector-parra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La langue du corps : \u00ab\u00a0Orgia\u00a0\u00bb, un op\u00e9ra d&rsquo;H\u00e8ctor Parra."}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/37e4ba43a15488149bccee91529c3e32","name":"H\u00e8ctor Parra","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f52b9bdb650b6fd7715d17c00b95af5889a6c9454fdf624b872d849f50465ffc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f52b9bdb650b6fd7715d17c00b95af5889a6c9454fdf624b872d849f50465ffc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f52b9bdb650b6fd7715d17c00b95af5889a6c9454fdf624b872d849f50465ffc?s=96&d=mm&r=g","caption":"H\u00e8ctor Parra"},"url":"https:\/\/www.ensembleintercontemporain.com\/fr\/author\/hector-parra\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/29821\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/users\/241\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/comments\/?post=29821"}],"version-history":[{"count":11,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/29821\/revisions\/"}],"predecessor-version":[{"id":29938,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/29821\/revisions\/29938\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/media\/23170\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/media\/?parent=29821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/categories\/?post=29821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/tags\/?post=29821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}