{"id":23656,"date":"2022-12-10T19:48:21","date_gmt":"2022-12-10T18:48:21","guid":{"rendered":"https:\/\/www.ensembleintercontemporain.com\/?p=23656"},"modified":"2022-12-10T19:48:21","modified_gmt":"2022-12-10T18:48:21","slug":"les-iles-vagabondes-dolga-neuwirth","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/","title":{"rendered":"Les \u00eeles vagabondes d&rsquo;Olga Neuwirth."},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-23657\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4914-max10mb-nb.jpg\" alt=\"\" width=\"1862\" height=\"1242\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4914-max10mb-nb.jpg 1862w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4914-max10mb-nb-300x200.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4914-max10mb-nb-1024x683.jpg 1024w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4914-max10mb-nb-768x512.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4914-max10mb-nb-1536x1025.jpg 1536w\" sizes=\"auto, (max-width: 1862px) 100vw, 1862px\" \/><\/strong><\/p>\n<p><span style=\"color: #003366;\"><strong><span style=\"font-size: 14pt;\">C<\/span>r\u00e9\u00e9 il y a d\u00e9j\u00e0 sept ans, <em>Le Encantadas o le avventure nel\u00a0mare delle meraviglie <\/em>(Le Encantadas\u00a0ou les aventures en mer des merveilles) d\u2019Olga\u00a0Neuwirth est l\u2019unique \u0153uvre, mais quelle \u0153uvre, au programme du concert du 13 d\u00e9cembre \u00e0 la Cit\u00e9 de la musique. La compositrice autrichienne nous embarque pour une grande odyss\u00e9e\u00a0imaginaire de Venise aux <em>Encantadas<\/em>, \u00eeles enchant\u00e9es des Gal\u00e1pagos. R\u00e9alis\u00e9 peu avant la cr\u00e9ation de l\u2019\u0153uvre en 2015 ce grand entretien en retrace la gen\u00e8se et en expose les multiples ramifications litt\u00e9raires et musicales. \u00a0\u00a0<\/strong><\/span><\/p>\n<p><strong>Dans <em>Le Encantadas<\/em>, on est frapp\u00e9 par plusieurs \u00e9l\u00e9ments. Le titre, d\u2019abord, qui se r\u00e9f\u00e8re \u00e0 une \u0153uvre de Herman Melville traitant en 1854 de l\u2019archipel des Galapagos, un ensemble d\u2019\u00eeles jadis baptis\u00e9 Las Encantadas par les Espagnols. La conception spatiale et le rapport \u00e0 la ville de Venise, ensuite, qui tissent un lien avec le <em>Prometeo<\/em> de Luigi Nono. \u00c0 partir de ces deux observations surgit enfin l\u2019id\u00e9e d\u2019une disposition de diff\u00e9rentes sections sous forme d\u2019\u00eeles et celle d\u2019un voyage d\u2019\u00eele en \u00eele, qui joue un r\u00f4le important chez Nono et Melville, mais aussi dans nombre de vos partitions anciennes.<br \/>\n<\/strong><span style=\"font-size: 14pt;\">En effet, ma confrontation avec Melville est continue et d\u00e9terminante, m\u00eame si elle a d\u00e9bouch\u00e9 sur une double d\u00e9ception. Il y a mon projet inachev\u00e9 de film sur Melville, <em>Songs of the Unleashed Ocean <\/em>: j\u2019en ai certes termin\u00e9 le script et ai visit\u00e9 tous les lieux aux \u00c9tats-Unis o\u00f9 Melville a s\u00e9journ\u00e9, mais le film n\u2019a pas pu \u00eatre r\u00e9alis\u00e9 pour des raisons financi\u00e8res, m\u00eame si les deux acteurs principaux, anglo-am\u00e9ricains, et tout \u00e0 fait merveilleux, avaient donn\u00e9 leur accord. Et puis, il y a mon hommage \u00e0 Melville, <em>The Outcast, A Musicstallation &#8211;<\/em><em> Theater with Video<\/em>, dont la cr\u00e9ation a eu lieu en 2012 mais s\u2019est r\u00e9v\u00e9l\u00e9e insatisfaisante pour toutes sortes de raisons, et qui attend donc une v\u00e9ritable premi\u00e8re.<br \/>\nJ\u2019ai toujours \u00e9t\u00e9 s\u00e9duite par les allusions maritimes au sein d\u2019espaces sacr\u00e9s, comme les ressemblances entre chaire et navire dans la Seamen\u2019s Bethel \u00e0 New Bedford ou comme certaines particularit\u00e9s locales des \u00e9glises v\u00e9nitiennes, notamment le ch\u0153ur sur\u00e9lev\u00e9 qu\u2019on appelle <em>barco <\/em>ou ces plafonds en bois, destin\u00e9s \u00e0 am\u00e9liorer l\u2019acoustique, et qu\u2019on dit <em>a carena di mare <\/em>(en forme de car\u00e8ne). Tout cela est n\u00e9 d\u2019un amour de longue date pour l\u2019architecture et les villes situ\u00e9es pr\u00e8s de la mer et pour l\u2019incompr\u00e9hensibilit\u00e9 de cette mer en tant que telle. Le th\u00e8me \u00ab\u00a0architecture et mer \u00e0 Venise\u00a0\u00bb m\u2019a beaucoup hant\u00e9e, tout comme le fait que Jacopo Sansovino et Andrea Palladio aient eu beaucoup d\u2019amis musiciens avec lesquels ils discutaient de questions d\u2019acoustique, ou encore que Leon Battista Alberti et Palladio se soient souvenus d\u2019un conseil de Vitruve en int\u00e9grant dans leurs \u00e9difices religieux des corniches ou des plinthes, afin de rendre l\u2019acoustique plus claire lors des ex\u00e9cutions chorales. Mais je suis tout de m\u00eame revenue \u00e0 Melville, en raison de cette tol\u00e9rance vis-\u00e0-vis de l\u2019Autre et des autres aires culturelles \u00e0 laquelle il nous invite de mani\u00e8re r\u00e9p\u00e9t\u00e9e.<br \/>\nUn autre aspect central pour <em>Le Encantadas o le avventure nel mare delle meraviglie<\/em>, c\u2019est mon exp\u00e9rience, d\u00e9sormais ancienne, de Venise. J\u2019y ai souvent s\u00e9journ\u00e9, enfant, puis adolescente ; j\u2019ai plusieurs fois fait le voyage pour assister \u00e0 la Festa dell\u2019Unit\u00e0 sur le Campo del Ghetto Nuovo.<br \/>\n\u00c0 cela se sont ajout\u00e9es l\u2019\u00e9tude de la musique de Luigi Nono et les exp\u00e9riences que j\u2019ai rassembl\u00e9es au cours des quatre ann\u00e9es o\u00f9 j\u2019ai v\u00e9cu \u00e0 Venise, dans un appartement juste derri\u00e8re le ghetto. \u00c0 l\u2019\u00e2ge de seize ans, j\u2019ai aussi eu le bonheur d\u2019assister \u00e0 une ex\u00e9cution du <em>Prometeo <\/em>de Nono \u00e0 l\u2019\u00e9glise San Lorenzo (photo ci-dessous).<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-23660\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/san-lorenzo-2-dr-1024x633.jpg\" alt=\"\" width=\"1024\" height=\"633\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/san-lorenzo-2-dr-1024x633.jpg 1024w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/san-lorenzo-2-dr-300x185.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/san-lorenzo-2-dr-768x475.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/san-lorenzo-2-dr.jpg 1100w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><span style=\"font-size: 12pt;\">\u00c9glise San Lorenzo, Venise\u00a0<\/span><br \/>\n<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u00c0 ce mat\u00e9riau personnel et diversifi\u00e9 s\u2019ajoute l\u2019id\u00e9e de nomadisme, que je d\u00e9crirais musicalement comme un voyage, une travers\u00e9e de paysages sonores : on d\u00e9file devant des images ou des mondes diff\u00e9rents, aux timbres gorg\u00e9s de significations ou de souvenirs. Les \u00ab \u00eeles solitaires \u00bb repr\u00e9sentent quelque chose qui n\u2019est pas fix\u00e9 g\u00e9ographiquement et rel\u00e8vent d\u2019espaces imaginaires et mythologiques. Ces \u00ab\u00a0essais de dispositifs spatiaux\u00a0\u00bb remontent aux ann\u00e9es 1992-93, au d\u00e9but de mon travail sur <em>B\u00e4hlamms Fest<\/em>, et \u00e0 l\u2019utilisation du son et de la vid\u00e9o en surround dans <em>The Long Rain <\/em>(1999) et imm\u00e9diatement apr\u00e8s dans <em>Lost Highway <\/em>(2002-2003) et <em>&#8230;ce qui arrive&#8230; <\/em>(2004), \u00e0 l\u2019utopos visuel et musical. On pourrait relier cela \u00e0 Melville dans <em>The Encantadas <\/em>:<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">For those same Islands seeming now and than,<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Are not firme land, nor any certein wonne,<\/span><br \/>\n<span style=\"font-size: 14pt;\">But stragling plots, which to and fro do ronne<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">In the wide waters; therefore are they hight<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">The Wandering Islands<\/span><br \/>\n<span style=\"font-size: 14pt;\"><em><br \/>\nCes \u00eeles qui parfois se montrent au regard<br \/>\nNe sont point ferme sol ou substance certaine, <\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><em>Mais terres \u00e9gar\u00e9es parmi les eaux nombreuses <\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><em>Et \u00e7\u00e0 et l\u00e0 courant : les \u00eeles Vagabondes.<\/em><\/span><\/p>\n<p><span style=\"font-size: 12pt;\">(Herman Melville <em>Les Encantadas ou \u00celes enchant\u00e9es, <\/em>traduction Michel Leiris, Coll. Folio, Gallimard)<br \/>\n<\/span><\/p>\n<p><strong>L\u2019id\u00e9e des \u00eeles sonores est au fond d\u00e9j\u00e0 pr\u00e9sente chez Melville : dans <em>The Encantadas<\/em>, il cerne l\u2019archipel au moyen de dix esquisses litt\u00e9raires dans lesquelles il combine description de la nature, compte-rendu de voyage, r\u00e9flexion philosophique et r\u00e9cit d\u2019\u00e9v\u00e9nements historiques.<br \/>\n<\/strong><span style=\"font-size: 14pt;\">C\u2019est pr\u00e9cis\u00e9ment cette h\u00e9t\u00e9rog\u00e9n\u00e9it\u00e9 qui est fascinante chez Melville, et c\u2019est elle qui lui a valu tant d\u2019hostilit\u00e9 de son vivant. Il s\u2019est soustrait, dans son \u00e9criture, \u00e0 l\u2019obligation d\u2019illustrer un genre unique. On ne pouvait plus l\u2019enfermer dans une cat\u00e9gorie, et cela a irrit\u00e9 au point que certains coll\u00e8gues et critiques lui ont d\u00e9ni\u00e9 tout talent. Cela vaut aussi pour le livre<br \/>\n<\/span><span style=\"font-size: 14pt;\"><em>The Encantadas\u00a0:<\/em> outre certains r\u00e9cits d\u2019\u00e9v\u00e9nements historiques, o\u00f9 l\u2019on peut reconna\u00eetre les \u00e9l\u00e9ments d\u2019un manifeste de politique sociale, on trouve des d\u00e9veloppements sur la configuration de ces \u00ab \u00eeles enchant\u00e9es \u00bb, mais qui traitent simultan\u00e9ment de leur hostilit\u00e9 envers les hommes et de leur beaut\u00e9. Melville en d\u00e9crit ainsi la nature prolif\u00e9rante, ce vert insaisissable de la jungle, tout en insistant sur son monde volcanique, impossible \u00e0 habiter, un monde sec et hostile.<br \/>\nLa texture de ce livre correspond \u00e0 l\u2019id\u00e9e que je me fais depuis toujours de la composition : travailler avec un<img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-23662\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/herman-melville-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/herman-melville-300x300.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/herman-melville-150x150.jpg 150w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/herman-melville.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> mat\u00e9riau h\u00e9t\u00e9rog\u00e8ne et choisir des dur\u00e9es diff\u00e9rentes pour chacun des processus sonores, de sorte que ma r\u00e9flexion a concentr\u00e9 tous ses efforts sur des formes \u00e0 chaque fois nouvelles. Il y a dans mes <em>Encantadas <\/em>cinq \u00eeles, avec deux interludes, ainsi qu\u2019un prologue et un \u00e9pilogue. Mais pour ce qui est de la forme que rev\u00eat ma musique, c\u2019est surtout l\u2019id\u00e9e de la travers\u00e9e incertaine d\u2019un archipel qui est importante : vivre la perception de quelque chose qui pourrait faire partie d\u2019un ensemble, mais qui appara\u00eet dans le m\u00eame temps comme autonome.<br \/>\nLe regard \u2013 ici, l\u2019oreille \u2013 glisse vers un lointain ind\u00e9termin\u00e9, sur la mer. Les \u00eeles qui constituent l\u2019archipel se dessinent, dont les contours sont tout juste affirm\u00e9s, presque \u00e0 port\u00e9e de main. Peu apr\u00e8s, elles ne sont d\u00e9j\u00e0 plus que des silhouettes n\u00e9buleuses qui, d\u00e8s que le bateau avance et laisse derri\u00e8re lui un sillage d\u2019\u00e9cume blanche, deviennent de plus en plus diffuses. Au del\u00e0 de cela, la formule \u00ab traverser la mer \u00bb est, bien s\u00fbr, devenue en Europe une m\u00e9taphore terrible pour les migrants&#8230;<br \/>\n<\/span><\/p>\n<p><strong>Jusqu\u2019\u00e0 quel point le <em>Prometeo<\/em> de Nono est-il un point de rep\u00e8re dans cette structure en archipel ?<\/strong><em><br \/>\n<\/em><span style=\"font-size: 14pt;\">En tant que compositrice, je ne peux que passer \u00e0 travers l\u2019histoire, pour m\u2019en d\u00e9tacher ensuite et me rejoindre moi-m\u00eame. Il s\u2019agit donc de se laisser inspirer, puis de d\u00e9velopper ses propres inspirations. Le <em>Prometeo\u00a0 <\/em>de Nono (photo ci-dessous) fait partie de ce type de stimulations que j\u2019ai tent\u00e9 de reprendre et de d\u00e9velopper. J\u2019accomplis un pas distinct de celui de Nono, d\u00e8s lors que je n\u2019implante pas l\u2019\u0153uvre \u00e0 l\u2019int\u00e9rieur d\u2019une \u00e9glise <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-23664\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/prometeo-300x235.jpg\" alt=\"\" width=\"300\" height=\"235\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/prometeo-300x235.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/prometeo-768x601.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/prometeo.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>r\u00e9ellement existante, mais que je recours \u00e0 une \u00e9glise San Lorenzo reproduite, simul\u00e9e, \u00ab fausse \u00bb.<br \/>\nIl est d\u2019ailleurs \u00e9tonnant que personne n\u2019ait song\u00e9 \u00e0 r\u00e9aliser cela avant moi ! Quand j\u2019ai d\u00e9velopp\u00e9 ce projet il y a des ann\u00e9es, et apr\u00e8s mon projet inabouti de 2007 avec l\u2019architecte Gregg Lynn \u2013 bas\u00e9 sur les potentialit\u00e9s de sa conception de <em>time-based animation techniques <\/em>\u2013, le point de d\u00e9part pour <em>Le Encantadas <\/em>a encore \u00e9t\u00e9 l\u2019espace et l\u2019acoustique, car j\u2019ai toujours eu \u00e0 lutter contre des probl\u00e8mes d\u2019acoustique dans les lieux de concert. Comment peut-on rendre audible l\u2019espace ? Pourquoi est-ce que je ne capture pas l\u2019acoustique d\u2019une \u00e9glise pour l\u2019implanter ensuite dans un autre espace et l\u2019y transformer ? Je veux donc \u00ab construire \u00bb ma propre acoustique en vue des processus musicaux qui s\u2019y d\u00e9ploient \u00e0 chaque fois. Une \u00ab architecture liquide \u00bb, en fonction des mani\u00e8res d\u2019utiliser l\u2019architecture et l\u2019acoustique. Un jour, en 2009, pendant une de mes nombreuses promenades apr\u00e8s avoir compos\u00e9, j\u2019ai vu l\u2019\u00e9glise ouverte et j\u2019ai pu entrer. \u00c7a a \u00e9t\u00e9 comme le d\u00e9clencheur du projet. Cette \u00e9glise singuli\u00e8re, tr\u00e8s haute, dont l\u2019autel est situ\u00e9 au centre de l\u2019espace, est malheureusement \u00e0 l\u2019abandon et ferm\u00e9e ; mais sa beaut\u00e9 (acoustique) m\u2019a presque lanc\u00e9 un d\u00e9fi. En somme, une sorte de conservation du patrimoine acoustique..<\/span>.<\/p>\n<p><strong>Comment avez-vous proc\u00e9d\u00e9 alors ?<br \/>\n<\/strong><span style=\"font-size: 14pt;\">J\u2019ai d\u2019abord d\u00fb convaincre. Cela a pris des ann\u00e9es. Quand j\u2019ai finalement r\u00e9ussi \u00e0 convaincre Armin K\u00f6hler, dans une zone de transit de l\u2019a\u00e9roport de Berlin \u2013 sans lui, le projet n\u2019existerait pas \u2013, je me suis rapproch\u00e9e de Markus Noisternig, avec qui je travaille depuis <em>B\u00e4hlamms Fest <\/em>sur la diffusion en surround et qui fait des recherches \u00e0 l\u2019Ircam. Je lui ai demand\u00e9 s\u2019il pouvait imaginer entreprendre avec moi un voyage exploratoire pour \u00ab capturer \u00bb l\u2019acoustique de San Lorenzo et pour la reconstruire apr\u00e8s dans n\u2019importe quelle autre salle de concert. Nous avons utilis\u00e9 pour ce faire un syst\u00e8me <em>impulse-response<\/em>. Pour le d\u00e9crire simplement : on envoie un signal dans l\u2019espace (\u00e0 partir de points), on mesure pendant un certain laps de temps, simultan\u00e9ment, la r\u00e9ponse du syst\u00e8me et on l\u2019enregistre.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-23666\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4738-max10mb-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4738-max10mb-1024x683.jpg 1024w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4738-max10mb-300x200.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4738-max10mb-768x512.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4738-max10mb-1536x1025.jpg 1536w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4738-max10mb.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><strong>Comment travaillez-vous avec ces \u00e9l\u00e9ments ?<br \/>\n<\/strong><span style=\"font-size: 14pt;\">Je voulais avant tout faire appara\u00eetre l\u2019espace et la forme de mani\u00e8re plastique et flexible, et au moyen d\u2019unit\u00e9s ou d\u2019\u00e9l\u00e9ments variables. Il convient d\u2019abord de neutraliser autant que possible l\u2019acoustique propre de la salle de concert pour y ins\u00e9rer ensuite celle de l\u2019\u00e9glise simul\u00e9e. J\u2019essaie ensuite d\u2019utiliser musicalement cette \u00ab acoustique captur\u00e9e \u00bb comme un moyen formel. Ainsi, quand la musique l\u2019exige, je fais raccourcir l\u2019\u00e9cho de San Lorenzo, ce qui donne l\u2019impression d\u2019un espace r\u00e9tr\u00e9ci \u2013 un <em>decay time\u00a0 <\/em>de moins de deux secondes, par exemple, produit un space acoustique clair, adapt\u00e9 aux passages rapides. J\u2019ai donc la possibilit\u00e9 de supprimer presque enti\u00e8rement cette acoustique dans certains passages d\u00e9termin\u00e9s, de rendre l\u2019espace petit et \u00e9troit, et de le gonfler ensuite \u00e0 nouveau. On peut cependant isoler certains \u00e9l\u00e9ments de l\u2019acoustique de l\u2019\u00e9glise : certains \u00e9v\u00e9nements musicaux de la zone situ\u00e9e \u00e0 l\u2019avant dans le lieu d\u2019ex\u00e9cution peuvent \u00eatre d\u00e9plac\u00e9s dans la \u00ab zone arri\u00e8re \u00bb de l\u2019espace de San Lorenzo \u2013 puisque l\u2019\u00e9glise est divis\u00e9e en deux parties qui sonnent diff\u00e9remment \u2013, pendant qu\u2019un autre \u00e9v\u00e9nement r\u00e9sonne au m\u00eame moment dans la \u00ab premi\u00e8re zone \u00bb, celle pr\u00e8s de l\u2019entr\u00e9e, plus vaste.<br \/>\n<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-23668\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/san-lorenzo-3-dr-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/san-lorenzo-3-dr-1024x768.jpg 1024w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/san-lorenzo-3-dr-300x225.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/san-lorenzo-3-dr-768x576.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/san-lorenzo-3-dr.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\">\u00c9glise San Lorenzo, Venise\u00a0 <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u00c0 certains endroits, on entend seulement l\u2019espace acoustique de l\u2019\u00e9glise. Et parfois, je r\u00e9duis l\u2019effectif \u00e0 quelques instruments, pour rendre perceptibles des points pr\u00e9cis de l\u2019\u00e9glise ou pour diriger l\u2019attention sur la r\u00e9sonance artificielle, autrement dit pas celle de San Lorenzo.<\/span><br \/>\n<span style=\"font-size: 14pt;\">J\u2019ai toujours compos\u00e9 des acoustiques simultan\u00e9es, cr\u00e9ant de la sorte un jeu entre spatialit\u00e9 r\u00e9elle et spatialit\u00e9 fictive. Pour la diffusion, nous utilisons un environnement surround en 3D (Ambisonics), comme dans les cin\u00e9mas et les plan\u00e9tariums, o\u00f9 on les appelle <em>Dome Projections<\/em>. Il est d\u2019ailleurs curieux que j\u2019ai appel\u00e9 mes grands espaces en 3D dans <em>The Long Rain <\/em>presque de la m\u00eame mani\u00e8re : des <em>Sun-domes<\/em>.<br \/>\nLe syst\u00e8me Ambisonics est dispos\u00e9 autour de six groupes instrumentaux dont l\u2019effectif et l\u2019accord se distinguent toujours ; ils forment deux triangles imbriqu\u00e9s et sont donc plac\u00e9s aux pointes extr\u00eames d\u2019une \u00e9toile de David.<br \/>\n<\/span><\/p>\n<p><span style=\"font-size: 12pt;\"><strong>Il est int\u00e9ressant que vous ayez utilis\u00e9 des enregistrements effectu\u00e9s sur le terrain et que vous ayez ainsi renou\u00e9 avec ce que vous avez d\u00e9j\u00e0 fait dans vos toutes premi\u00e8res \u0153uvres des ann\u00e9es 1990.<br \/>\n<\/strong><\/span><span style=\"font-size: 14pt;\">C\u2019est exactement \u00e7a, mais le d\u00e9fi est ici de voir comment une telle utilisation de sons change. Par exemple, j\u2019ai pu faire en 2002 des enregistrements au Mus\u00e9e juif de Berlin pour mon \u0153uvre <em>torsion\u00a0<\/em>:<em> transparent variation<\/em>, avant l\u2019installation des collections, dans les <em>Voids <\/em>con\u00e7us par Daniel Libeskind, et o\u00f9 l\u2019on entend, distordue, la circulation des voitures au dehors.<\/span><br \/>\n<span style=\"font-size: 14pt;\">Ces enregistrements \u00e9taient ins\u00e9r\u00e9s sans aucune transformation dans la texture musicale, ils la d\u00e9chiraient en quelque sorte. Cette fois, il \u00e9tait important pour moi d\u2019utiliser les <em>field recordings <\/em>r\u00e9alis\u00e9s dans la lagune de Venise et dans la ville elle-m\u00eame, et j\u2019en ai fait d\u2019innombrables depuis 1997, comme des parties d\u2019une pi\u00e8ce radiophonique, car dans <em>Le Encantadas, <\/em>espace int\u00e9rieur et espace ext\u00e9rieur s\u2019interp\u00e9n\u00e8trent.<\/span><br \/>\n<span style=\"font-size: 14pt;\">L\u2019\u00e9glise San Lorenzo est certes un espace int\u00e9rieur, mais perm\u00e9able aux sons qui proviennent de l\u2019ext\u00e9rieur. Comme les murs sont poreux et que certaines parties des fen\u00eatres sont cass\u00e9es, on per\u00e7oit toujours de quelque mani\u00e8re le dehors. J\u2019utilise par cons\u00e9quent certains \u00e9v\u00e9nements acoustiques qui captent l\u2019environnement, l\u2019espace de la ville : des sons de bateaux \u00e0 moteur, des voix, diff\u00e9rentes cloches&#8230;, et tout cela se transforme en fonction de la position de l\u2019auditeur. Pour les enregistrements dans la lagune, nous avons utilis\u00e9 un microphone <em>soundfield all around<\/em>, si bien que l\u2019on peut entendre comment, par exemple, les sons de cloche proviennent de diff\u00e9rents points, comment l\u2019environnement sonore se modifie dans une image en 3D quand on s\u2019\u00e9loigne de la source, et comment les sons se perdent progressivement, tandis que d\u2019autres signatures sonores se retrouvent au premier plan.<br \/>\nCe type de ph\u00e9nom\u00e8nes perceptifs m\u2019a \u00e9galement pr\u00e9occup\u00e9e en composant : non seulement les enregistrements sur le terrain apparaissent isol\u00e9ment \u00e0 certains endroits, mais il y a aussi des passages o\u00f9 j\u2019ai analys\u00e9 et transcrit pour ensemble les cloches enregistr\u00e9es. Coordonn\u00e9s par <em>click track <\/em>\u2013 ce timbre particulier n\u00e9cessitat d\u2019\u00eatre exactement ensemble \u2013, les musiciens doivent alors produire \u00e0 l\u2019unisson des spectres d\u2019harmoniques sur les sons de cloche. \u00c0 ce moment-l\u00e0, le grand espace de San Lorenzo dispara\u00eet. Une forme urbaine, ou architecturale, qui d\u00e9pend \u00e9troitement du mat\u00e9riau musical.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-23670\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/olga-neuwirth-encantadas-cite-de-la-musique-2015c-eic-dscf4007-1024x577.jpg\" alt=\"\" width=\"1024\" height=\"577\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/olga-neuwirth-encantadas-cite-de-la-musique-2015c-eic-dscf4007-1024x577.jpg 1024w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/olga-neuwirth-encantadas-cite-de-la-musique-2015c-eic-dscf4007-300x169.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/olga-neuwirth-encantadas-cite-de-la-musique-2015c-eic-dscf4007-768x433.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/olga-neuwirth-encantadas-cite-de-la-musique-2015c-eic-dscf4007-1536x866.jpg 1536w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/olga-neuwirth-encantadas-cite-de-la-musique-2015c-eic-dscf4007.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p><span style=\"font-size: 12pt;\"><em>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Le Encantadas o le avventure nel mare delle meraviglie<\/em>, Cit\u00e9 de la musique, Paris, 2015<\/span><\/p>\n<p><strong>Comment aborde-t-on une dur\u00e9e de soixante-dix minutes ? C\u2019est vraiment&#8230;<\/strong><em><br \/>\n<\/em><span style=\"font-size: 14pt;\">&#8230; terriblement long. J\u2019ai planifi\u00e9 un \u00ab sillage \u00bb temporel sous une forme qui me paraissait intuitivement juste. C\u2019est pour cela aussi qu\u2019il y a plusieurs \u00eeles, pr\u00e9c\u00e9d\u00e9es d\u2019un <em>Prologo <\/em>; on commence sur un des enregistrements de la lagune, avant la musique pour ensemble, et alors les \u00eeles oc\u00e9aniques s\u2019\u00e9l\u00e8vent des profondeurs avec des \u00e9ruptions et des mouvements subaquatiques. Certains \u00e9v\u00e9nements surgissent lentement, avec des temporalit\u00e9s distinctes, disparaissent et reviennent, et l\u2019oreille n\u2019a m\u00eame pas le temps d\u2019annexer ces \u00eeles sonores. En outre, il faut bien s\u00fbr prendre en compte ce qui vous int\u00e9resse le plus. C\u2019est donc un itin\u00e9raire personnel que j\u2019ai choisi dans cet archipel. Je plonge ainsi le public dans un voyage fictif \u00e0 travers l\u2019espace et le temps : en tant qu\u2019auditeur, on est embarqu\u00e9 pendant soixante-dix minutes dans un labyrinthe d\u2019espaces int\u00e9rieurs ou ext\u00e9rieurs, d\u2019archipels (sonores), de ph\u00e9nom\u00e8nes acoustiques donn\u00e9s tels quels ou retravaill\u00e9s.<br \/>\n<\/span><\/p>\n<p><strong>Nous voici revenus \u00e0 l\u2019id\u00e9e du voyage qui a \u00e9t\u00e9 si importante chez vous depuis <em>B\u00e4hlamms Fest<\/em>&#8230;<\/strong><br \/>\n<span style=\"font-size: 14pt;\">Cette pens\u00e9e demeure, elle est importante pour moi depuis toujours. L\u2019exp\u00e9rience du <em>Prometeo <\/em>de 1984 a \u00e9galement jou\u00e9 un certain r\u00f4le. Comme l\u2019\u00e9crivait Herder : \u00ab Un navire suspendu entre ciel et mer, combien ne donne-t-il \u00e0 penser au sujet de la sph\u00e8re immense ! \u00bb Dans plusieurs de mes \u0153uvres, il \u00e9tait d\u00e9j\u00e0 question d\u2019espace, si bien que <em>Le Encantadas <\/em>en est au fond la continuation logique.<\/span><\/p>\n<p><strong>L\u2019utilisation de voix ins\u00e9r\u00e9es reprend aussi des exp\u00e9riences ant\u00e9rieures.<br \/>\n<\/strong><span style=\"font-size: 14pt;\">Exactement. Toutes les voix sont soit pr\u00e9enregistr\u00e9es, soit g\u00e9n\u00e9r\u00e9es artificiellement. Cette derni\u00e8re technique joue un r\u00f4le vers la fin de l\u2019\u0153uvre : l\u2019\u00eele en tant que monde imaginaire, comme dans la litt\u00e9ratures fantastique. Il y a l\u00e0 un moment \u00ab surr\u00e9aliste \u00bb o\u00f9 tout devient plus artificiel. \u00ab L\u2019\u00eele solitaire \u00bb fournit le double des instruments et des voix. Un double instable, d\u00e9tach\u00e9 du r\u00e9el, dont il n\u2019a pas la consistance. J\u2019utilise par exemple \u00e0 cet endroit des remarques d\u2019adolescents, que j\u2019ai collect\u00e9es \u00e0 New York, sur ce qui est important pour eux, sur ce qui les pr\u00e9occupe ; elles sont ensuite ins\u00e9r\u00e9es \u00e0 partir de la voix artificielle de mon ordinateur Apple, comme un souvenir personnel du processeur de signaux <em>Speak &amp; Spell <\/em>mis sur le march\u00e9 en 1978, et qu\u2019on m\u2019avait offert \u00e0 l\u2019\u00e9poque.<\/span><br \/>\n<span style=\"font-size: 14pt;\">Pour aller encore plus loin, une chanteuse devient une \u00ab projection en 3D \u00bb, comme dans le roman <em>L\u2019Invention de Morel <\/em>d\u2019Adolfo Bioy Casares, qui a trait au virtuel ; c\u2019est ici l\u2019image d\u2019une menace qui surgit de l\u2019ext\u00e9rieur, mais aussi un espace r\u00e9serv\u00e9 \u00e0 l\u2019\u00e9nigme. J\u2019ai \u00e9crit \u00e0 cet effet \u00ab a Song \u00bb pour la voix num\u00e9rique de Hatsune Miku \u2013 le producteur japonais l\u2019appelle <em>an android diva in the near-future world where songs are lost <\/em>\u2013, que je vais r\u00e9utiliser dans d\u2019autres \u0153uvres. Ces programmes de synth\u00e8se vocale g\u00e9n\u00e9rant des voix num\u00e9riques m\u2019int\u00e9ressaient d\u00e9j\u00e0 en 1992, quand j\u2019ai commenc\u00e9 \u00e0 travailler sur <em>B\u00e4hlamms Fest<\/em>. Aujourd\u2019hui, vingt ans plus tard, le travail de programmation a beaucoup progress\u00e9 et les r\u00e9sultats sont bien meilleurs. J\u2019exploite tout le spectre, depuis des voix humaines non transform\u00e9es jusqu\u2019\u00e0 ce type de voix artificielle, dont j\u2019ai souvent qualifi\u00e9 nagu\u00e8re le son d\u2019\u00ab androgyne \u00bb, en passant par toutes sortes de degr\u00e9s de transformation. En raison de cette multiplicit\u00e9 de voix, <em>Le Encantadas <\/em>est aussi pour moi une sorte de th\u00e9\u00e2tre musical.<\/span><\/p>\n<p><strong>Un th\u00e9\u00e2tre imaginaire pour l\u2019oreille, peut-\u00eatre ?<\/strong><em><br \/>\n<\/em><span style=\"font-size: 14pt;\">Oui. Au sens figur\u00e9, c\u2019est un roman d\u2019aventures, qui traverse de multiples espaces sonores.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #003366;\"><strong><span style=\"font-size: 12pt;\">Et aussi : un reportage vid\u00e9o sur la cr\u00e9ation de <em>Le Encantadas o le avventure nel mare delle meraviglie<\/em><\/span><\/strong><\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/yGCYC9SHc3Y\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Photos : Olga Neuwirth \u00a9 Rui Camillo \/<span style=\"font-size: 12pt;\"><em>\u00a0Le Encantadas o le avventure nel mare delle meraviglie<\/em>, Cit\u00e9 de la musique, Paris, 2015 \u00a9 EIC \/ autres photos : DR\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9\u00e9 il y a d\u00e9j\u00e0 sept ans, en 2015, \u00ab\u00a0Le Encantadas o le avventure nel\u00a0mare delle meraviglie\u00a0\u00bb (Le Encantadas\u00a0ou les aventures en mer des merveilles) d\u2019Olga\u00a0Neuwirth est l\u2019unique \u0153uvre, mais quelle \u0153uvre, au programme du concert du 13 d\u00e9cembre \u00e0 la Cit\u00e9 de la musique. La compositrice autrichienne nous embarque pour une grande odyss\u00e9e\u00a0imaginaire de Venise aux Encantadas, \u00eeles\u00a0enchant\u00e9es des Gal\u00e1pagos. R\u00e9alis\u00e9 peu avant la cr\u00e9ation de l\u2019\u0153uvre cet entretien en retrace la gen\u00e8se et en expose les multiples ramifications litt\u00e9raires et musicales. \u00a0\u00a0<\/p>\n","protected":false},"author":114,"featured_media":23657,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[55,488],"class_list":["post-23656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-cite-de-la-musique","tag-olga-neuwirth"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les \u00eeles vagabondes d&#039;Olga Neuwirth. - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les \u00eeles vagabondes d&#039;Olga Neuwirth. - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"Cr\u00e9\u00e9 il y a d\u00e9j\u00e0 sept ans, en 2015, &quot;Le Encantadas o le avventure nel\u00a0mare delle meraviglie&quot; (Le Encantadas\u00a0ou les aventures en mer des merveilles) d\u2019Olga\u00a0Neuwirth est l\u2019unique \u0153uvre, mais quelle \u0153uvre, au programme du concert du 13 d\u00e9cembre \u00e0 la Cit\u00e9 de la musique. La compositrice autrichienne nous embarque pour une grande odyss\u00e9e\u00a0imaginaire de Venise aux Encantadas, \u00eeles\u00a0enchant\u00e9es des Gal\u00e1pagos. R\u00e9alis\u00e9 peu avant la cr\u00e9ation de l\u2019\u0153uvre cet entretien en retrace la gen\u00e8se et en expose les multiples ramifications litt\u00e9raires et musicales. \u00a0\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-10T18:48:21+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4914-max10mb-nb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1862\" \/>\n\t<meta property=\"og:image:height\" content=\"1242\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Stefan Drees\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stefan Drees\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2022\\\/12\\\/les-iles-vagabondes-dolga-neuwirth\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2022\\\/12\\\/les-iles-vagabondes-dolga-neuwirth\\\/\"},\"author\":{\"name\":\"Stefan Drees\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/af7e99c4f2fe4e4b56cd22a86b0db005\"},\"headline\":\"Les \u00eeles vagabondes d&rsquo;Olga Neuwirth.\",\"datePublished\":\"2022-12-10T18:48:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2022\\\/12\\\/les-iles-vagabondes-dolga-neuwirth\\\/\"},\"wordCount\":3396,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2022\\\/12\\\/les-iles-vagabondes-dolga-neuwirth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2022\\\/12\\\/b-i0a4914-max10mb-nb.jpg\",\"keywords\":[\"Cit\u00e9 de la musique\",\"Olga Neuwirth\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2022\\\/12\\\/les-iles-vagabondes-dolga-neuwirth\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2022\\\/12\\\/les-iles-vagabondes-dolga-neuwirth\\\/\",\"name\":\"Les \u00eeles vagabondes d'Olga Neuwirth. - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2022\\\/12\\\/les-iles-vagabondes-dolga-neuwirth\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2022\\\/12\\\/les-iles-vagabondes-dolga-neuwirth\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2022\\\/12\\\/b-i0a4914-max10mb-nb.jpg\",\"datePublished\":\"2022-12-10T18:48:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/af7e99c4f2fe4e4b56cd22a86b0db005\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2022\\\/12\\\/les-iles-vagabondes-dolga-neuwirth\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2022\\\/12\\\/les-iles-vagabondes-dolga-neuwirth\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2022\\\/12\\\/les-iles-vagabondes-dolga-neuwirth\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2022\\\/12\\\/b-i0a4914-max10mb-nb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2022\\\/12\\\/b-i0a4914-max10mb-nb.jpg\",\"width\":1862,\"height\":1242},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2022\\\/12\\\/les-iles-vagabondes-dolga-neuwirth\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les \u00eeles vagabondes d&rsquo;Olga Neuwirth.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/af7e99c4f2fe4e4b56cd22a86b0db005\",\"name\":\"Stefan Drees\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66d7ea293eece6373f8a2ade51e5cb09fe63f44a216ecab4aab9b45607986261?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66d7ea293eece6373f8a2ade51e5cb09fe63f44a216ecab4aab9b45607986261?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/66d7ea293eece6373f8a2ade51e5cb09fe63f44a216ecab4aab9b45607986261?s=96&d=mm&r=g\",\"caption\":\"Stefan Drees\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/author\\\/stefan-drees\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les \u00eeles vagabondes d'Olga Neuwirth. - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/","og_locale":"fr_FR","og_type":"article","og_title":"Les \u00eeles vagabondes d'Olga Neuwirth. - Ensemble intercontemporain","og_description":"Cr\u00e9\u00e9 il y a d\u00e9j\u00e0 sept ans, en 2015, \"Le Encantadas o le avventure nel\u00a0mare delle meraviglie\" (Le Encantadas\u00a0ou les aventures en mer des merveilles) d\u2019Olga\u00a0Neuwirth est l\u2019unique \u0153uvre, mais quelle \u0153uvre, au programme du concert du 13 d\u00e9cembre \u00e0 la Cit\u00e9 de la musique. La compositrice autrichienne nous embarque pour une grande odyss\u00e9e\u00a0imaginaire de Venise aux Encantadas, \u00eeles\u00a0enchant\u00e9es des Gal\u00e1pagos. R\u00e9alis\u00e9 peu avant la cr\u00e9ation de l\u2019\u0153uvre cet entretien en retrace la gen\u00e8se et en expose les multiples ramifications litt\u00e9raires et musicales. \u00a0\u00a0","og_url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2022-12-10T18:48:21+00:00","og_image":[{"width":1862,"height":1242,"url":"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4914-max10mb-nb.jpg","type":"image\/jpeg"}],"author":"Stefan Drees","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Stefan Drees","Dur\u00e9e de lecture estim\u00e9e":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/"},"author":{"name":"Stefan Drees","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/af7e99c4f2fe4e4b56cd22a86b0db005"},"headline":"Les \u00eeles vagabondes d&rsquo;Olga Neuwirth.","datePublished":"2022-12-10T18:48:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/"},"wordCount":3396,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4914-max10mb-nb.jpg","keywords":["Cit\u00e9 de la musique","Olga Neuwirth"],"articleSection":["Entretien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/","url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/","name":"Les \u00eeles vagabondes d'Olga Neuwirth. - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4914-max10mb-nb.jpg","datePublished":"2022-12-10T18:48:21+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/af7e99c4f2fe4e4b56cd22a86b0db005"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4914-max10mb-nb.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2022\/12\/b-i0a4914-max10mb-nb.jpg","width":1862,"height":1242},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2022\/12\/les-iles-vagabondes-dolga-neuwirth\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les \u00eeles vagabondes d&rsquo;Olga Neuwirth."}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/af7e99c4f2fe4e4b56cd22a86b0db005","name":"Stefan Drees","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/66d7ea293eece6373f8a2ade51e5cb09fe63f44a216ecab4aab9b45607986261?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/66d7ea293eece6373f8a2ade51e5cb09fe63f44a216ecab4aab9b45607986261?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/66d7ea293eece6373f8a2ade51e5cb09fe63f44a216ecab4aab9b45607986261?s=96&d=mm&r=g","caption":"Stefan Drees"},"url":"https:\/\/www.ensembleintercontemporain.com\/fr\/author\/stefan-drees\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/23656\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/users\/114\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/comments\/?post=23656"}],"version-history":[{"count":11,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/23656\/revisions\/"}],"predecessor-version":[{"id":23693,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/23656\/revisions\/23693\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/media\/23657\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/media\/?parent=23656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/categories\/?post=23656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/tags\/?post=23656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}