{"id":17952,"date":"2019-11-15T11:51:53","date_gmt":"2019-11-15T10:51:53","guid":{"rendered":"https:\/\/www.ensembleintercontemporain.com\/?p=17952"},"modified":"2019-12-09T17:53:37","modified_gmt":"2019-12-09T16:53:37","slug":"aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/","title":{"rendered":"\u00ab Aller plus loin \u00bb. Entretien avec Lucie Leguay, cheffe d\u2019orchestre."},"content":{"rendered":"<p><strong><span style=\"color: #003366;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17954\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/img9206_def-article-2.jpg\" alt=\"\" width=\"1920\" height=\"2160\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/img9206_def-article-2.jpg 1920w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/img9206_def-article-2-267x300.jpg 267w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/img9206_def-article-2-768x864.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/img9206_def-article-2-910x1024.jpg 910w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\"><strong><span style=\"color: #003366;\">Elle est la laur\u00e9ate du r\u00e9cent Tremplin international pour jeunes cheffes d&rsquo;orchestre organis\u00e9 par la Philharmonie de Paris et, depuis la rentr\u00e9e, la nouvelle cheffe assistante de l\u2019EIC. Entretien avec Lucie Leguay sur son parcours et ses perspectives au sein de l\u2019Ensemble.<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Lucie, d\u2019o\u00f9 vous vient votre int\u00e9r\u00eat pour la musique contemporaine ?<\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">De loin ! D\u00e9j\u00e0, au cours de mes \u00e9tudes, je dirigeais les cr\u00e9ations de mes amis compositeurs, qui \u00e9taient aussi mes condisciples en classe d\u2019\u00e9criture et d\u2019orchestration \u00e0 Lille. Cette proximit\u00e9 est \u00e9videmment tr\u00e8s enrichissante : elle permet de d\u00e9couvrir l\u2019univers du compositeur en m\u00eame temps que d\u2019aller au plus pr\u00e8s de son \u0153uvre. <\/span><span style=\"font-size: 14pt;\">Une exp\u00e9rience m\u2019a donn\u00e9 l\u2019envie d\u2019aller plus loin\u00a0: ma rencontre avec Peter E\u00f6tv\u00f6s \u00e0 Budapest. Au cours de ses masterclasses, les jeunes chefs ont la chance de travailler avec des jeunes compositeurs et de fr\u00e9quenter des personnalit\u00e9s aussi \u00e9minentes que Heinz Holliger ou Kaija Saariaho.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Pourquoi ce poste de chef assistant \u00e0 l\u2019EIC vous attirait-il ?<\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Cela repr\u00e9sentait pour moi une chance d\u2019approfondir plus encore ce r\u00e9pertoire que j\u2019affectionne chaque jour un peu plus et de d\u00e9couvrir de nouvelles \u0153uvres et ce dans un contexte id\u00e9al, avec un ensemble et en compagnie d\u2019un chef d\u2019une qualit\u00e9 et d\u2019une exigence rares. J\u2019avoue que la perspective d\u2019\u00e9changer avec ces solistes qui, pour beaucoup, ont travaill\u00e9 avec Pierre Boulez, \u00e9tait aussi tr\u00e8s \u00e9mouvante\u00a0: je d\u00e9couvre \u00e0 leur contact l\u2019histoire et l\u2019ADN de cet ensemble absolument unique dans le monde musical.<\/span><\/p>\n<p><strong> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17958\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/dscf6865-article.jpg\" alt=\"\" width=\"1920\" height=\"1331\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/dscf6865-article.jpg 1920w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/dscf6865-article-300x208.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/dscf6865-article-768x532.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/dscf6865-article-1024x710.jpg 1024w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Qu\u2019attendez-vous de cette exp\u00e9rience avec l\u2019Ensemble ?<\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">J\u2019esp\u00e8re avant tout apprendre. D\u2019abord en observant Matthias Pintscher, sa mani\u00e8re d\u2019aborder ce r\u00e9pertoire et de travailler, mais aussi les autres chefs invit\u00e9s. C\u2019est \u00e9galement l\u2019opportunit\u00e9 pour moi\u00a0d\u2019\u00e9changer avec les musiciens sur leur grande exp\u00e9rience de ce r\u00e9pertoire. De plus, chaque concert est l\u2019occasion de d\u00e9couvrir de nouveaux artistes (compositeurs ou solistes). Je me r\u00e9jouis de cette collaboration pour les deux prochaines ann\u00e9es, c\u2019est une vraie chance et je souhaite en profiter au maximum !<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Comment s&rsquo;est d\u00e9roul\u00e9 votre prise de fonctions? <\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Le jour du concours, j\u2019\u00e9tais vraiment impressionn\u00e9e de diriger ces musiciens, que je connaissais de loin gr\u00e2ce aux nombreux concerts auxquels j\u2019ai assist\u00e9s. Ensuite, j\u2019ai d\u2019embl\u00e9e \u00e9t\u00e9 prise par les activit\u00e9s de l\u2019Ensemble. Je me suis m\u00eame trouv\u00e9e \u00ab\u00a0en situation\u00a0\u00bb d\u00e8s mes premiers jours, puisque j\u2019ai d\u00fb remplacer Matthias au pied lev\u00e9 pour une r\u00e9p\u00e9tition, et ce, sans conna\u00eetre la pi\u00e8ce\u00a0! C\u2019est ainsi que je suis vraiment entr\u00e9e dans cette famille de musiciens exigeante et de tr\u00e8s haut niveau \u2014 et qui, au surplus, s\u2019est aussi r\u00e9v\u00e9l\u00e9e bienveillante et compr\u00e9hensive dans cette situation exceptionnelle.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Vous avez \u00e9t\u00e9, l\u2019an pass\u00e9, laur\u00e9ate du \u00ab Tremplin pour jeunes cheffes d\u2019orchestre \u00bb organis\u00e9 par la Philharmonie de Paris. Qu\u2019est-ce que cela vous inspire et qu\u2019est-ce que cela vous a apport\u00e9 ?<\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Ce Tremplin porte bien son nom puisqu\u2019il m\u2019a apport\u00e9 une vraie visibilit\u00e9, qui s\u2019est traduite par un coup d\u2019acc\u00e9l\u00e9rateur dans ma carri\u00e8re de cheffe d\u2019orchestre, ainsi que par de tr\u00e8s belles rencontres. J\u2019ai \u00e0 pr\u00e9sent un emploi du temps bien charg\u00e9, se partageant entre diff\u00e9rents engagements professionnels et mon poste de chef assistante aupr\u00e8s de quatre orchestres (Orchestre National de Lille, Orchestre National d\u2019Ile-de-France, Orchestre de Picardie et\u2026 l\u2019Ensemble intercontemporain, bien s\u00fbr).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Photos (de haut en bas) :\u00a9 Franck Ferville \/ Lucie Leguay et Matthias Pintscher, Conservatoire de Paris, novembre 2019 \u00a9 EIC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elle est la laur\u00e9ate du r\u00e9cent Tremplin international pour jeunes cheffes d&rsquo;orchestres organis\u00e9 par la Philharmonie de Paris  et, depuis la rentr\u00e9e, la nouvelle cheffe assistante de l\u2019EIC. Entretien avec Lucie Leguay sur son parcours et ses perspectives au sein de l\u2019Ensemble.<\/p>\n","protected":false},"author":106,"featured_media":17971,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[348,600],"class_list":["post-17952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-chef-dorchestre","tag-philharmonie-de-paris"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00ab Aller plus loin \u00bb. Entretien avec Lucie Leguay, cheffe d\u2019orchestre. - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00ab Aller plus loin \u00bb. Entretien avec Lucie Leguay, cheffe d\u2019orchestre. - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"Elle est la laur\u00e9ate du r\u00e9cent Tremplin international pour jeunes cheffes d&#039;orchestres organis\u00e9 par la Philharmonie de Paris et, depuis la rentr\u00e9e, la nouvelle cheffe assistante de l\u2019EIC. Entretien avec Lucie Leguay sur son parcours et ses perspectives au sein de l\u2019Ensemble.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-15T10:51:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-09T16:53:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/img9264_une-def.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1543\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lou Madjar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lou Madjar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/11\\\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/11\\\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\\\/\"},\"author\":{\"name\":\"Lou Madjar\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/f56cef9c7c3dbbaa55b6fb6424402c60\"},\"headline\":\"\u00ab Aller plus loin \u00bb. Entretien avec Lucie Leguay, cheffe d\u2019orchestre.\",\"datePublished\":\"2019-11-15T10:51:53+00:00\",\"dateModified\":\"2019-12-09T16:53:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/11\\\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\\\/\"},\"wordCount\":657,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/11\\\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2019\\\/11\\\/img9264_une-def.jpg\",\"keywords\":[\"chef d'orchestre\",\"Philharmonie de Paris\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/11\\\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/11\\\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\\\/\",\"name\":\"\u00ab Aller plus loin \u00bb. Entretien avec Lucie Leguay, cheffe d\u2019orchestre. - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/11\\\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/11\\\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2019\\\/11\\\/img9264_une-def.jpg\",\"datePublished\":\"2019-11-15T10:51:53+00:00\",\"dateModified\":\"2019-12-09T16:53:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/f56cef9c7c3dbbaa55b6fb6424402c60\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/11\\\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/11\\\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/11\\\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2019\\\/11\\\/img9264_une-def.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2019\\\/11\\\/img9264_une-def.jpg\",\"width\":2400,\"height\":1543},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/11\\\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab Aller plus loin \u00bb. Entretien avec Lucie Leguay, cheffe d\u2019orchestre.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/f56cef9c7c3dbbaa55b6fb6424402c60\",\"name\":\"Lou Madjar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9659f14931b162ccd8972a82e8049b47fcc5c3bd4dddeb071645991624353db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9659f14931b162ccd8972a82e8049b47fcc5c3bd4dddeb071645991624353db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c9659f14931b162ccd8972a82e8049b47fcc5c3bd4dddeb071645991624353db?s=96&d=mm&r=g\",\"caption\":\"Lou Madjar\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/author\\\/lou-madjar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00ab Aller plus loin \u00bb. Entretien avec Lucie Leguay, cheffe d\u2019orchestre. - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00ab Aller plus loin \u00bb. Entretien avec Lucie Leguay, cheffe d\u2019orchestre. - Ensemble intercontemporain","og_description":"Elle est la laur\u00e9ate du r\u00e9cent Tremplin international pour jeunes cheffes d'orchestres organis\u00e9 par la Philharmonie de Paris et, depuis la rentr\u00e9e, la nouvelle cheffe assistante de l\u2019EIC. Entretien avec Lucie Leguay sur son parcours et ses perspectives au sein de l\u2019Ensemble.","og_url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2019-11-15T10:51:53+00:00","article_modified_time":"2019-12-09T16:53:37+00:00","og_image":[{"width":2400,"height":1543,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/img9264_une-def.jpg","type":"image\/jpeg"}],"author":"Lou Madjar","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lou Madjar","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/"},"author":{"name":"Lou Madjar","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/f56cef9c7c3dbbaa55b6fb6424402c60"},"headline":"\u00ab Aller plus loin \u00bb. Entretien avec Lucie Leguay, cheffe d\u2019orchestre.","datePublished":"2019-11-15T10:51:53+00:00","dateModified":"2019-12-09T16:53:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/"},"wordCount":657,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/img9264_une-def.jpg","keywords":["chef d'orchestre","Philharmonie de Paris"],"articleSection":["Entretien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/","url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/","name":"\u00ab Aller plus loin \u00bb. Entretien avec Lucie Leguay, cheffe d\u2019orchestre. - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/img9264_une-def.jpg","datePublished":"2019-11-15T10:51:53+00:00","dateModified":"2019-12-09T16:53:37+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/f56cef9c7c3dbbaa55b6fb6424402c60"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/img9264_une-def.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/11\/img9264_une-def.jpg","width":2400,"height":1543},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/11\/aller-plus-loin-entretien-avec-lucie-leguay-cheffe-dorchestre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00ab Aller plus loin \u00bb. Entretien avec Lucie Leguay, cheffe d\u2019orchestre."}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/f56cef9c7c3dbbaa55b6fb6424402c60","name":"Lou Madjar","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c9659f14931b162ccd8972a82e8049b47fcc5c3bd4dddeb071645991624353db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c9659f14931b162ccd8972a82e8049b47fcc5c3bd4dddeb071645991624353db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c9659f14931b162ccd8972a82e8049b47fcc5c3bd4dddeb071645991624353db?s=96&d=mm&r=g","caption":"Lou Madjar"},"url":"https:\/\/www.ensembleintercontemporain.com\/fr\/author\/lou-madjar\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/17952\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/users\/106\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/comments\/?post=17952"}],"version-history":[{"count":8,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/17952\/revisions\/"}],"predecessor-version":[{"id":18143,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/17952\/revisions\/18143\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/media\/17971\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/media\/?parent=17952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/categories\/?post=17952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/tags\/?post=17952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}