{"id":17457,"date":"2019-10-17T19:04:09","date_gmt":"2019-10-17T17:04:09","guid":{"rendered":"https:\/\/www.ensembleintercontemporain.com\/?p=17457"},"modified":"2019-11-20T15:17:56","modified_gmt":"2019-11-20T14:17:56","slug":"comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/","title":{"rendered":"Comme un tremblement int\u00e9rieur. Entretien avec James Dillon, compositeur."},"content":{"rendered":"<p><span style=\"color: #003366;\"><strong><span style=\"font-size: 14pt;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17855\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/dsc_4083_photo_janet_sinica.jpg\" alt=\"\" width=\"1920\" height=\"1560\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/dsc_4083_photo_janet_sinica.jpg 1920w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/dsc_4083_photo_janet_sinica-300x244.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/dsc_4083_photo_janet_sinica-768x624.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/dsc_4083_photo_janet_sinica-1024x832.jpg 1024w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #003366;\"><strong><span style=\"font-size: 14pt;\">Faisant sienne une conception cosmique de la musique, le compositeur \u00e9cossais James Dillon laisse volontiers planer un certain myst\u00e8re sur ses \u0153uvres. Sophistiqu\u00e9e, complexe et organique, sa musique peut aussi \u00eatre sensuelle et vibrante. Avec <em>Tanz\/haus: triptych 2017 <\/em>qui sera jou\u00e9e pour la premi\u00e8re fois en France le <a href=\"https:\/\/www.ensembleintercontemporain.com\/fr\/concert\/demeure-et-tremblements-2019-11-27-20h30-paris\/\">27 novembre 2019<\/a> \u00e0 la Philharmonie de Paris, il explore le champ \u00e0 la fois infinit\u00e9simal et abyssal du tremblement et du vibrato.<\/span><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"font-size: 14pt;\">James, peut-on d\u00e9duire du titre <em>Tanz\/haus<\/em> et de l\u2019\u00e9tymologie que vous pr\u00e9cisez (l\u2019id\u00e9e de tremblement pour le premier terme, celle de cacher pour le second) que le fondement formel de l\u2019\u0153uvre serait une dualit\u00e9 entre une activit\u00e9 rythmique dense mais de tr\u00e8s faible amplitude et des plages plus mouvantes ?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">Le mat\u00e9riau est organis\u00e9 autour de deux id\u00e9es : la polarit\u00e9 \u2013 j\u2019imagine ici une continuit\u00e9 le long d\u2019un axe entre stase et mouvement \u2013 et la fa\u00e7on dont une qualit\u00e9 peut se transformer en une autre, la stase \u00e9tant anim\u00e9e par un tremblement et les textures en mouvement pouvant quant \u00e0 elles \u00eatre statiques, comme les rayons d\u2019une roue en rotation. J\u2019imagine un continuum dense sur toute son \u00e9tendue, bigarr\u00e9, plein d\u2019ondulations, de ruptures. <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Deux images principales ont \u00e9merg\u00e9 pendant le travail sur <em>Tanz\/haus<\/em> : d\u2019une part, l\u2019id\u00e9e d\u2019\u00ab automates \u00bb et sa relation au mouvement, et d\u2019autre part, une id\u00e9e tr\u00e8s particuli\u00e8re du mouvement, ce que l\u2019historien d\u2019art Henri Focillon appelle la \u00ab fragilit\u00e9 h\u00e9sitante \u00bb, une id\u00e9e \u00e0 la fois physique et conceptuelle du tremblement, du tremor, du vibrato. Au centre de <em>Tanz\/haus<\/em>, et c\u2019est l\u00e0 un moment symbolique, toute l\u2019activit\u00e9 \u00e9mane du fr\u00e9missement des cordes de guitare, un tremblement idiomatique r\u00e9sultant du feedback entre les capteurs magn\u00e9tiques de la guitare \u00e9lectrique. \u00c0 cet \u00e9gard, je ne pense pas \u00e0 l\u2019histoire de la guitare \u00e9lectrique, bien que j\u2019en sois conscient, mais plut\u00f4t \u00e0 un aspect plus pragmatique ou empirique qui consiste \u00e0 tenter de cr\u00e9er un moment en \u00e9quilibre entre immobilit\u00e9 et mouvement. Vous vous int\u00e9ressez \u00e0 l\u2019alchimie et \u00e0 la Kabbale.<\/span><\/p>\n<p><strong><span style=\"font-size: 14pt;\">L\u2019id\u00e9e de \u00ab haus \u00bb dans le titre est-elle li\u00e9e \u00e0 l\u2019\u00e9sot\u00e9risme ?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">Cela participe pour moi d\u2019un int\u00e9r\u00eat plus g\u00e9n\u00e9ral pour la langue, l\u2019histoire, les id\u00e9es ; en d\u2019autres termes, les fa\u00e7ons de penser. L\u2019\u00e9sot\u00e9risme ne m\u2019int\u00e9resse pas en soi, mais les \u00e9tymologies, oui, notamment toutes ces qualit\u00e9s que nous qualifions de \u00ab musicales \u00bb et qui \u00e9chappent \u00e0 la d\u00e9termination conceptuelle. De ce point de vue, tout est \u00ab cach\u00e9 \u00bb. En introduisant la barre oblique (\/) dans le titre, je s\u00e9pare et joins les deux termes, et ce signe typographique se refl\u00e8te d\u2019ailleurs dans l\u2019utilisation du point d\u2019orgue subito dans la pi\u00e8ce.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17990\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/dscf7653.jpg\" alt=\"\" width=\"1920\" height=\"1274\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/dscf7653.jpg 1920w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/dscf7653-300x199.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/dscf7653-768x510.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/dscf7653-1024x679.jpg 1024w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\"><strong>L\u2019utilisation assez r\u00e9pandue des bourdons dans <em>Tanz\/haus<\/em> est-elle li\u00e9e \u00e0 votre int\u00e9r\u00eat pour la musique indienne, qui a \u00e9t\u00e9 rendue explicite dans certaines de vos \u0153uvres \u00e0 la fin des ann\u00e9es 1970 ?<\/strong> <\/span><\/p>\n<p><span style=\"font-size: 14pt;\">C\u2019est probable, et elle est li\u00e9e aussi \u00e0 mes exp\u00e9riences ant\u00e9rieures avec la musique de cornemuse \u00e9cossaise, mais ce n\u2019est pas quelque chose de conscient en tant que tel. Je m\u2019int\u00e9resse plut\u00f4t, d\u2019une part, au maintien de points de rep\u00e8res ou de centres harmoniques et, d\u2019autre part, \u00e0 l\u2019instabilit\u00e9 subtile des notes p\u00e9dales, c\u2019est-\u00e0-dire des bourdons.<\/span><\/p>\n<p><strong><span style=\"font-size: 14pt;\">Quels types de sons avez-vous inclus dans la partie \u00e9lectronique ? Ouvrent-ils un champ dramaturgique ?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">L\u00e0 o\u00f9 les configurations analogique et num\u00e9rique se rencontrent, le champ s\u00e9mantique qui s\u2019ouvre prend certainement un aspect dramaturgique. L\u2019une des voix de la couche de mat\u00e9riel pr\u00e9enregistr\u00e9 est assez litt\u00e9rale puisqu\u2019il s\u2019agit d\u2019un bref extrait d\u2019un enregistrement audio d\u2019une conf\u00e9rence donn\u00e9e par Heidegger en 1952 sur les dangers de la technologie. Au-del\u00e0 de l\u2019ironie, les sons pr\u00e9enregistr\u00e9s se r\u00e9partissent pour moi en deux cat\u00e9gories fondamentales, symbolique et\/ou sonore ; les sons sont choisis soit pour leur charge r\u00e9f\u00e9rentielle, soit pour leur potentiel mn\u00e9monique. Excusez moi de ne parler que peu de po\u00e9sie. Vous en conviendrez, il est plus facile de d\u00e9guiser les \u00ab b\u00e9gaiements \u00bb (Beckett) derri\u00e8re le langage technique !<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\">D\u00e9couvrir la musique de James Dillon :<br \/>\n<\/span><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/f8-CyUEzOL4\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/CEbC72drbuA\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\nPhotos :\u00a0\u00a9 Janet Sinica \/ \u00a9 EIC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faisant sienne une conception cosmique de la musique, le compositeur \u00e9cossais James Dillon laisse volontiers planer un certain myst\u00e8re sur ses \u0153uvres. Sophistiqu\u00e9e, complexe et organique, sa musique peut aussi \u00eatre sensuelle et vibrante. Avec <em>Tanz\/haus: triptych 2017<\/em> qui sera jou\u00e9e pour la premi\u00e8re fois en France le 27 novembre 2019, il explore le champ \u00e0 la fois infinit\u00e9simal et abyssal du tremblement et du vibrato.<\/p>\n","protected":false},"author":122,"featured_media":17857,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[156,993],"class_list":["post-17457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-james-dillon","tag-musique-britannique","concert-demeure-et-tremblements"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comme un tremblement int\u00e9rieur. Entretien avec James Dillon, compositeur. - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comme un tremblement int\u00e9rieur. Entretien avec James Dillon, compositeur. - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"Faisant sienne une conception cosmique de la musique, le compositeur \u00e9cossais James Dillon laisse volontiers planer un certain myst\u00e8re sur ses \u0153uvres. Sophistiqu\u00e9e, complexe et organique, sa musique peut aussi \u00eatre sensuelle et vibrante. Avec Tanz\/haus: triptych 2017 qui sera jou\u00e9e pour la premi\u00e8re fois en France le 27 novembre 2019, il explore le champ \u00e0 la fois infinit\u00e9simal et abyssal du tremblement et du vibrato.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-17T17:04:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-20T14:17:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/demeureettremblements_doury_2010cl31_web_l300px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3000\" \/>\n\t<meta property=\"og:image:height\" content=\"1998\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Rigaudi\u00e8re\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Rigaudi\u00e8re\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/10\\\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/10\\\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\\\/\"},\"author\":{\"name\":\"Pierre Rigaudi\u00e8re\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/661ea739b85c10a912b434ffefe6f299\"},\"headline\":\"Comme un tremblement int\u00e9rieur. Entretien avec James Dillon, compositeur.\",\"datePublished\":\"2019-10-17T17:04:09+00:00\",\"dateModified\":\"2019-11-20T14:17:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/10\\\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\\\/\"},\"wordCount\":760,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/10\\\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2019\\\/10\\\/demeureettremblements_doury_2010cl31_web_l300px.jpg\",\"keywords\":[\"James Dillon\",\"musique britannique\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/10\\\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/10\\\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\\\/\",\"name\":\"Comme un tremblement int\u00e9rieur. Entretien avec James Dillon, compositeur. - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/10\\\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/10\\\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2019\\\/10\\\/demeureettremblements_doury_2010cl31_web_l300px.jpg\",\"datePublished\":\"2019-10-17T17:04:09+00:00\",\"dateModified\":\"2019-11-20T14:17:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/661ea739b85c10a912b434ffefe6f299\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/10\\\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/10\\\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/10\\\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2019\\\/10\\\/demeureettremblements_doury_2010cl31_web_l300px.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2019\\\/10\\\/demeureettremblements_doury_2010cl31_web_l300px.jpg\",\"width\":3000,\"height\":1998},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/10\\\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comme un tremblement int\u00e9rieur. Entretien avec James Dillon, compositeur.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/661ea739b85c10a912b434ffefe6f299\",\"name\":\"Pierre Rigaudi\u00e8re\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09881c67469fb3ac52693e208f3f81f987810d195f0c54465466557d2ba35148?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09881c67469fb3ac52693e208f3f81f987810d195f0c54465466557d2ba35148?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09881c67469fb3ac52693e208f3f81f987810d195f0c54465466557d2ba35148?s=96&d=mm&r=g\",\"caption\":\"Pierre Rigaudi\u00e8re\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/author\\\/pierre-rigaudiere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comme un tremblement int\u00e9rieur. Entretien avec James Dillon, compositeur. - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/","og_locale":"fr_FR","og_type":"article","og_title":"Comme un tremblement int\u00e9rieur. Entretien avec James Dillon, compositeur. - Ensemble intercontemporain","og_description":"Faisant sienne une conception cosmique de la musique, le compositeur \u00e9cossais James Dillon laisse volontiers planer un certain myst\u00e8re sur ses \u0153uvres. Sophistiqu\u00e9e, complexe et organique, sa musique peut aussi \u00eatre sensuelle et vibrante. Avec Tanz\/haus: triptych 2017 qui sera jou\u00e9e pour la premi\u00e8re fois en France le 27 novembre 2019, il explore le champ \u00e0 la fois infinit\u00e9simal et abyssal du tremblement et du vibrato.","og_url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2019-10-17T17:04:09+00:00","article_modified_time":"2019-11-20T14:17:56+00:00","og_image":[{"width":3000,"height":1998,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/demeureettremblements_doury_2010cl31_web_l300px.jpg","type":"image\/jpeg"}],"author":"Pierre Rigaudi\u00e8re","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pierre Rigaudi\u00e8re","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/"},"author":{"name":"Pierre Rigaudi\u00e8re","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/661ea739b85c10a912b434ffefe6f299"},"headline":"Comme un tremblement int\u00e9rieur. Entretien avec James Dillon, compositeur.","datePublished":"2019-10-17T17:04:09+00:00","dateModified":"2019-11-20T14:17:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/"},"wordCount":760,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/demeureettremblements_doury_2010cl31_web_l300px.jpg","keywords":["James Dillon","musique britannique"],"articleSection":["Entretien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/","url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/","name":"Comme un tremblement int\u00e9rieur. Entretien avec James Dillon, compositeur. - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/demeureettremblements_doury_2010cl31_web_l300px.jpg","datePublished":"2019-10-17T17:04:09+00:00","dateModified":"2019-11-20T14:17:56+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/661ea739b85c10a912b434ffefe6f299"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/demeureettremblements_doury_2010cl31_web_l300px.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/10\/demeureettremblements_doury_2010cl31_web_l300px.jpg","width":3000,"height":1998},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/10\/comme-un-tremblement-interieur-entretien-avec-james-dillon-compositeur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comme un tremblement int\u00e9rieur. Entretien avec James Dillon, compositeur."}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/661ea739b85c10a912b434ffefe6f299","name":"Pierre Rigaudi\u00e8re","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/09881c67469fb3ac52693e208f3f81f987810d195f0c54465466557d2ba35148?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/09881c67469fb3ac52693e208f3f81f987810d195f0c54465466557d2ba35148?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/09881c67469fb3ac52693e208f3f81f987810d195f0c54465466557d2ba35148?s=96&d=mm&r=g","caption":"Pierre Rigaudi\u00e8re"},"url":"https:\/\/www.ensembleintercontemporain.com\/fr\/author\/pierre-rigaudiere\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/17457\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/users\/122\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/comments\/?post=17457"}],"version-history":[{"count":12,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/17457\/revisions\/"}],"predecessor-version":[{"id":17996,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/posts\/17457\/revisions\/17996\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/media\/17857\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/media\/?parent=17457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/categories\/?post=17457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/fr\/wp-json\/wp\/v2\/tags\/?post=17457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}