{"id":9354,"date":"2016-09-30T11:00:26","date_gmt":"2016-09-30T09:00:26","guid":{"rendered":"http:\/\/www.ensembleinter.com\/accents-online\/?p=9354"},"modified":"2019-04-03T19:01:23","modified_gmt":"2019-04-03T17:01:23","slug":"cote-coree-entretien-avec-hae-sun-kang-violoniste","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/en\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/","title":{"rendered":"C\u00f4t\u00e9 Cor\u00e9e. Entretien avec Hae-Sun Kang, violoniste."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2016\/09\/1_IMG2158.jpg\" alt=\"1_img2158\" width=\"492\" height=\"459\" \/><br \/>\n<span style=\"color: #003366;\"><strong><span id=\"inserted6413\">D<\/span>u 26 au 28 octobre 2016 l\u2019EIC conclura\u00a0sa tourn\u00e9e en Asie par une s\u00e9rie de concerts et d\u2019activit\u00e9s p\u00e9dagogiques en Cor\u00e9e du Sud. Entretien avec Hae-Sun Kang, violoniste \u00e0 l\u2019Ensemble, originaire du \u00ab\u00a0Pays du matin calme\u00a0\u00bb.\u00a0<\/strong><\/span><\/p>\n<p><strong>Hae-Sun, que repr\u00e9sente pour vous cette tourn\u00e9e en Cor\u00e9e du Sud ?<\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">C\u2019est une grande premi\u00e8re\u00a0! C\u2019est en effet la premi\u00e8re fois que je vais en Cor\u00e9e avec l\u2019Ensemble intercontemporain \u2014 et pour cause, c\u2019est la premi\u00e8re visite de l\u2019EIC\u00a0dans ce pays. Pour moi, c\u2019est un honneur et une immense responsabilit\u00e9. En Cor\u00e9e, comme dans quelques autres pays, r\u00e8gne encore une id\u00e9e fausse et n\u00e9anmoins tenace\u00a0: celle qui voudrait que les musiciens qui interpr\u00e8tent la musique contemporaine le font parce qu\u2019ils sont moins bons que les autres et qu\u2019ils ne savent pas jouer autre chose. Je donne r\u00e9guli\u00e8rement des interviews \u00e0 des journalistes cor\u00e9ens, et cette question revient sans cesse\u00a0: je dois toujours d\u00e9mentir. L\u2019une des premi\u00e8res responsabilit\u00e9s pour moi au cours de cette tourn\u00e9e sera donc de montrer ce que signifie bien jouer les musiques d\u2019aujourd\u2019hui, qu\u2019il est inadmissible de mal les jouer, et que de bons musiciens existent qui les interpr\u00e8tent avec un grand sens professionnel et musical. C\u2019est absolument essentiel.<\/span><br \/>\n<span style=\"font-size: 14pt;\">D\u2019autre part, la sc\u00e8ne musicale cor\u00e9enne est rest\u00e9e assez classique, m\u00eame si on constate ces derni\u00e8res ann\u00e9es l\u2019apparition de quelques rendez-vous\u00a0de musique contemporaine. Le public tout comme les musiciens cor\u00e9ens attendent donc beaucoup de nous\u00a0: ils veulent d\u00e9couvrir notre r\u00e9pertoire et notre savoir-faire.<\/span><\/p>\n<p class=\"legend\" style=\"text-align: center;\">\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2016\/09\/2-Core\u0301e.jpg\" alt=\"2-coree\" width=\"492\" height=\"335\" \/>Tongyeong International Music Foundation<\/p>\n<p><strong>Vous n\u2019\u00eates pas seulement ambassadrice de cette musique aupr\u00e8s du public cor\u00e9en, mais aussi ambassadrice de la Cor\u00e9e au sein m\u00eame de l\u2019Ensemble intercontemporain\u00a0: que ferez-vous d\u00e9couvrir de la vie cor\u00e9enne \u00e0 vos coll\u00e8gues solistes\u00a0?<\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">Outre la vie culturelle, j\u2019aimerais surtout partager avec eux tout ce qui a trait \u00e0 l\u2019art de vivre cor\u00e9en. Certains y sont d\u00e9j\u00e0 all\u00e9s, mais beaucoup ne connaissent pas. Or la Cor\u00e9e est tr\u00e8s diff\u00e9rente des autres pays de la r\u00e9gion\u00a0(Japon, Chine, etc.)\u00a0: c\u2019est un pays \u00e0 part. Lorsqu\u2019on veut trouver un point de comparaison avec l\u2019Europe, c\u2019est souvent \u00e0 l\u2019Italie qu\u2019on la compare. Il y r\u00e8gne en effet quelque chose de tr\u00e8s m\u00e9diterran\u00e9en, voire latin\u00a0: la fantaisie, le c\u0153ur, la chaleur humaine, la spontan\u00e9it\u00e9. Les cor\u00e9ens sont tr\u00e8s accueillants, ouverts \u00e0 l\u2019autre, et j\u2019esp\u00e8re que mes coll\u00e8gues pourront en profiter.<\/span><br \/>\n<span style=\"font-size: 14pt;\">Cet esprit se retrouve d\u2019ailleurs dans les assiettes. La gastronomie cor\u00e9enne est bien plus vaste que le petit \u00e9chantillon qu\u2019on peut go\u00fbter en France et c\u2019est, l\u00e0 encore, une cuisine tr\u00e8s relev\u00e9e, qui pr\u00e9sente de nombreuses similitudes avec celles de l\u2019Italie ou de la Provence et, plus largement, de la M\u00e9diterran\u00e9e\u00a0: beaucoup d\u2019ail et de piments, de m\u00e9langes de poissons et de viandes.<\/span><br \/>\n<span style=\"font-size: 14pt;\">Au reste, cette exception cor\u00e9enne se retrouve \u00e9galement dans ses musiques traditionnelles, qui sont passionnantes. Si elles pr\u00e9sentent quelques familiarit\u00e9s avec celles de Chine ou du Japon, on ne pourrait pas les confondre.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2016\/09\/2-DSCF0176.jpg\" alt=\"2-dscf0176\" width=\"492\" height=\"328\" \/><\/p>\n<p><strong>Revenons \u00e0 la musique. Unsuk Chin est la compositrice\u00a0cor\u00e9enne\u00a0la plus connue et reconnue aujourd\u2019hui, notamment en Europe o\u00f9 elle r\u00e9side depuis longtemps. Elle pourrait appara\u00eetre comme \u00ab\u00a0l\u2019arbre qui cache la for\u00eat\u00a0\u00bb. Mais \u00e0 quoi ressemble cette for\u00eat\u00a0?<\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">J&#8217;habite Paris et j&#8217;ai rarement\u00a0l\u2019occasion de\u00a0s\u00e9journer\u00a0en Cor\u00e9e. J\u2019y vais\u00a0une fois par an pour me produire en soliste mais j\u2019y reste trop peu de temps pour apprendre \u00e0 conna\u00eetre la sc\u00e8ne artistique foisonnante qui s\u2019y d\u00e9veloppe. Je vois nombre de compositeurs qui m\u00e9riteraient d\u2019\u00eatre connus, mais j\u2019aurais du mal \u00e0 analyser les lignes de force. J\u2019attends justement de cette tourn\u00e9e d\u2019en d\u00e9couvrir davantage.<\/span><br \/>\n<span style=\"font-size: 14pt;\">Le fait est que la relative m\u00e9connaissance dans laquelle se trouve le reste du monde eu \u00e9gard \u00e0 la cr\u00e9ation musicale cor\u00e9enne tient \u00e9galement \u00e0 l\u2019histoire r\u00e9cente de ce pays, de la fin du second conflit mondiale \u00e0 aujourd\u2019hui. Depuis une vingtaine d\u2019ann\u00e9es, la libert\u00e9 de circulation s\u2019am\u00e9liore et de nombreux talents \u00e9closent, rayonnant bien au-del\u00e0 du territoire cor\u00e9en. On l\u2019observe dans tous les domaines artistiques\u00a0: le cin\u00e9ma, par exemple, qui remporte un tr\u00e8s grand succ\u00e8s aujourd\u2019hui \u00e0 l\u2019international, mais aussi la peinture et la litt\u00e9rature\u2026 sans parler de la musique, bien entendu.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/236612566&amp;color=ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Photos (de haut en bas)\u00a0: \u00a9 Franck Ferville \/ DR \/ \u00a9 EIC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Du 26 au 28 octobre l\u2019EIC conclura sa tourn\u00e9e en Asie par une s\u00e9rie de concerts et d\u2019activit\u00e9s p\u00e9dagogiques en Cor\u00e9e du Sud. Entretien avec Hae-Sun Kang, violoniste \u00e0 l\u2019Ensemble, originaire du \u00ab pays du Matin calme \u00bb.<\/p>\n","protected":false},"author":5,"featured_media":15963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[701,736,16],"class_list":["post-9354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-annee-france-coree","tag-coree","tag-hae-sun-kang"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f4t\u00e9 Cor\u00e9e. Entretien avec Hae-Sun Kang, violoniste. - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/en\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f4t\u00e9 Cor\u00e9e. Entretien avec Hae-Sun Kang, violoniste. - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"Du 26 au 28 octobre l\u2019EIC conclura sa tourn\u00e9e en Asie par une s\u00e9rie de concerts et d\u2019activit\u00e9s p\u00e9dagogiques en Cor\u00e9e du Sud. Entretien avec Hae-Sun Kang, violoniste \u00e0 l\u2019Ensemble, originaire du \u00ab pays du Matin calme \u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-30T09:00:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-03T17:01:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2016\/09\/kang_hae-sun_img2153franck-ferville.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\u00e9remie Szpirglas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00e9remie Szpirglas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2016\\\/09\\\/cote-coree-entretien-avec-hae-sun-kang-violoniste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2016\\\/09\\\/cote-coree-entretien-avec-hae-sun-kang-violoniste\\\/\"},\"author\":{\"name\":\"J\u00e9remie Szpirglas\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/439a7dd5cd8a167c34c931d7cc900214\"},\"headline\":\"C\u00f4t\u00e9 Cor\u00e9e. Entretien avec Hae-Sun Kang, violoniste.\",\"datePublished\":\"2016-09-30T09:00:26+00:00\",\"dateModified\":\"2019-04-03T17:01:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2016\\\/09\\\/cote-coree-entretien-avec-hae-sun-kang-violoniste\\\/\"},\"wordCount\":826,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2016\\\/09\\\/cote-coree-entretien-avec-hae-sun-kang-violoniste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2016\\\/09\\\/kang_hae-sun_img2153franck-ferville.jpg\",\"keywords\":[\"ann\u00e9e France-Cor\u00e9e\",\"Cor\u00e9e\",\"Hae-Sun Kang\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2016\\\/09\\\/cote-coree-entretien-avec-hae-sun-kang-violoniste\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2016\\\/09\\\/cote-coree-entretien-avec-hae-sun-kang-violoniste\\\/\",\"name\":\"C\u00f4t\u00e9 Cor\u00e9e. Entretien avec Hae-Sun Kang, violoniste. - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2016\\\/09\\\/cote-coree-entretien-avec-hae-sun-kang-violoniste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2016\\\/09\\\/cote-coree-entretien-avec-hae-sun-kang-violoniste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2016\\\/09\\\/kang_hae-sun_img2153franck-ferville.jpg\",\"datePublished\":\"2016-09-30T09:00:26+00:00\",\"dateModified\":\"2019-04-03T17:01:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/439a7dd5cd8a167c34c931d7cc900214\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2016\\\/09\\\/cote-coree-entretien-avec-hae-sun-kang-violoniste\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2016\\\/09\\\/cote-coree-entretien-avec-hae-sun-kang-violoniste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2016\\\/09\\\/cote-coree-entretien-avec-hae-sun-kang-violoniste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2016\\\/09\\\/kang_hae-sun_img2153franck-ferville.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2016\\\/09\\\/kang_hae-sun_img2153franck-ferville.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2016\\\/09\\\/cote-coree-entretien-avec-hae-sun-kang-violoniste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f4t\u00e9 Cor\u00e9e. Entretien avec Hae-Sun Kang, violoniste.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/439a7dd5cd8a167c34c931d7cc900214\",\"name\":\"J\u00e9remie Szpirglas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g\",\"caption\":\"J\u00e9remie Szpirglas\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/author\\\/benjamin-szpirglas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f4t\u00e9 Cor\u00e9e. Entretien avec Hae-Sun Kang, violoniste. - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/en\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/","og_locale":"en_US","og_type":"article","og_title":"C\u00f4t\u00e9 Cor\u00e9e. Entretien avec Hae-Sun Kang, violoniste. - Ensemble intercontemporain","og_description":"Du 26 au 28 octobre l\u2019EIC conclura sa tourn\u00e9e en Asie par une s\u00e9rie de concerts et d\u2019activit\u00e9s p\u00e9dagogiques en Cor\u00e9e du Sud. Entretien avec Hae-Sun Kang, violoniste \u00e0 l\u2019Ensemble, originaire du \u00ab pays du Matin calme \u00bb.","og_url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2016-09-30T09:00:26+00:00","article_modified_time":"2019-04-03T17:01:23+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2016\/09\/kang_hae-sun_img2153franck-ferville.jpg","type":"image\/jpeg"}],"author":"J\u00e9remie Szpirglas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"J\u00e9remie Szpirglas","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/"},"author":{"name":"J\u00e9remie Szpirglas","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/439a7dd5cd8a167c34c931d7cc900214"},"headline":"C\u00f4t\u00e9 Cor\u00e9e. Entretien avec Hae-Sun Kang, violoniste.","datePublished":"2016-09-30T09:00:26+00:00","dateModified":"2019-04-03T17:01:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/"},"wordCount":826,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2016\/09\/kang_hae-sun_img2153franck-ferville.jpg","keywords":["ann\u00e9e France-Cor\u00e9e","Cor\u00e9e","Hae-Sun Kang"],"articleSection":["Entretien"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/","url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/","name":"C\u00f4t\u00e9 Cor\u00e9e. Entretien avec Hae-Sun Kang, violoniste. - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2016\/09\/kang_hae-sun_img2153franck-ferville.jpg","datePublished":"2016-09-30T09:00:26+00:00","dateModified":"2019-04-03T17:01:23+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/439a7dd5cd8a167c34c931d7cc900214"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2016\/09\/kang_hae-sun_img2153franck-ferville.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2016\/09\/kang_hae-sun_img2153franck-ferville.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2016\/09\/cote-coree-entretien-avec-hae-sun-kang-violoniste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/en\/"},{"@type":"ListItem","position":2,"name":"C\u00f4t\u00e9 Cor\u00e9e. Entretien avec Hae-Sun Kang, violoniste."}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/439a7dd5cd8a167c34c931d7cc900214","name":"J\u00e9remie Szpirglas","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g","caption":"J\u00e9remie Szpirglas"},"url":"https:\/\/www.ensembleintercontemporain.com\/en\/author\/benjamin-szpirglas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/9354\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/users\/5\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/comments\/?post=9354"}],"version-history":[{"count":3,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/9354\/revisions\/"}],"predecessor-version":[{"id":16602,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/9354\/revisions\/16602\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/15963\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/?parent=9354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/categories\/?post=9354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/tags\/?post=9354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}