{"id":8178,"date":"2015-07-17T14:30:18","date_gmt":"2015-07-17T12:30:18","guid":{"rendered":"http:\/\/www.ensembleinter.com\/accents-online\/?p=8178"},"modified":"2015-07-17T14:30:18","modified_gmt":"2015-07-17T12:30:18","slug":"retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/","title":{"rendered":"Retour sur la saison 2014-15 : Matthias Pintscher, directeur musical de l&#039;Ensemble intercontemporain"},"content":{"rendered":"<p><a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/Matthias-Pinstcher-1DEF\u00a9Franck-Ferville.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8194\" alt=\"Matthias Pinstcher-1DEF\u00a9Franck Ferville\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/Matthias-Pinstcher-1DEF\u00a9Franck-Ferville.jpg\" width=\"492\" height=\"533\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/Matthias-Pinstcher-1DEF\u00a9Franck-Ferville.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/Matthias-Pinstcher-1DEF\u00a9Franck-Ferville-277x300.jpg 277w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><br \/>\n<span style=\"color: #000080;\"><i><span style=\"font-size: large;\">A<\/span>pr\u00e8s les solistes de l\u2019Ensemble il \u00e9tait logique que ces retours sur la saison 2014-15 s\u2019ach\u00e8vent par celui de notre directeur musical Matthias Pintscher qui revient donc pour nous sur une ann\u00e9e qui illustre remarquablement bien son ambitieux projet artistique.<\/i><\/span><br \/>\n&nbsp;<br \/>\n<b>Quelles ont \u00e9t\u00e9 pour vous les exp\u00e9riences les plus m\u00e9morables de cette saison pass\u00e9e\u00a0?<\/b><br \/>\nL\u2019exp\u00e9rience la plus forte a \u00e9t\u00e9 la d\u00e9couverte de l\u2019acoustique de la grande salle de la Philharmonie (photo ci-dessous) . Quel d\u00e9lice, que ce soit pour nous, mais aussi tous les musiciens qui auront la chance de s\u2019y produire, et surtout pour tous les m\u00e9lomanes\u00a0! C\u2019est l\u2019une des plus belles salles et l\u2019une des meilleures acoustiques d\u2019Europe\u00a0: d\u2019une grande transparence et d\u2019une rare pr\u00e9cision, alli\u00e9es \u00e0 une chaleur et une rondeur extr\u00eamement agr\u00e9ables. On peut saisir le moindre d\u00e9tail, la moindre nuance \u2014 jusqu\u2019au dernier rang du dernier balcon. C\u2019est un ph\u00e9nom\u00e8ne rare qu\u2019une salle de concert fonctionne si bien du point de vue acoustique. Comme pour toute nouvelle salle, quelques ajustements restent sans doute \u00e0 faire, particuli\u00e8rement pour la mettre pleinement au service de projets innovants. \u00a0Je suis certain que nous y arriverons.<br \/>\n<a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSCF1737.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8184\" alt=\"DSCF1737\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSCF1737.jpg\" width=\"492\" height=\"330\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSCF1737.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSCF1737-300x201.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><br \/>\nC\u2019est aussi dans cette salle qu\u2019ont eu lieu les deux principaux temps forts de cette derni\u00e8re saison \u2014 et je crois que je parle l\u00e0, non seulement pour moi, mais pour tous les solistes de l\u2019Ensemble \u2014\u00a0: le premier \u00e9tant le concert au cours duquel nous avons jou\u00e9 <i>Am\u00e9riques<\/i> de Var\u00e8se (photo ci-dessous) et <i>Pli selon Pli<\/i> de Boulez avec les \u00e9tudiants du Conservatoire de Paris, et le second \u00e9tant, en juin, le concert <i>R\u00e9pons,<\/i> cette \u0153uvre qui est notre carte de visite\u00a0et que personne d\u2019autre au monde ne joue avec la m\u00eame conviction, la pr\u00e9cision, la m\u00eame profondeur. Deux concerts qui se sont jou\u00e9s \u00e0 guichet ferm\u00e9 \u2014signe que nous sommes sans doute le vrai.<br \/>\n<a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSCF1947.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8183\" alt=\"DSCF1947\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSCF1947.jpg\" width=\"492\" height=\"328\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSCF1947.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSCF1947-300x200.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><br \/>\nAu reste, un autre aspect que j\u2019ai beaucoup aim\u00e9 cette saison, c\u2019est de diriger beaucoup d\u2019\u0153uvres de Pierre Boulez, \u00e0 l\u2019occasion de son quatre-vingt-dixi\u00e8me anniversaire\u00a0: Pierre Boulez est mon temps fort personnel de cette saison\u00a0! J\u2019en ai m\u00eame dirig\u00e9 dans d\u2019autres circonstances, sans l\u2019Ensemble et loin de Paris. Je garderai toujours en m\u00e9moire le soir o\u00f9 nous avons jou\u00e9 <i>R\u00e9pons<\/i> dans ce lieu si particulier qu\u2019est la Gashouder d\u2019Amsterdam, gigantesque silo industriel reconverti en salle de spectacle.<br \/>\n<a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSCF52481.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8187\" alt=\"DSCF5248\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSCF52481.jpg\" width=\"492\" height=\"277\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSCF52481.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSCF52481-300x169.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">\u00a0<span style=\"font-size: small;\">&#8230;<em>explosante-fixe<\/em>&#8230; de Pierre Boulez \u00e0 la Cit\u00e9 de la musique (Philharmonie 2) \u00a0le 21.03.2015<\/span><\/p>\n<p>Les deux soir\u00e9es Turbulences en \u00ab\u00a0clair-obscur\u00a0\u00bb avec Marko Nikodijevic (photo ci-dessous) ont \u00e9t\u00e9 un autre temps fort de cette saison. Je n\u2019y \u00e9tais pas pr\u00e9sent moi-m\u00eame, mais le retour que j\u2019ai eu a \u00e9t\u00e9 \u00e9tonnamment positif, tant de la part du public que des musiciens qui ont tous \u00e9t\u00e9 enthousiasm\u00e9s par cette rencontre \u2014 au point que nous lui avons pass\u00e9 une nouvelle commande. R\u00e9ussir ainsi \u00e0 int\u00e9grer \u00e0 l\u2019univers de l\u2019Ensemble une galaxie qui lui \u00e9tait jusque l\u00e0 compl\u00e8tement inconnue est pour moi un grand plaisir et une source de fiert\u00e9.<br \/>\n<a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSCF8610-BD1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8195\" alt=\"DSCF8610-BD\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSCF8610-BD1.jpg\" width=\"492\" height=\"418\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSCF8610-BD1.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSCF8610-BD1-300x255.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: small;\">Gr\u00e9goire Simon ( \u00e0 gauche) et Marko Nikodijevic<\/span><\/p>\n<p>Dans le m\u00eame ordre d\u2019id\u00e9es, d\u2019un ensemble qui investit sur l\u2019avenir d\u2019un artiste, un autre souvenir fort de cette saison a \u00e9t\u00e9 de voir la mani\u00e8re dont notre jeune chef assistant Julien Leroy (photo ci-dessous) a pris son essor\u00a0: si intelligent et si modeste, il s\u2019est d\u00e9velopp\u00e9 au cours de ces trois derni\u00e8res ann\u00e9es d\u2019une mani\u00e8re extraordinaire, d\u2019un point de vue artistique et humain. C\u2019est une image un peu triste, puisque cette saison marque aussi la fin de son passage \u00e0 l\u2019Ensemble\u00a0: Julien nous quitte pour se lancer dans une carri\u00e8re prometteuse, \u00e0 n\u2019en pas douter.<br \/>\n<a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSC_9729.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8193\" alt=\"DSC_9729\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSC_9729.jpg\" width=\"492\" height=\"327\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSC_9729.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSC_9729-300x199.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><br \/>\n&nbsp;<br \/>\n<b>Quelles surprises cette saison vous a-t-elle r\u00e9serv\u00e9es\u00a0?<\/b><br \/>\nDans le domaine de la cr\u00e9ation, les surprises sont nombreuses \u2014 je dirais m\u00eame qu\u2019elles sont attendues\u00a0! On ne peut pas planifier le succ\u00e8s d\u2019un concert ou d\u2019une cr\u00e9ation. Les r\u00e9actions \u00e0 une nouvelle partition, de la part des musiciens ou du public, sont impr\u00e9visibles. Parfois c\u2019est l\u2019\u00e9chec total. Parfois, c\u2019est une excellent surprise, comme par exemple la pi\u00e8ce que nous avait concoct\u00e9 mon ami new-yorkais David Fulmer (photo ci-dessous) : sa musique a \u00e9t\u00e9 imm\u00e9diatement adopt\u00e9e par les musiciens, bien que non conventionnelle et tr\u00e8s diff\u00e9rente de ce \u00e0 quoi ils sont habitu\u00e9s.<br \/>\n<a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSCF6901.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8188\" alt=\"DSCF6901\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSCF6901.jpg\" width=\"492\" height=\"277\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSCF6901.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSCF6901-300x169.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><br \/>\nD\u2019autres projets qui me tenaient tr\u00e8s \u00e0 c\u0153ur, notamment p\u00e9dagogiques, ont \u00e9t\u00e9 d\u2019excellentes surprises\u00a0: la r\u00e9action des jeunes publics est un v\u00e9ritable bonheur. Et je veux remercier ici Sylvie Cohen de les avoir rendu possibles. Je me souviendrai toujours de ce jeune gar\u00e7on, auquel Cl\u00e9ment Lebrun avait confi\u00e9 la direction de l\u2019Ensemble\u00a0: debout sur l\u2019estrade, il \u00ab\u00a0touchait\u00a0\u00bb le son, conduisant avec son corps un crescendo ou un decrescendo\u2026 Cette vision fascinante d\u2019un enfant faisant l\u2019exp\u00e9rience du pouvoir du son me remplit d\u2019espoir quant \u00e0 l\u2019avenir.<br \/>\n<a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSCF4497.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8186\" alt=\"DSCF4497\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2015\/07\/DSCF4497.jpg\" width=\"492\" height=\"328\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSCF4497.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/DSCF4497-300x200.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><br \/>\nSur une note un peu plus m\u00e9lancolique, nous avons \u00e9t\u00e9 surpris par la d\u00e9cision de notre talentueux et aventureux altiste Gr\u00e9goire Simon de poursuivre sa carri\u00e8re seul, \u00e0 Berlin\u00a0\u2014 mais ce sera aussi l\u2019occasion de d\u00e9couvrir le nouveau soliste qui le remplacera. \u00c0 ce sujet, nous aurons \u00e9galement la chance d\u2019accueillir la saison prochaine un nouveau trompettiste.<br \/>\n<b style=\"line-height: 1.5em;\">Certaines des nombreuses activit\u00e9s men\u00e9es cette ann\u00e9e vous ont-elles inspir\u00e9 de nouvelles id\u00e9es de format\u00a0?<\/b><br \/>\nC\u2019est une chose de r\u00e9fl\u00e9chir \u00e0 des formats, c\u2019en est une autre d\u2019en faire l\u2019exp\u00e9rience, dans les contraintes pragmatiques des organisateurs. Tout ce que nous faisons est une continuation du travail engag\u00e9, en regardant toujours vers l\u2019avant. Nous continuerons ainsi \u00e0 m\u00ealer pi\u00e8ces solos, pi\u00e8ces de chambre non dirig\u00e9es et pi\u00e8ces d\u2019ensemble\u00a0: ce m\u00e9lange est \u00e0 mon sens tr\u00e8s sain pour l\u2019oreille et permet de pr\u00e9server un esprit frais afin de mieux appr\u00e9cier les nuances et la complexit\u00e9 de chacune.<br \/>\nD\u2019autre part, nous initions la saison prochaine un projet en collaboration avec la Ga\u00eet\u00e9 Lyrique\u00a0: quatre \u00ab\u00a0ateliers-concerts\u00a0\u00bb de d\u00e9cembre 2015 \u00e0 juin 2016 men\u00e9s conjointement par la jeune et tr\u00e8s originale compositrice Patricia Alessandrini, Cl\u00e9ment Lebrun que notre public parisien conna\u00eet bien, et les solistes de l\u2019Ensemble. La Ga\u00eet\u00e9 Lyrique est pour nous un nouveau lieu qui nous permet d\u2019aller \u00e0 la rencontre d\u2019autres publics \u00e0 Paris. Le lieu de l\u2019\u00e9v\u00e9nement, et sa visibilit\u00e9, rev\u00eat une importance au moins \u00e9gale celle de la r\u00e9flexion sur son format.<br \/>\n&nbsp;<br \/>\nA voir aussi : \u00a0la captation d&#8217;<em>Am\u00e9riques<\/em> d&#8217;Edgard Var\u00e8se r\u00e9alis\u00e9e dans la Grande salle de la Philharmonie de Paris le 3 f\u00e9vrier 2015.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Upo5FStElCc\" height=\"277\" width=\"492\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><br \/>\n&nbsp;<br \/>\nPhotos de haut en bas : (c) Franck Ferville \/ (c) Luc Hossepied pour l&#8217;Ensemble intercontemporain<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s les solistes de l\u2019Ensemble il \u00e9tait logique que ces retours sur la saison 2014-15 s\u2019ach\u00e8vent par celui de notre directeur musical Matthias Pintscher qui revient donc pour nous sur une ann\u00e9e qui illustre remarquablement bien son ambitieux et stimulant projet artistique.<\/p>\n","protected":false},"author":5,"featured_media":8191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[634,662,170,631,579,600,562,563],"class_list":["post-8178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-clement-lebrun","tag-conservatoire-de-paris","tag-edgard-varese","tag-marko-nikodijevic","tag-matthias-pinstcher","tag-philharmonie-de-paris","tag-turbulences","tag-week-end-turbulences"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retour sur la saison 2014-15 : Matthias Pintscher, directeur musical de l&#039;Ensemble intercontemporain - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retour sur la saison 2014-15 : Matthias Pintscher, directeur musical de l&#039;Ensemble intercontemporain - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s les solistes de l\u2019Ensemble il \u00e9tait logique que ces retours sur la saison 2014-15 s\u2019ach\u00e8vent par celui de notre directeur musical Matthias Pintscher qui revient donc pour nous sur une ann\u00e9e qui illustre remarquablement bien son ambitieux et stimulant projet artistique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-17T12:30:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/Matthias-Pinstcher-2DEF\u00a9Franck-Ferville.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"464\" \/>\n\t<meta property=\"og:image:height\" content=\"237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\u00e9remie Szpirglas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00e9remie Szpirglas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2015\\\/07\\\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2015\\\/07\\\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\\\/\"},\"author\":{\"name\":\"J\u00e9remie Szpirglas\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/439a7dd5cd8a167c34c931d7cc900214\"},\"headline\":\"Retour sur la saison 2014-15 : Matthias Pintscher, directeur musical de l&#039;Ensemble intercontemporain\",\"datePublished\":\"2015-07-17T12:30:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2015\\\/07\\\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\\\/\"},\"wordCount\":1207,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2015\\\/07\\\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2015\\\/07\\\/Matthias-Pinstcher-2DEF\u00a9Franck-Ferville.jpg\",\"keywords\":[\"Cl\u00e9ment Lebrun\",\"Conservatoire de Paris\",\"Edgard Var\u00e8se\",\"Marko Nikodijevic\",\"Matthias Pinstcher\",\"Philharmonie de Paris\",\"Turbulences\",\"week-end Turbulences\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2015\\\/07\\\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2015\\\/07\\\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\\\/\",\"name\":\"Retour sur la saison 2014-15 : Matthias Pintscher, directeur musical de l&#039;Ensemble intercontemporain - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2015\\\/07\\\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2015\\\/07\\\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2015\\\/07\\\/Matthias-Pinstcher-2DEF\u00a9Franck-Ferville.jpg\",\"datePublished\":\"2015-07-17T12:30:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/439a7dd5cd8a167c34c931d7cc900214\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2015\\\/07\\\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2015\\\/07\\\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2015\\\/07\\\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2015\\\/07\\\/Matthias-Pinstcher-2DEF\u00a9Franck-Ferville.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2015\\\/07\\\/Matthias-Pinstcher-2DEF\u00a9Franck-Ferville.jpg\",\"width\":464,\"height\":237},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2015\\\/07\\\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retour sur la saison 2014-15 : Matthias Pintscher, directeur musical de l&#039;Ensemble intercontemporain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/439a7dd5cd8a167c34c931d7cc900214\",\"name\":\"J\u00e9remie Szpirglas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g\",\"caption\":\"J\u00e9remie Szpirglas\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/author\\\/benjamin-szpirglas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retour sur la saison 2014-15 : Matthias Pintscher, directeur musical de l&#039;Ensemble intercontemporain - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/en\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/","og_locale":"en_US","og_type":"article","og_title":"Retour sur la saison 2014-15 : Matthias Pintscher, directeur musical de l&#039;Ensemble intercontemporain - Ensemble intercontemporain","og_description":"Apr\u00e8s les solistes de l\u2019Ensemble il \u00e9tait logique que ces retours sur la saison 2014-15 s\u2019ach\u00e8vent par celui de notre directeur musical Matthias Pintscher qui revient donc pour nous sur une ann\u00e9e qui illustre remarquablement bien son ambitieux et stimulant projet artistique.","og_url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2015-07-17T12:30:18+00:00","og_image":[{"width":464,"height":237,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/Matthias-Pinstcher-2DEF\u00a9Franck-Ferville.jpg","type":"image\/jpeg"}],"author":"J\u00e9remie Szpirglas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"J\u00e9remie Szpirglas","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/"},"author":{"name":"J\u00e9remie Szpirglas","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/439a7dd5cd8a167c34c931d7cc900214"},"headline":"Retour sur la saison 2014-15 : Matthias Pintscher, directeur musical de l&#039;Ensemble intercontemporain","datePublished":"2015-07-17T12:30:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/"},"wordCount":1207,"commentCount":0,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/Matthias-Pinstcher-2DEF\u00a9Franck-Ferville.jpg","keywords":["Cl\u00e9ment Lebrun","Conservatoire de Paris","Edgard Var\u00e8se","Marko Nikodijevic","Matthias Pinstcher","Philharmonie de Paris","Turbulences","week-end Turbulences"],"articleSection":["Entretien"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/","url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/","name":"Retour sur la saison 2014-15 : Matthias Pintscher, directeur musical de l&#039;Ensemble intercontemporain - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/Matthias-Pinstcher-2DEF\u00a9Franck-Ferville.jpg","datePublished":"2015-07-17T12:30:18+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/439a7dd5cd8a167c34c931d7cc900214"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/Matthias-Pinstcher-2DEF\u00a9Franck-Ferville.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2015\/07\/Matthias-Pinstcher-2DEF\u00a9Franck-Ferville.jpg","width":464,"height":237},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2015\/07\/retour-sur-la-saison-2014-15-matthias-pintscher-directeur-musical-de-lensemble-intercontemporain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/en\/"},{"@type":"ListItem","position":2,"name":"Retour sur la saison 2014-15 : Matthias Pintscher, directeur musical de l&#039;Ensemble intercontemporain"}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/439a7dd5cd8a167c34c931d7cc900214","name":"J\u00e9remie Szpirglas","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g","caption":"J\u00e9remie Szpirglas"},"url":"https:\/\/www.ensembleintercontemporain.com\/en\/author\/benjamin-szpirglas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/8178\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/users\/5\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/comments\/?post=8178"}],"version-history":[{"count":0,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/8178\/revisions\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/8191\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/?parent=8178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/categories\/?post=8178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/tags\/?post=8178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}