{"id":7322,"date":"2014-09-30T17:45:44","date_gmt":"2014-09-30T15:45:44","guid":{"rendered":"http:\/\/www.ensembleinter.com\/accents-online\/?p=7322"},"modified":"2014-09-30T17:45:44","modified_gmt":"2014-09-30T15:45:44","slug":"matieres-sonores-entretien-avec-helmut-lachenmann-compositeur","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/","title":{"rendered":"Mati\u00e8res sonores. Grand entretien avec Helmut Lachenmann, compositeur"},"content":{"rendered":"<p><a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2014\/09\/Unknown.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7323\" alt=\"Unknown\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2014\/09\/Unknown.jpeg\" width=\"492\" height=\"488\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/09\/Unknown.jpeg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/09\/Unknown-150x150.jpeg 150w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/09\/Unknown-300x298.jpeg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><br \/>\n<em><span style=\"color: #333300;\">Avec Helmut Lachenmann il faut s\u2019attendre \u00e0 une r\u00e9vision lucide de tout le r\u00e8gne musical\u00a0: depuis la production m\u00eame des sons (ce qui fut fait avec sa \u00ab\u00a0musique concr\u00e8te instrumentale\u00a0\u00bb dans les ann\u00e9es soixante), au protocole du concert lui-m\u00eame, comme dans ces <\/span><\/em><span style=\"color: #333300;\">Concertini (<\/span><em><span style=\"color: #333300;\">2005) au programme de la <a href=\"http:\/\/www.ensembleinter.com\/fr\/fiche-concert.php?IDconcert=757&amp;precedent=756&amp;is_transmettre=0\">soir\u00e9e du 17 octobre prochain \u00e0 la Cit\u00e9 de la musique<\/a>. Cet entretien au long cours men\u00e9 par le musicologue Martin Kaltenecker, sp\u00e9cialiste de l&#8217;oeuvre du compositeur allemand, nous \u00e9claire sur le parcours singulier d\u2019un immense explorateur de la mati\u00e8re sonore.<\/span><\/em><br \/>\n&nbsp;<br \/>\nNous vivons une \u00e9poque o\u00f9 l\u2019acc\u00e8s aux partitions et la circulation des oeuvres est facile. J\u2019imagine que quand vous avez commenc\u00e9 \u00e0 \u00e9tudier la composition, en 1954, la situation \u00e9tait encore tr\u00e8s diff\u00e9rente ?<br \/>\nJ\u2019ai r\u00e9ussi, \u00e0 l\u2019\u00e9poque, \u00e0 me procurer par toutes sortes de biais les grandes partitions d\u2019orchestre. J\u2019avais connu Anton Webern surtout parce que Wolfgang Fortner, qui enseignait la composition \u00e0 Fribourg et avait l\u00e0-bas un ensemble d\u2019\u00e9tudiants, avait dirig\u00e9 (tant bien que mal) le <em>Concerto op. 24<\/em> et la <em>Symphonie op. 22.<\/em> Mon propre professeur, Johann Nepomuk David, avait fait presser un disque \u00e0 partir de cet enregistrement que j\u2019\u00e9coutais en boucle. En 1957, lorsque je suis venu pour la premi\u00e8re fois \u00e0 Darmstadt, il y a eu une analyse tr\u00e8s d\u00e9taill\u00e9e de la cantate <em>Augenlicht<\/em> de Webern par Hermann Scherchen, et c\u2019est lui au fond qui m\u2019a fait conna\u00eetre son travail. Je me souviens aussi qu\u2019il n\u2019existait pas encore \u00e0 l\u2019\u00e9poque de partition publi\u00e9e de <em>Wozzeck<\/em> et j\u2019ai d\u00fb emprunter la grande partition du chef. J\u2019ai aussi recopi\u00e9 le <em>Concerto de chambre<\/em> de Berg, qui appartenait \u00e0 la radio de Stuttgart, et j\u2019ai fait de m\u00eame pour Webern. Le premier mouvement de sa symphonie est un double canon ; je l\u2019ai donc d\u00e9pli\u00e9 et not\u00e9 sur quatre port\u00e9es, comme dans une particelle. J\u2019usais beaucoup de papier \u00e0 l\u2019\u00e9poque pour ce type de travaux. J\u2019ai \u00e9galement reproduit <em>Kontra-Punkte<\/em> de Stockhausen, d\u00e9j\u00e0 publi\u00e9 par Universal mais que j\u2019apprenais ainsi vraiment \u00e0 conna\u00eetre en prenant chaque son dans la main. Nous n\u2019avions pas non plus acc\u00e8s en Allemagne au <em>Trio \u00e0 cordes<\/em> de Sch\u00f6nberg, publi\u00e9 par un \u00e9diteur am\u00e9ricain ; l\u00e0 aussi je recopiais. Et puis finalement, la raison pour laquelle Nono a accept\u00e9 de me prendre comme \u00e9l\u00e8ve (au lieu de se consacrer \u00e0 sa femme et \u00e0 sa composition, dans cet ordre, comme il me le disait dans une lettre), c\u2019est que je lui avais envoy\u00e9 ses <em>Varianti<\/em> enti\u00e8rement recopi\u00e9s par moi. C\u2019\u00e9tait un peu comme pour la Torah chez les Juifs : j\u2019avais con\u00e7u une sorte de copie verticale, en rouleau, qui faisait appara\u00eetre les variations progressives.<br \/>\n<iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/3MChTWNDAg8?list=RDy7Gzrake8nI\" height=\"277\" width=\"492\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><br \/>\nEst-ce que les exp\u00e9riences d\u2019\u00e9coute ont ensuite confirm\u00e9 (ou infirm\u00e9) ce qu\u2019on pouvait imaginer \u00e0 partir de la partition ?<br \/>\nDisons que pour ce qui est de l\u2019\u00c9cole de Vienne, comme je jouais aussi les <em>Variations op. 27<\/em> de Webern, je saisissais bien l\u2019esprit de cette musique. Nono, c\u2019est diff\u00e9rent \u2013 j\u2019aurais pu contempler tout aussi bien une constellation. J\u2019y voyais une sorte de paysage, encore que la partition \u00e9tait relativement suggestive \u00e0 cause des indications dynamiques, des crescendos sur une seule note ; il y avait des gestes rh\u00e9toriques que l\u2019on rep\u00e9rait. C\u2019est une chose d\u2019ailleurs d\u2019imaginer par avance l\u2019apparence sonore d\u2019une musique, et une autre de pr\u00e9voir son apparence expressive. Et quant \u00e0 Nono, je crois bien qu\u2019il \u00ab n\u2019entendait \u00bb pas vraiment ce qu\u2019il composait \u2013 je dis l\u00e0 une chose horrible \u00e0 imaginer pour un musicien fran\u00e7ais ! Mais il n\u2019y avait alors \u00e0 Venise aucune musique contemporaine \u00e0 \u00e9couter, rien, contrairement \u00e0 Berio, qui pouvait travailler avec des ensembles comme Stockhausen ou Boulez.<br \/>\nNono \u00e9tait dans son appartement sur la Giudecca et il a du coup choisi des effectifs tr\u00e8s homog\u00e8nes : des voix, quelques percussions s\u00e9lectionn\u00e9es, comme dans <em>Cori di Didone<\/em>, un monde sonore qu\u2019il pouvait imaginer parfaitement et auquel il appliquait un travail de combinatoire. Souvent,\u00a0il \u00e9tait le premier surpris par le r\u00e9sultat, voire choqu\u00e9 ! Mais pour moi, cet \u00e9l\u00e9ment de surprise est tr\u00e8s important ; comme je le dis souvent, un compositeur qui sait ce qu\u2019il veut ne veut que ce qu\u2019il sait.<br \/>\nAvez-vous exp\u00e9riment\u00e9 ce genre de chocs quand vous avez entendu des ex\u00e9cutions de votre propre musique ?<br \/>\n\u00c0 partir du moment o\u00f9 j\u2019avais con\u00e7u la \u00ab musique concr\u00e8te instrumentale \u00bb, qui formalise la production imm\u00e9diate du son, c\u2019est-\u00e0-dire l\u2019\u00e9nergie, la force ou la douceur qu\u2019il faut mobiliser, j\u2019avais une image relativement claire des sons qui allaient r\u00e9sulter de tous ces nouveaux modes de jeu. Mais malgr\u00e9 tout, ce type de pi\u00e8ces \u2013 <em>Mouvement<\/em> par exemple \u2013, et m\u00eame celles d\u2019aujourd\u2019hui, acqui\u00e8rent souvent dans l\u2019interpr\u00e9tation une expressivit\u00e9 que je n\u2019ai pas int\u00e9gr\u00e9e par avance. Elles deviennent \u00ab symphoniques \u00bb pour ainsi dire. Je veux toujours cr\u00e9er des paysages de sons, des situations sonores qui se\u00a0transforment, et voil\u00e0 qu\u2019elles ont soudain ce caract\u00e8re \u00ab parlant \u00bb.<br \/>\n<iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/y7Gzrake8nI\" height=\"277\" width=\"492\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><br \/>\nVous avez d\u00fb affronter au d\u00e9but beaucoup de r\u00e9actions hostiles de la part de musiciens d\u2019orchestre. Est-ce que cela a chang\u00e9 avec le temps ?<br \/>\nIl subsiste toujours des r\u00e9fractaires embusqu\u00e9s \u2013 comme ces guerriers japonais qui attendent encore sur je ne sais quelle \u00eele la fin de la Seconde Guerre mondiale. Il y a toujours quelque part des premiers pupitres de contrebasse qui disent : \u00ab Non, Lachenmann, \u00e7a ne fait pas partie du r\u00e9pertoire, nous ne sommes pas dispos\u00e9s \u00e0 jouer cela. \u00bb Pour beaucoup d\u2019entre eux, les limites s\u2019arr\u00eatent \u00e0 ce que Richard Strauss a pr\u00e9vu pour leur instrument. Mais il y a, heureusement, d\u2019autres r\u00e9actions ; apr\u00e8s tout, le Philharmonique de Berlin s\u2019y est maintenant mis, et il y a \u00e9galement le r\u00f4le positif des musiciens qui jouent dans les ensembles, ce qui a produit une synergie, du moins un changement des mentalit\u00e9s. Et il y a beaucoup plus de curiosit\u00e9 parmi les jeunes.<br \/>\nReste la question du planning des r\u00e9p\u00e9titions. De fa\u00e7on g\u00e9n\u00e9rale, tout le monde pense que pendant une r\u00e9p\u00e9tition, on joue, on n\u2019apprend pas. Et je r\u00e9p\u00e8te souvent dans les conservatoires, qu\u2019au fond, la qualit\u00e9 professionnelle d\u2019un musicien se rep\u00e8re aussi dans cette capacit\u00e9 humaine et technique qui fait qu\u2019il acceptera d\u2019\u00eatre malhabile durant une r\u00e9p\u00e9tition, et donc d\u2019apprendre encore. Pour jouer des oeuvres de Wolfgang Rihm, cela n\u2019est bien s\u00fbr pas n\u00e9cessaire, mais pour rendre par exemple toute la brillance de la musique de Salvatore Sciarrino, il faut que les r\u00e9flexes corporels y soient. Ne parlons pas\u00a0des \u00c9tats-Unis, o\u00f9 les orchestres r\u00e9p\u00e8tent beaucoup moins encore. Des r\u00e9p\u00e9titions partielles, par groupes, comme je les r\u00e9clame depuis toujours, sont impossibles.<br \/>\nEst-ce que vous reliez toujours la notion de \u00ab musique concr\u00e8te instrumentale \u00bb \u00e0 vos oeuvres r\u00e9centes ?<br \/>\nJ\u2019ai en fait retrouv\u00e9 le son \u00ab philharmonique \u00bb, je l\u2019ai int\u00e9gr\u00e9 dans mon arsenal, et cela d\u00e8s <em>Allegro sostenuto<\/em>. Dans <em>Concertini<\/em> ou le troisi\u00e8me <em>Quatuor<\/em>, on trouve m\u00eame des figures presque virtuoses, enlev\u00e9es. Mais l\u2019id\u00e9e de d\u00e9part demeure : c\u2019est une musique qui part de l\u2019interrogation du geste et de l\u2019\u00e9nergie. Un tr\u00e9molo est lui aussi une situation \u00e9nerg\u00e9tique, ou bien le vibrato, ou le glissando. J\u2019ai donc interrog\u00e9 ces mod\u00e8les ou figures tr\u00e8s traditionnelles sous le rapport de l\u2019\u00e9nergie ; quand huit cors tiennent un long accord dans un adagio de Bruckner, l\u2019auditeur re\u00e7oit aussi l\u2019impression d\u2019un immense poumon\u2026<br \/>\nUn des premiers r\u00e9sultats aura \u00e9t\u00e9 <em>Allegro sostenuto<\/em>, dont certaines sections abordent par exemple sur ce qui arrive \u00e0 la musique quand on l\u2019acc\u00e9l\u00e8re, quand on la d\u00e9cha\u00eene. Il ne s\u2019agit donc pas de d\u00e9naturer mais de d\u00e9familiariser en cr\u00e9ant des contextes nouveaux ; non pas de collectionner des sons \u00e9tranges, mais d\u2019inscrire tout un arsenal dans cette \u00ab philosophie \u00bb du concret.<br \/>\n<iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/b5r-jDxh7DI\" height=\"369\" width=\"492\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><br \/>\nPhotos : (c) Philippe Gontier<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec Helmut Lachenmann il faut s\u2019attendre \u00e0 une r\u00e9vision lucide de tout le r\u00e8gne musical\u00a0: depuis la production m\u00eame des sons \u00a0au protocole du concert lui-m\u00eame, comme dans ces\u00a0Concertini (2005) au programme de la soir\u00e9e du 17 octobre prochain \u00e0 la Cit\u00e9 de la musique. Cet entretien au long cours nous \u00e9claire sur le parcours singulier d\u2019un immense explorateur de la mati\u00e8re sonore.<\/p>\n","protected":false},"author":7,"featured_media":7358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[110],"class_list":["post-7322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-helmut-lachenmann"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mati\u00e8res sonores. Grand entretien avec Helmut Lachenmann, compositeur - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mati\u00e8res sonores. Grand entretien avec Helmut Lachenmann, compositeur - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"Avec Helmut Lachenmann il faut s\u2019attendre \u00e0 une r\u00e9vision lucide de tout le r\u00e8gne musical\u00a0: depuis la production m\u00eame des sons \u00a0au protocole du concert lui-m\u00eame, comme dans ces\u00a0Concertini (2005) au programme de la soir\u00e9e du 17 octobre prochain \u00e0 la Cit\u00e9 de la musique. Cet entretien au long cours nous \u00e9claire sur le parcours singulier d\u2019un immense explorateur de la mati\u00e8re sonore.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-30T15:45:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/09\/Lachenmann_908618_04_une.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"464\" \/>\n\t<meta property=\"og:image:height\" content=\"237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Kaltenecker\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Kaltenecker\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2014\\\/09\\\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2014\\\/09\\\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\\\/\"},\"author\":{\"name\":\"Martin Kaltenecker\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/e955adbc5d659a58842a64663c50f640\"},\"headline\":\"Mati\u00e8res sonores. Grand entretien avec Helmut Lachenmann, compositeur\",\"datePublished\":\"2014-09-30T15:45:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2014\\\/09\\\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\\\/\"},\"wordCount\":1417,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2014\\\/09\\\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2014\\\/09\\\/Lachenmann_908618_04_une.jpg\",\"keywords\":[\"helmut lachenmann\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2014\\\/09\\\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2014\\\/09\\\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\\\/\",\"name\":\"Mati\u00e8res sonores. Grand entretien avec Helmut Lachenmann, compositeur - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2014\\\/09\\\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2014\\\/09\\\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2014\\\/09\\\/Lachenmann_908618_04_une.jpg\",\"datePublished\":\"2014-09-30T15:45:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/e955adbc5d659a58842a64663c50f640\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2014\\\/09\\\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2014\\\/09\\\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2014\\\/09\\\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2014\\\/09\\\/Lachenmann_908618_04_une.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2014\\\/09\\\/Lachenmann_908618_04_une.jpg\",\"width\":464,\"height\":237},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2014\\\/09\\\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mati\u00e8res sonores. Grand entretien avec Helmut Lachenmann, compositeur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/e955adbc5d659a58842a64663c50f640\",\"name\":\"Martin Kaltenecker\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e6f12788318d35597c4c3b10d5956317752761a0767bb1b7214f33fcb3f804a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e6f12788318d35597c4c3b10d5956317752761a0767bb1b7214f33fcb3f804a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e6f12788318d35597c4c3b10d5956317752761a0767bb1b7214f33fcb3f804a?s=96&d=mm&r=g\",\"caption\":\"Martin Kaltenecker\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/author\\\/martin-kaltenecker\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mati\u00e8res sonores. Grand entretien avec Helmut Lachenmann, compositeur - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/","og_locale":"en_US","og_type":"article","og_title":"Mati\u00e8res sonores. Grand entretien avec Helmut Lachenmann, compositeur - Ensemble intercontemporain","og_description":"Avec Helmut Lachenmann il faut s\u2019attendre \u00e0 une r\u00e9vision lucide de tout le r\u00e8gne musical\u00a0: depuis la production m\u00eame des sons \u00a0au protocole du concert lui-m\u00eame, comme dans ces\u00a0Concertini (2005) au programme de la soir\u00e9e du 17 octobre prochain \u00e0 la Cit\u00e9 de la musique. Cet entretien au long cours nous \u00e9claire sur le parcours singulier d\u2019un immense explorateur de la mati\u00e8re sonore.","og_url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2014-09-30T15:45:44+00:00","og_image":[{"width":464,"height":237,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/09\/Lachenmann_908618_04_une.jpg","type":"image\/jpeg"}],"author":"Martin Kaltenecker","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Martin Kaltenecker","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/"},"author":{"name":"Martin Kaltenecker","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/e955adbc5d659a58842a64663c50f640"},"headline":"Mati\u00e8res sonores. Grand entretien avec Helmut Lachenmann, compositeur","datePublished":"2014-09-30T15:45:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/"},"wordCount":1417,"commentCount":0,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/09\/Lachenmann_908618_04_une.jpg","keywords":["helmut lachenmann"],"articleSection":["Entretien"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/","url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/","name":"Mati\u00e8res sonores. Grand entretien avec Helmut Lachenmann, compositeur - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/09\/Lachenmann_908618_04_une.jpg","datePublished":"2014-09-30T15:45:44+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/e955adbc5d659a58842a64663c50f640"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/09\/Lachenmann_908618_04_une.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/09\/Lachenmann_908618_04_une.jpg","width":464,"height":237},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2014\/09\/matieres-sonores-entretien-avec-helmut-lachenmann-compositeur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/en\/"},{"@type":"ListItem","position":2,"name":"Mati\u00e8res sonores. Grand entretien avec Helmut Lachenmann, compositeur"}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/e955adbc5d659a58842a64663c50f640","name":"Martin Kaltenecker","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/5e6f12788318d35597c4c3b10d5956317752761a0767bb1b7214f33fcb3f804a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e6f12788318d35597c4c3b10d5956317752761a0767bb1b7214f33fcb3f804a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e6f12788318d35597c4c3b10d5956317752761a0767bb1b7214f33fcb3f804a?s=96&d=mm&r=g","caption":"Martin Kaltenecker"},"url":"https:\/\/www.ensembleintercontemporain.com\/en\/author\/martin-kaltenecker\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/7322\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/users\/7\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/comments\/?post=7322"}],"version-history":[{"count":0,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/7322\/revisions\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/7358\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/?parent=7322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/categories\/?post=7322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/tags\/?post=7322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}