{"id":7106,"date":"2014-07-04T11:12:12","date_gmt":"2014-07-04T09:12:12","guid":{"rendered":"http:\/\/www.ensembleinter.com\/accents-online\/?p=7106"},"modified":"2014-07-04T11:12:12","modified_gmt":"2014-07-04T09:12:12","slug":"retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/","title":{"rendered":"Retour sur la saison 2013-14 : le regard de Gr\u00e9goire Simon, altiste"},"content":{"rendered":"<p><span style=\"font-size: large;\"><a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2014\/07\/1-.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7107\" alt=\"1-\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2014\/07\/1-.jpg\" width=\"492\" height=\"581\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/1-.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/1--254x300.jpg 254w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><\/span><br \/>\n<span style=\"font-size: large;\">T<\/span>ous les regards se tournent d\u00e9j\u00e0 vers <a href=\"http:\/\/issuu.com\/ensembleinter\/docs\/bs1415\/1\">\u00a0la nouvelle saison \u00a02014-15 <\/a>ce qui n&#8217;est pas une raison pour tirer un trait sur celle encore en cours et qui se terminera officiellement le <a href=\"http:\/\/www.ensembleinter.com\/fr\/concert-765-Concert-de-l'acad%C3%A9mie-du-festival-ManiFeste.html\">10 juillet prochain<\/a> avec un dernier concert. \u00a0 Nous avons donc demand\u00e9 \u00e0 quatre solistes ( Gr\u00e9goire Simon, Fr\u00e9d\u00e9rique Cambreling, Emmanuelle Oph\u00e8le, Victor Hanna) et \u00e0 Matthias Pintscher, le directeur musical de l&#8217;Ensemble, de partager avec nous leur regard sur la saison 2013-14. On commence avec <strong>Gr\u00e9goire Simon<\/strong>, altiste, qui r\u00e9pond \u00e0 quatre questions.<br \/>\n<strong>Gr\u00e9goire, quels ont \u00e9t\u00e9 pour vous les temps forts de la saison 2013-14 ?<\/strong><br \/>\nTout d\u2019abord, les trois<strong> <a href=\"http:\/\/www.weekendturbulences.com\/\">week-ends Turbulences<\/a><\/strong>\u00a0: ceux-ci nous ont donn\u00e9s l\u2019occasion de jouer des pi\u00e8ces que nous interpr\u00e9tons tr\u00e8s rarement, et d\u2019\u00e9largir la programmation, en m\u00ealant des pi\u00e8ces anciennes \u00e0 notre r\u00e9pertoire, avec des contrastes, qu\u2019on ne peut pas toujours obtenir au sein d\u2019un format de concert plus court. J\u2019ai \u00e9galement beaucoup appr\u00e9ci\u00e9 tout ce qui se passait au cours des entractes durant lesquels \u00e9taient jou\u00e9es des pi\u00e8ces qui ne sont pas forc\u00e9ment pens\u00e9es pour \u00eatre interpr\u00e9t\u00e9es sur sc\u00e8ne, de fa\u00e7on frontale, et qui cr\u00e9ent ainsi des ambiances singuli\u00e8res.<br \/>\nEt puis je retiendrai aussi le cycle des<strong><em> Espaces Acoustiques<\/em> <\/strong>de G\u00e9rard Grisey (photo ci-dessous), sans doute parce que j\u2019y ai jou\u00e9 un r\u00f4le central. C\u2019est une \u0153uvre forte et unique. Le public a en outre r\u00e9pondu pr\u00e9sent et j\u2019ai ressenti des vibrations particuli\u00e8res dans la salle.<br \/>\n<strong><a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2014\/07\/3-.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7108\" alt=\"3-\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2014\/07\/3-.jpg\" width=\"492\" height=\"327\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/3-.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/3--300x199.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><\/strong><br \/>\n<strong>Apr\u00e8s une saison, quel regard portez-vous sur l\u2019arriv\u00e9e de Matthias Pintscher \u00e0 la t\u00eate de l\u2019Ensemble ?<\/strong><br \/>\nC\u2019est un chef qui joue et compose, et j\u2019ai l\u2019impression que \u00e7a se ressent lorsqu\u2019il dirige\u00a0: il d\u00e9gage sur sc\u00e8ne une esp\u00e8ce de d\u00e9contraction \u00e9tonnante et rare, que ce soit par sa gestuelle, ou tout simplement par son attitude face aux musiciens. Je pense que \u00e7a nous donne beaucoup de souplesse dans le jeu et dans l\u2019interpr\u00e9tation. Son \u00e9coute, ses gestes font passer \u00e9norm\u00e9ment d\u2019informations et d\u2019affects.<br \/>\nEt puis, avec lui, nous avons pu jouer du Mahler et du Wagner. Si Matthias Pintscher dit beaucoup aimer la tradition fran\u00e7aise, la tradition allemande est \u00e0 mon avis bien ancr\u00e9e en lui. Ce point de vue est peut-\u00eatre celui d\u2019un musicien \u00e0 cordes, mais j\u2019ai le sentiment qu\u2019il oriente le travail sonore\u00a0: il aime la masse orchestrale, et il aime les sons pleins et riches qui peuvent parfois se perdre en musique contemporaine, o\u00f9 la concentration porte davantage sur la pr\u00e9cision et les attaques. Lui se bat aussi pour la sensualit\u00e9 du son et ceci est tr\u00e8s b\u00e9n\u00e9fique pour le son de l\u2019ensemble, qui n\u2019en perd pas pour autant sa clart\u00e9 et son identit\u00e9.<br \/>\n<strong>Parmi tous les projets pluridisciplinaires lesquels vous ont le plus marqu\u00e9 ?<\/strong><br \/>\nJ\u2019ai beaucoup aim\u00e9 <em><strong>Le Voyage d&#8217;hiver<\/strong> <\/em>(photo ci-dessous), notamment parce que l\u2019interpr\u00e9tation est magnifique et que les compositions de Mark Andre sont tr\u00e8s r\u00e9ussies, d\u2019une finesse remarquable \u2013 et ce n\u2019\u00e9tait pas un mince d\u00e9fi que de se confronter \u00e0 un tel monument, aussi intime soit-il. La mise en sc\u00e8ne \u00e9tait tr\u00e8s l\u00e9g\u00e8re, parvenant \u00e0 cr\u00e9er une dimension spectaculaire avec une grande \u00e9conomie de moyens\u00a0: c\u2019\u00e9tait tr\u00e8s envoutant.<br \/>\nQuant \u00e0 moi, j\u2019ai particip\u00e9 pour la premi\u00e8re fois aux<strong> Intersessions au Triton<\/strong>, des rencontres crois\u00e9es entre les solistes de l\u2019Ensemble et les musiciens issus des musiques improvis\u00e9es. C\u2019est une approche totalement diff\u00e9rente du concert ou de la sc\u00e8ne. Nous avons beaucoup de chance que l\u2019Ensemble nous offre ces possibilit\u00e9s .<br \/>\n<strong><a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2014\/07\/4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7109\" alt=\"4\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2014\/07\/4.jpg\" width=\"492\" height=\"328\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/4.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/4-300x200.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><\/strong><br \/>\n<strong>Quels sont pour vous les grands rendez-vous de la saison 2014-15 ?<\/strong><br \/>\nJe suis tr\u00e8s curieux des deux jours de <a href=\"http:\/\/www.ensembleinter.com\/fr\/concert-770-Turbulences-%E2%80%93-Clair-Obscur,-avec-Marco-Nikodijevic-1-2.html\">nouvelles Turbulences pilot\u00e9s par Marko Nikodijevic<\/a>. C\u2019est un musicien unique qui a ressenti, d\u00e8s le d\u00e9but, la n\u00e9cessit\u00e9 de faire autrement et qui est arriv\u00e9 avec des id\u00e9es tr\u00e8s originales comme m\u00ealer Gesualdo, Vivier et la musique \u00e9lectronique, ou animer les entractes d\u2019improvisations \u00e9lectroniques. Le travail avec lui est tr\u00e8s agr\u00e9able\u00a0: il vient avec une proposition g\u00e9n\u00e9ralement tr\u00e8s claire \u00e0 laquelle on peut r\u00e9agir pour faire des propositions\u00a0; tout se d\u00e9roule ainsi, en aller et retour, de mani\u00e8re tr\u00e8s organique. \u00c7a va \u00eatre un week-end un peu ambiant, tr\u00e8s diff\u00e9rent de la programmation habituelle.<br \/>\nUn <a href=\"http:\/\/www.ensembleinter.com\/fr\/concert-789-Week-end-Pierre-Boulez-1-3.html\">week-end entier \u00a0sera consacr\u00e9 \u00e0 Pierre Boulez<\/a>, sous un angle in\u00e9dit, et comprendra l\u00e0 encore un programme vaste et contrast\u00e9, avec notamment les ballets de Maurice B\u00e9jart et une grande soir\u00e9e avec l\u2019Ensemble qui interpr\u00e9tera entre autre \u2026<em>explosante-fixe<\/em>\u2026 \u00a0Je suis \u00e9galement tr\u00e8s curieux d\u2019entendre le groupe de free jazz invit\u00e9 pour venir jouer en milieu de soir\u00e9e\u00a0: c\u2019est un groupe appel\u00e9 Die Hochstapler, qui signifie \u00ab\u00a0les faussaires\u00a0\u00bb ou \u00ab\u00a0les imposteurs\u00a0\u00bb. Ils travaillent habituellement sur Anthony Braxton et Ornette Coleman, volant leurs compositions pour faire les leurs \u2013 ils reproduiront pour nous la m\u00eame d\u00e9marche en partant d\u2019\u0153uvres de Pierre Boulez ou de John Cage. Ce sera tr\u00e8s excitant d\u2019entendre tout cela dans le m\u00eame concert.<br \/>\n<a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2014\/07\/2-.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7110\" alt=\"2-\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2014\/07\/2-.jpg\" width=\"492\" height=\"327\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/2-.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/2--300x199.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\nPhotos : portrait (c) Franck Ferville \/ autres photos : (c) Luc Hossepied pour l&#8217;Ensemble intercontemporain<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tous les regards se tournent d\u00e9j\u00e0 vers \u00a0<a href=\"http:\/\/issuu.com\/ensembleinter\/docs\/bs1415\/1\">la nouvelle saison \u00a02014-1<\/a>5 \u00a0ce qui n&#8217;est pas une raison pour tirer un trait sur celle encore en cours. \u00a0 Nous avons donc demand\u00e9 \u00e0 quatre solistes (Gr\u00e9goire Simon, Fr\u00e9d\u00e9rique Cambreling, Emmanuelle Oph\u00e8le, Victor Hanna) et \u00e0 Matthias Pintscher, le directeur musical de l&#8217;Ensemble, de partager avec nous leur regard sur la saison 2013-14. On commence avec\u00a0<strong>Gr\u00e9goire Simon<\/strong>, altiste, qui r\u00e9pond \u00e0 quatre questions.<\/p>\n","protected":false},"author":5,"featured_media":7111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[570,613,561,563],"class_list":["post-7106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-gregoire-simon","tag-le-voyage-dhiver","tag-saison-2013-14","tag-week-end-turbulences"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retour sur la saison 2013-14 : le regard de Gr\u00e9goire Simon, altiste - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retour sur la saison 2013-14 : le regard de Gr\u00e9goire Simon, altiste - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"Tous les regards se tournent d\u00e9j\u00e0 vers \u00a0la nouvelle saison \u00a02014-15 \u00a0ce qui n&#039;est pas une raison pour tirer un trait sur celle encore en cours. \u00a0 Nous avons donc demand\u00e9 \u00e0 quatre solistes (Gr\u00e9goire Simon, Fr\u00e9d\u00e9rique Cambreling, Emmanuelle Oph\u00e8le, Victor Hanna) et \u00e0 Matthias Pintscher, le directeur musical de l&#039;Ensemble, de partager avec nous leur regard sur la saison 2013-14. On commence avec\u00a0Gr\u00e9goire Simon, altiste, qui r\u00e9pond \u00e0 quatre questions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-04T09:12:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/DSC_6061-Une.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"464\" \/>\n\t<meta property=\"og:image:height\" content=\"237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\u00e9remie Szpirglas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00e9remie Szpirglas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/07\\\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/07\\\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\\\/\"},\"author\":{\"name\":\"J\u00e9remie Szpirglas\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/439a7dd5cd8a167c34c931d7cc900214\"},\"headline\":\"Retour sur la saison 2013-14 : le regard de Gr\u00e9goire Simon, altiste\",\"datePublished\":\"2014-07-04T09:12:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/07\\\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\\\/\"},\"wordCount\":932,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/07\\\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2014\\\/07\\\/DSC_6061-Une.jpg\",\"keywords\":[\"gr\u00e9goire simon\",\"Le voyage d'hiver\",\"saison 2013-14\",\"week-end Turbulences\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/07\\\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/07\\\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\\\/\",\"name\":\"Retour sur la saison 2013-14 : le regard de Gr\u00e9goire Simon, altiste - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/07\\\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/07\\\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2014\\\/07\\\/DSC_6061-Une.jpg\",\"datePublished\":\"2014-07-04T09:12:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/439a7dd5cd8a167c34c931d7cc900214\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/07\\\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/07\\\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/07\\\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2014\\\/07\\\/DSC_6061-Une.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2014\\\/07\\\/DSC_6061-Une.jpg\",\"width\":464,\"height\":237},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/07\\\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retour sur la saison 2013-14 : le regard de Gr\u00e9goire Simon, altiste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/439a7dd5cd8a167c34c931d7cc900214\",\"name\":\"J\u00e9remie Szpirglas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g\",\"caption\":\"J\u00e9remie Szpirglas\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/author\\\/benjamin-szpirglas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retour sur la saison 2013-14 : le regard de Gr\u00e9goire Simon, altiste - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/","og_locale":"en_US","og_type":"article","og_title":"Retour sur la saison 2013-14 : le regard de Gr\u00e9goire Simon, altiste - Ensemble intercontemporain","og_description":"Tous les regards se tournent d\u00e9j\u00e0 vers \u00a0la nouvelle saison \u00a02014-15 \u00a0ce qui n'est pas une raison pour tirer un trait sur celle encore en cours. \u00a0 Nous avons donc demand\u00e9 \u00e0 quatre solistes (Gr\u00e9goire Simon, Fr\u00e9d\u00e9rique Cambreling, Emmanuelle Oph\u00e8le, Victor Hanna) et \u00e0 Matthias Pintscher, le directeur musical de l'Ensemble, de partager avec nous leur regard sur la saison 2013-14. On commence avec\u00a0Gr\u00e9goire Simon, altiste, qui r\u00e9pond \u00e0 quatre questions.","og_url":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2014-07-04T09:12:12+00:00","og_image":[{"width":464,"height":237,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/DSC_6061-Une.jpg","type":"image\/jpeg"}],"author":"J\u00e9remie Szpirglas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"J\u00e9remie Szpirglas","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/"},"author":{"name":"J\u00e9remie Szpirglas","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/439a7dd5cd8a167c34c931d7cc900214"},"headline":"Retour sur la saison 2013-14 : le regard de Gr\u00e9goire Simon, altiste","datePublished":"2014-07-04T09:12:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/"},"wordCount":932,"commentCount":0,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/DSC_6061-Une.jpg","keywords":["gr\u00e9goire simon","Le voyage d'hiver","saison 2013-14","week-end Turbulences"],"articleSection":["Entretien"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/","url":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/","name":"Retour sur la saison 2013-14 : le regard de Gr\u00e9goire Simon, altiste - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/DSC_6061-Une.jpg","datePublished":"2014-07-04T09:12:12+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/439a7dd5cd8a167c34c931d7cc900214"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/DSC_6061-Une.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/07\/DSC_6061-Une.jpg","width":464,"height":237},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/07\/retour-sur-la-saison-2013-14-le-regard-de-gregoire-simon-altiste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/en\/"},{"@type":"ListItem","position":2,"name":"Retour sur la saison 2013-14 : le regard de Gr\u00e9goire Simon, altiste"}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/439a7dd5cd8a167c34c931d7cc900214","name":"J\u00e9remie Szpirglas","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g","caption":"J\u00e9remie Szpirglas"},"url":"https:\/\/www.ensembleintercontemporain.com\/en\/author\/benjamin-szpirglas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/7106\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/users\/5\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/comments\/?post=7106"}],"version-history":[{"count":0,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/7106\/revisions\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/7111\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/?parent=7106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/categories\/?post=7106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/tags\/?post=7106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}