{"id":6831,"date":"2014-03-28T19:00:56","date_gmt":"2014-03-28T17:00:56","guid":{"rendered":"http:\/\/www.ensembleinter.com\/accents-online\/?p=6831"},"modified":"2014-03-28T19:00:56","modified_gmt":"2014-03-28T17:00:56","slug":"entretien-avec-johannes-boris-borowski-compositeur","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/","title":{"rendered":"Entretien avec Johannes Boris Borowski, compositeur"},"content":{"rendered":"<p><a href=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2014\/04\/Borowski_Johannes_Boris_c_Priska_Ketterer.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6832\" alt=\"Borowski_Johannes_Boris_c_Priska_Ketterer\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2014\/04\/Borowski_Johannes_Boris_c_Priska_Ketterer.jpg\" width=\"492\" height=\"739\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/04\/Borowski_Johannes_Boris_c_Priska_Ketterer.jpg 492w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/04\/Borowski_Johannes_Boris_c_Priska_Ketterer-200x300.jpg 200w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/a><br \/>\n<a href=\"http:\/\/www.weekendturbulences.com\/presentation-du-week-end-air-libre\/\">Le 12 avril prochain, dans le cadre du week-end Turbulences <\/a>pilot\u00e9 par Bruno Mantovani, le jeune compositeur allemand Johannes Boris Borowski pr\u00e9sentera en cr\u00e9ation mondiale son <i>Concerto pour basson<\/i>, commande de l&#8217;Ensemble intercontemporain. Il nous parle de cette \u0153uvre qui s&#8217;inscrira dans la th\u00e9matique g\u00e9n\u00e9rale de ce week-end : le rapport entre l&#8217;individu et le collectif.<br \/>\n<b>Si l\u2019on met de c\u00f4t\u00e9 les pi\u00e8ces pour orchestre, vous n\u2019avez pas \u00e9crit pour le basson avant votre <i>Concerto<\/i>. Comment est n\u00e9e l\u2019id\u00e9e d\u2019\u00e9crire pour cet instrument et que repr\u00e9sente-t-il pour vous ?\u00a0 <\/b><br \/>\nCe n\u2019est pas l\u2019id\u00e9e d\u2019\u00e9crire un concerto pour basson qui est venue en premier, mais le d\u00e9sir d\u2019\u00e9crire une pi\u00e8ce pour Pascal Gallois et l\u2019Ensemble intercontemporain. Ce n\u2019est donc pas l\u2019instrument en lui-m\u00eame, mais la relation personnelle qui m\u2019a amen\u00e9 \u00e0 d\u00e9couvrir le basson, la richesse de ses possibilit\u00e9s sonores, la vari\u00e9t\u00e9 de ses techniques de jeu, etc. Le basson est l\u2019un des instruments les plus int\u00e9ressants de la famille des bois. Si on veut bien le lib\u00e9rer des images et des clich\u00e9s traditionnels, il devient tout \u00e0 coup quelque chose de diff\u00e9rent et d\u2019\u00e9trange. C\u2019est souvent cela qui m&#8217;int\u00e9resse et guide mon travail : l&#8217;exp\u00e9rience de l&#8217;\u00e9tranget\u00e9, ce qui la provoque et ce qui en r\u00e9sulte.<br \/>\nJ\u2019ai rencontr\u00e9 Pascal Gallois \u00e0 plusieurs reprises, pour lui faire part de mes id\u00e9es et pour trouver l\u2019inspiration. J&#8217;ai pr\u00e9f\u00e9rer n\u00e9anmoins rester \u00e0 distance, parce que je voulais l\u2019amener vers quelque chose d\u2019inhabituel, qui ne fasse pas encore partie de son r\u00e9pertoire. Ce travail implique non seulement de trouver de nouvelles techniques et de nouveaux sons, mais de cr\u00e9er des situations in\u00e9dites, y compris en employant les techniques communes. Par exemple, le son \u201cordinaire\u201d de l\u2019instrument peut sonner de fa\u00e7on inattendue s\u2019il est plac\u00e9 dans un environnement \u00e9trange.<br \/>\n<b>Comment d\u00e9cririez-vous la relation soliste \/ ensemble mise en place dans votre concerto ? Est-ce que l\u2019ensemble ne devient pas lui aussi soliste ? <\/b><br \/>\nCe qui a \u00e9t\u00e9 d\u00e9cisif pour moi c\u2019est de r\u00e9aliser qu\u2019il y aurait un soliste sur sc\u00e8ne devant un ensemble, mais un ensemble constitu\u00e9 uniquement de solistes. Cette pr\u00e9occupation se refl\u00e8te d\u00e8s les premi\u00e8res mesures de la partition, lorsque le basson solo dialogue avec le basson de l\u2019ensemble. D\u2019un point de vue musical, ce sont tous les deux des solistes. La diff\u00e9rence est d\u2019ordre externe, dramaturgique, elle ne fait pas encore partie de la structure musicale.<br \/>\nDans le dernier mouvement, tandis que l\u2019ensemble d\u00e9veloppe une texture proprement orchestrale \u2013\u00a0d\u00e9j\u00e0 annonc\u00e9e auparavant \u2013, le soliste reste silencieux. Il reste toutefois pr\u00e9sent, physiquement, toujours face \u00e0 l\u2019ensemble. Ce genre de petite \u201cprovocation\u201d met au jour la monumentalit\u00e9 qui est tr\u00e8s souvent th\u00e9matis\u00e9e dans les concertos pour solistes. Ce qui m\u2019int\u00e9resse dans la monumentalit\u00e9, ce n\u2019est pas qu\u2019elle mette en jeu quelque chose d\u2019immense, mais plut\u00f4t qu\u2019elle engage une relation \u00e0 la perspective, qu\u2019elle permet de basculer d\u2019un niveau cognitif \u00e0 un autre, voire de prendre le risque de perdre ses rep\u00e8res et d\u2019en tirer de nouvelles exp\u00e9riences.<br \/>\nToutes ces questions sur la relation soliste \/ ensemble sont tr\u00e8s proches de celles qui r\u00e9gissent les relations humaines, o\u00f9 il s\u2019agit d\u2019\u00e9quilibrer les conflits entre l\u2019autonomie et l\u2019h\u00e9t\u00e9ronomie, de faire l\u2019exp\u00e9rience, tant\u00f4t douloureuse tant\u00f4t heureuse, de l&#8217;alt\u00e9rit\u00e9, et d&#8217;en tirer un enseignement personnel. Echouer ou r\u00e9ussir, ce n\u2019est pas la question. La r\u00e9ussite seule serait ennuyeuse et n\u2019apporterait aucun \u00e9panouissement.<br \/>\n<b>Dans quelle mesure votre \u0153uvre rel\u00e8ve t-elle du genre traditionnel du concerto ? La division en 5 mouvements est plut\u00f4t inhabituelle\u2026<\/b><br \/>\nDe ce point de vue, mon <i>Concerto pour basson<\/i> se distingue nettement de mon <i>Concerto pour piano<\/i> \u00e9crit en 2010-2011. En \u00e9crivant le <i>Concerto pour piano<\/i>, je ne pouvais gu\u00e8re ignorer la tradition attach\u00e9e \u00e0 ce genre et je m&#8217;en suis senti partie prenante. Je me plaisais \u00e0 travailler les liens qui me reliaient \u00e0 cette tradition, par rapport \u00e0 mon histoire : dans quelle mesure je pouvais m&#8217;y ins\u00e9rer et dans quelle mesure je pouvais la modifier \u2013\u00a0ou du moins en d\u00e9gager de nouveaux aspects.<br \/>\nPour le <i>Concerto pour basson<\/i>, je me suis d\u00e9tach\u00e9 de cette question du rapport \u00e0 la tradition. Bien s\u00fbr, la relation entre le soliste et l&#8217;ensemble (et la relation de tous les musiciens de l&#8217;ensemble, entre eux et par rapport au soliste) reste importante, mais j&#8217;avais la sensation de me situer en dehors de la tradition tr\u00e8s particuli\u00e8re du concerto pour instrument soliste. Cette \u0153uvre hybride rel\u00e8ve \u00e0 la fois du &#8220;concerto&#8221;, de la &#8220;pi\u00e8ce pour ensemble&#8221; ou de la &#8220;pi\u00e8ce pour orchestre&#8221;, avec des cadences introduisant tout \u00e0 coup des fragments de &#8220;pi\u00e8ces solistes&#8221;. Et cette \u00e9quivocit\u00e9 rejaillit bien entendu sur la forme de la pi\u00e8ce.<br \/>\nCette forme est tr\u00e8s ambig\u00fce : il y a cinq mouvements mais avec tellement de connexions et de relations entre eux que l\u2019auditeur perd tr\u00e8s rapidement le sentiment statique de la forme. D\u00e8s lors qu\u2019il est dispos\u00e9 \u00e0 suivre les indices, il peut cr\u00e9er sa propre perception de la pi\u00e8ce. Il y a beaucoup de choses \u00e0 y comprendre, mais \u00e9galement beaucoup de secrets cach\u00e9s.<br \/>\nOn retrouve ici le lien avec la vie courante et la soci\u00e9t\u00e9. En tant qu&#8217;\u00eatres humains, nous sommes constamment confront\u00e9s \u00e0 des probl\u00e8mes g\u00e9n\u00e9raux (la r\u00e9alit\u00e9, l&#8217;existence, le savoir, etc), des probl\u00e8mes que nous n&#8217;avons pas la possibilit\u00e9 de comprendre ou r\u00e9soudre enti\u00e8rement, mais que nous pouvons partiellement questionner. Il y a l\u00e0 de nombreux &#8220;secrets&#8221; que nous nous plaisons \u00e0 d\u00e9celer, \u00e0 \u00e9lucider. Ecouter de la musique ne signifie pas tout (ou rien) comprendre. Nous avons l&#8217;intuition que quelque chose se passe et nous int\u00e9resse. Si nous ne le comprenons pas tout de suite, cela devient un d\u00e9fi \u00e0 relever. En tant que compositeur, j&#8217;essaie de m\u00e9nager dans mes pi\u00e8ces la possibilit\u00e9 de d\u00e9couvrir des liens ou des connexions entre les \u00e9l\u00e9ments. Etant loin de comprendre enti\u00e8rement ce que je fais (cela me semble important), je m&#8217;efforce d&#8217;en conna\u00eetre davantage, non seulement sur la musique, mais aussi sur moi-m\u00eame, ma perception, mes relations aux autres, \u00e0 la tradition et \u00e0 l&#8217;histoire. Je dois donc me rendre actif. Et le public avec moi. Ce n&#8217;est qu&#8217;en comparant nos exp\u00e9riences \u2013 qui prennent des formes individuelles et diff\u00e9rentes en chacun de nous \u2013\u00a0que nous pouvons rendre notre vie plus riche et profonde, \u00e0 d\u00e9faut de la rendre plus facile.<br \/>\nPhoto : Priska Ketterer<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"Johannes Boris Borowski \">Le 12 avril prochain<\/a>, dans le cadre du week-end Turbulences, <em>Air libre<\/em>, le jeune compositeur allemand Johannes Boris Borowski pr\u00e9sentera en cr\u00e9ation mondiale son <i>Concerto pour basson<\/i>, commande de l&#8217;Ensemble intercontemporain. Il nous parle de cette \u0153uvre qui s&#8217;inscrira dans la th\u00e9matique g\u00e9n\u00e9rale de ce week end : le rapport entre l&#8217;individu et le collectif.<\/p>\n","protected":false},"author":3,"featured_media":6835,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[48,223,60,430,563],"class_list":["post-6831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-basson","tag-concerto","tag-creation","tag-johannes-boris-borowski","tag-week-end-turbulences"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entretien avec Johannes Boris Borowski, compositeur - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entretien avec Johannes Boris Borowski, compositeur - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"Le 12 avril prochain, dans le cadre du week-end Turbulences, Air libre, le jeune compositeur allemand Johannes Boris Borowski pr\u00e9sentera en cr\u00e9ation mondiale son Concerto pour basson, commande de l&#039;Ensemble intercontemporain. Il nous parle de cette \u0153uvre qui s&#039;inscrira dans la th\u00e9matique g\u00e9n\u00e9rale de ce week end : le rapport entre l&#039;individu et le collectif.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-28T17:00:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/04\/Borowski_Johannes_Boris_une.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"464\" \/>\n\t<meta property=\"og:image:height\" content=\"237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre-Yves Mac\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre-Yves Mac\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/03\\\/entretien-avec-johannes-boris-borowski-compositeur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/03\\\/entretien-avec-johannes-boris-borowski-compositeur\\\/\"},\"author\":{\"name\":\"Pierre-Yves Mac\u00e9\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/754ccc2c496b6cf14c499f357309c165\"},\"headline\":\"Entretien avec Johannes Boris Borowski, compositeur\",\"datePublished\":\"2014-03-28T17:00:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/03\\\/entretien-avec-johannes-boris-borowski-compositeur\\\/\"},\"wordCount\":1168,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/03\\\/entretien-avec-johannes-boris-borowski-compositeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2014\\\/04\\\/Borowski_Johannes_Boris_une.jpg\",\"keywords\":[\"basson\",\"concerto\",\"cr\u00e9ation\",\"johannes boris borowski\",\"week-end Turbulences\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/03\\\/entretien-avec-johannes-boris-borowski-compositeur\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/03\\\/entretien-avec-johannes-boris-borowski-compositeur\\\/\",\"name\":\"Entretien avec Johannes Boris Borowski, compositeur - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/03\\\/entretien-avec-johannes-boris-borowski-compositeur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/03\\\/entretien-avec-johannes-boris-borowski-compositeur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2014\\\/04\\\/Borowski_Johannes_Boris_une.jpg\",\"datePublished\":\"2014-03-28T17:00:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/754ccc2c496b6cf14c499f357309c165\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/03\\\/entretien-avec-johannes-boris-borowski-compositeur\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/03\\\/entretien-avec-johannes-boris-borowski-compositeur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/03\\\/entretien-avec-johannes-boris-borowski-compositeur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2014\\\/04\\\/Borowski_Johannes_Boris_une.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2014\\\/04\\\/Borowski_Johannes_Boris_une.jpg\",\"width\":464,\"height\":237},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2014\\\/03\\\/entretien-avec-johannes-boris-borowski-compositeur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entretien avec Johannes Boris Borowski, compositeur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/754ccc2c496b6cf14c499f357309c165\",\"name\":\"Pierre-Yves Mac\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd5799e807a5fe5720815fa08f8b5bcc34742b1159fd1b7ef299ba57b1f2490a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd5799e807a5fe5720815fa08f8b5bcc34742b1159fd1b7ef299ba57b1f2490a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd5799e807a5fe5720815fa08f8b5bcc34742b1159fd1b7ef299ba57b1f2490a?s=96&d=mm&r=g\",\"caption\":\"Pierre-Yves Mac\u00e9\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/author\\\/pierre-yves-mace\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entretien avec Johannes Boris Borowski, compositeur - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/","og_locale":"en_US","og_type":"article","og_title":"Entretien avec Johannes Boris Borowski, compositeur - Ensemble intercontemporain","og_description":"Le 12 avril prochain, dans le cadre du week-end Turbulences, Air libre, le jeune compositeur allemand Johannes Boris Borowski pr\u00e9sentera en cr\u00e9ation mondiale son Concerto pour basson, commande de l'Ensemble intercontemporain. Il nous parle de cette \u0153uvre qui s'inscrira dans la th\u00e9matique g\u00e9n\u00e9rale de ce week end : le rapport entre l'individu et le collectif.","og_url":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2014-03-28T17:00:56+00:00","og_image":[{"width":464,"height":237,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/04\/Borowski_Johannes_Boris_une.jpg","type":"image\/jpeg"}],"author":"Pierre-Yves Mac\u00e9","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pierre-Yves Mac\u00e9","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/"},"author":{"name":"Pierre-Yves Mac\u00e9","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/754ccc2c496b6cf14c499f357309c165"},"headline":"Entretien avec Johannes Boris Borowski, compositeur","datePublished":"2014-03-28T17:00:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/"},"wordCount":1168,"commentCount":0,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/04\/Borowski_Johannes_Boris_une.jpg","keywords":["basson","concerto","cr\u00e9ation","johannes boris borowski","week-end Turbulences"],"articleSection":["Entretien"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/","url":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/","name":"Entretien avec Johannes Boris Borowski, compositeur - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/04\/Borowski_Johannes_Boris_une.jpg","datePublished":"2014-03-28T17:00:56+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/754ccc2c496b6cf14c499f357309c165"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/04\/Borowski_Johannes_Boris_une.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2014\/04\/Borowski_Johannes_Boris_une.jpg","width":464,"height":237},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2014\/03\/entretien-avec-johannes-boris-borowski-compositeur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/en\/"},{"@type":"ListItem","position":2,"name":"Entretien avec Johannes Boris Borowski, compositeur"}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/754ccc2c496b6cf14c499f357309c165","name":"Pierre-Yves Mac\u00e9","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/bd5799e807a5fe5720815fa08f8b5bcc34742b1159fd1b7ef299ba57b1f2490a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bd5799e807a5fe5720815fa08f8b5bcc34742b1159fd1b7ef299ba57b1f2490a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd5799e807a5fe5720815fa08f8b5bcc34742b1159fd1b7ef299ba57b1f2490a?s=96&d=mm&r=g","caption":"Pierre-Yves Mac\u00e9"},"url":"https:\/\/www.ensembleintercontemporain.com\/en\/author\/pierre-yves-mace\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/6831\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/users\/3\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/comments\/?post=6831"}],"version-history":[{"count":0,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/6831\/revisions\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/6835\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/?parent=6831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/categories\/?post=6831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/tags\/?post=6831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}