{"id":29855,"date":"2025-10-31T14:14:27","date_gmt":"2025-10-31T13:14:27","guid":{"rendered":"https:\/\/www.ensembleintercontemporain.com\/?p=29855"},"modified":"2025-11-05T12:05:19","modified_gmt":"2025-11-05T11:05:19","slug":"conferer-a-orgia-une-tonalite-ancestrale","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/","title":{"rendered":"\u2009H\u00e8ctor Parra : conf\u00e9rer \u00e0 &#8220;Orgia&#8221; une tonalit\u00e9 ancestrale.\u2009"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29856\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-scaled.jpg 2560w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-300x200.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-1024x683.jpg 1024w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-768x512.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-1536x1024.jpg 1536w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p><strong><span style=\"font-size: 12pt;\"><span style=\"color: #003366;\"><span style=\"font-size: 18pt;\">L<\/span>&#8216;op\u00e9ra <em>Orgia<\/em> d\u2019H\u00e8ctor Parra s\u2019impose comme une rencontre saisissante entre la radicalit\u00e9 po\u00e9tique de Pier Paolo Pasolini et la modernit\u00e9 lyrique du compositeur catalan. Adapt\u00e9 de la \u00a0pi\u00e8ce de th\u00e9\u00e2tre de Pasolini \u00e9crite en 1968, <em>Orgia<\/em> plonge dans l\u2019intimit\u00e9 d\u2019un huis clos o\u00f9 la violence des rapports humains, la question du mal et la monstruosit\u00e9 sont expos\u00e9es sans fard, dans une soci\u00e9t\u00e9 que Pasolini juge d\u00e9shumanis\u00e9e par le consum\u00e9risme et les r\u00e9surgences du fascisme. H\u00e8ctor Parra revient sur son int\u00e9r\u00eat pour ce texte f\u00e9roce et les enjeux de son adaptation pour l\u2019op\u00e9ra, qui sera mis en sc\u00e8ne \u00e0 la Cit\u00e9 de la musique <a href=\"https:\/\/www.ensembleintercontemporain.com\/fr\/concert\/eic-friends-orgia-2025-11-22-20h00-paris\/\">le 22 novembre<\/a> par Calixto Bieito.<\/span><\/span><\/strong><\/p>\n<p><strong>H\u00e8ctor<span style=\"font-size: medium;\">, qu\u2019est-ce qui vous a si sp\u00e9cialement attir\u00e9 dans <\/span><em style=\"font-size: 12pt;\">Orgia<\/em><span style=\"font-size: medium;\">\u2009? <\/span><\/strong><br \/>\n<span style=\"font-size: 14pt;\">J\u2019ai d\u00e9couvert <em>Orgia<\/em> en 2010 et je suis imm\u00e9diatement tomb\u00e9 amoureux de ce texte troublant qui m\u00e9lange la po\u00e9sie la plus sublime avec le constat tragique de l\u2019impossibilit\u00e9 de vivre une vie honn\u00eate, pleine et profonde, immerg\u00e9s que nous sommes dans le consum\u00e9risme n\u00e9o-capitaliste qui nous noie dans la m\u00e9diocrit\u00e9. En 2015, nous avons commenc\u00e9 \u00e0 discuter avec Calixto Bieito de la possibilit\u00e9 de transformer <em>Orgia<\/em> en op\u00e9ra. Au d\u00e9part, nous avions discut\u00e9 des r\u00e9sonances que le texte de Pasolini a avec celui de la <em>Passion du Christ<\/em>, et plus particuli\u00e8rement celle de Saint-Jean. Cela m\u2019avait conduit peu apr\u00e8s \u00e0 composer une \u0153uvre orchestrale pour instruments baroques et modernes vaguement inspir\u00e9e d\u2019<em>Orgia<\/em> et bas\u00e9e sur la <em>Passion selon Saint Jean<\/em> de Bach (<em>Irrisorio alito d\u2019aria<\/em>, 2017). Et Calixto a cr\u00e9\u00e9 une mise en sc\u00e8ne pour cette <em>Passion<\/em>.<\/span><\/p>\n<p><strong>Est-ce \u00e0 dire que, dans sa forme, votre partition r\u00e9pond directement aux enjeux de vos \u00e9changes avec Calixto Bieito\u2009?<\/strong><br \/>\n<span style=\"font-size: 14pt;\">Quand j\u2019ai parl\u00e9 avec Graziella Chiarcossi, la ni\u00e8ce et h\u00e9riti\u00e8re de Pasolini, elle m\u2019a demand\u00e9 de ne pas changer un seul mot de Pasolini, pas une seule virgule, mais de faire toutes les coupes n\u00e9cessaires au d\u00e9veloppement de l\u2019op\u00e9ra. Et c\u2019est Calixto qui a fait ces coupes. C\u2019\u00e9tait crucial pour moi car je souhaitais vraiment m\u2019inspirer de ce que Calixto mettait en avant pour essentialiser le drame pasolinien tout en respectant scrupuleusement sa structure compos\u00e9e d\u2019un prologue et de six \u00e9pisodes.<\/span><\/p>\n<p><strong>Comment avez-vous proc\u00e9d\u00e9 pour forger un lyrisme sp\u00e9cifique dans la langue de Pasolini\u2009?<\/strong><br \/>\n<span style=\"font-size: 14pt;\">J\u2019ai v\u00e9cu un an \u00e0 la Villa M\u00e9dicis en tant que pensionnaire. Ainsi, en 2021, je me suis d\u00e9plac\u00e9 \u00e0 Rome en famille pour \u00e9tudier l\u2019italien et absorber tout ce que je pouvais de la ville adoptive de Pasolini, de ses gens, de sa lumi\u00e8re\u2026 Au d\u00e9but du processus de composition, j\u2019ai dessin\u00e9 beaucoup de torses hell\u00e9nistiques au Palazzo Altemps, au Palazzo Massimo alle Terme ou \u00e0 la Centrale Montemartini. Mon but \u00e9tait d\u2019\u00e9couter leurs voix, de ressentir leurs tensions internes et leurs rythmes externes pour stimuler l\u2019imagination lyrique qui donnerait vie aux deux protagonistes d\u2019<em>Orgia<\/em>. Inspir\u00e9 par la mani\u00e8re particuli\u00e8re et radicale de Pasolini d\u2019explorer le pass\u00e9 pour \u00e9clairer le pr\u00e9sent d\u2019une lumi\u00e8re nouvelle, capable de nous projeter dans l\u2019avenir, j\u2019ai \u00e9tudi\u00e9 attentivement cette <em>lingua del corpo<\/em> qui est \u00e0 la base de notre culture, afin de l\u2019exprimer plastiquement de mani\u00e8re directe et gestuellement palpable. Dans mes dessins, chaque coup de crayon r\u00e9v\u00e8le sa direction, l\u2019\u00e9nergie avec laquelle il a \u00e9t\u00e9 r\u00e9alis\u00e9, sa relation avec les autres, ainsi que sa fonction structurelle au sein de l\u2019ensemble. Et apr\u00e8s chaque s\u00e9ance de dessin j\u2019ai rev\u00e9cu dans l\u2019atelier de composition les \u00e9tats psychologiques exp\u00e9riment\u00e9s devant les originaux grecs et romains pour, face au texte de Pasolini, donner naissance \u00e0 la partition d\u2019<em>Orgia <\/em>(photo ci-dessous).<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29859\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/partition-orgia.jpg\" alt=\"\" width=\"750\" height=\"926\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/partition-orgia.jpg 829w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/partition-orgia-243x300.jpg 243w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/partition-orgia-768x949.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><strong>Comment \u00e7a se joue musicalement\u2009?<\/strong><br \/>\n<span style=\"font-size: 14pt;\">Cette exp\u00e9rience plastique et esth\u00e9tique m\u2019a permis de d\u00e9velopper un lyrisme fluide qui, selon la nature du texte, prend des formes diff\u00e9rentes. L\u00e0 o\u00f9 le flux de la parole est plus rapide et les dialogues plus vifs et tranchants, les lignes m\u00e9lodiques suivent de pr\u00e8s les profils sinueux et rythmiques de la langue italienne originale. Ainsi, les couleurs phon\u00e9tiques de chaque phrase sont accentu\u00e9es par des dynamiques et des registres plus extr\u00eames, tandis que les passages transitoires sont exprim\u00e9s d\u2019une voix presque parl\u00e9e. Chaque registre, chaque intervalle, mais aussi chaque phon\u00e8me et chaque syllabe du texte poss\u00e8de ses couleurs, ses modes d\u2019expression lyrique. Et la partition devient une lettre intime que le compositeur livre au chanteur. Quand le chanteur r\u00e9alise tous ces transferts, il y a des \u00e9motions profondes qui \u00e9mergent. Apr\u00e8s, au cours des r\u00e9p\u00e9titions orchestrales, j\u2019ai \u00e9t\u00e9 tr\u00e8s inspir\u00e9 par la fa\u00e7on \u00e9blouissante qu\u2019a Pierre Bleuse de faire vibrer le souffle de la musique et son phras\u00e9 au travers de l\u2019air et d\u2019en transmettre ses vibrations et architectures\u2026<\/span><\/p>\n<p><strong>Mais est-ce qu\u2019on peut faire une r\u00e9volution po\u00e9tique sans faire une r\u00e9volution du langage\u2009?<\/strong><br \/>\n<span style=\"font-size: 14pt;\">\u00c0 la base, dans mon \u00e9criture, je cherche toujours une vocalit\u00e9 qui est le fruit du moment pr\u00e9sent et du v\u00e9cu intime que j\u2019en ai. Cela demande d\u2019accepter l\u2019ouverture totale de la voix, la vibration totale du corps humain. Mon but est de parvenir \u00e0 un langage lyrique actualis\u00e9 qui mette en jeu les probl\u00e8mes de notre \u00e9poque, \u00e0 travers un lyrisme expressif qui embrasse naturellement les \u00e9motions les plus vari\u00e9es. Avec la difficult\u00e9 implicite du moment \u2013 extr\u00eamement dangereux \u2013 qui s\u2019est ouvert dans le monde en raison de l\u2019influence \u00e9crasante d\u2019une techno-politique progressivement articul\u00e9e aux id\u00e9ologies n\u00e9o-fascistes, qui contaminent chacune des sph\u00e8res de notre soci\u00e9t\u00e9.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-29861\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-36-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-36-scaled.jpg 2560w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-36-300x200.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-36-1024x683.jpg 1024w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-36-768x512.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-36-1536x1024.jpg 1536w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-36-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p><strong>Vous recourez au langage pass\u00e9 de l\u2019op\u00e9ra, en retournant \u00e0 Jacopo Peri, aux origines de l\u2019op\u00e9ra. Ces types de langages musicaux r\u00e9pondent-ils \u00e0 un codage politique de votre part ?<\/strong><br \/>\n<span style=\"font-size: 14pt;\">Dans les passages o\u00f9 les personnages d\u2019<em>Orgia<\/em> expriment le contraste, si typique de Pasolini, entre le pr\u00e9sent consum\u00e9riste et d\u00e9shumanisant et un pass\u00e9 pr\u00e9industriel id\u00e9alis\u00e9 par lui, la musique orchestrale, \u00e0 travers les sons de l\u2019archiluth et de la harpe, se transforme pour nous ramener aux origines du genre op\u00e9ratique, en citant des passages cl\u00e9s de l\u2019<em>Euridice<\/em> de Peri et de l\u2019<em>Orfeo<\/em> de Monteverdi. Dans l\u2019\u00e9pisode III, les deux personnages et les bois de l\u2019orchestre chantent, en citant librement et en se transformant constamment, le passage dans lequel la messag\u00e8re de l\u2019op\u00e9ra <em>Orfeo<\/em> de Monteverdi annonce au demi-dieu la mort de sa bien-aim\u00e9e. Ce fragment lyrique inoubliable de l\u2019\u0153uvre fondatrice du genre op\u00e9ratique, avec ses m\u00e9lismes archa\u00efques, sa modalit\u00e9 \u00e9nigmatique et son pathos triste, se constitue ainsi en paradigme de la mort et du malheur exprim\u00e9s en musique, conf\u00e9rant \u00e0 <em>Orgia<\/em> une tonalit\u00e9 ancestrale.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">Propos recueillis par David Christoffel<\/p>\n<p style=\"text-align: left;\">Photos (de haut en bas) : \u00a9 E. Moreno Esquibel &#8211; Teatro Arriaga \/ \u00a9 Teatro Arriaga<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;op\u00e9ra &#8220;Orgia&#8221; d\u2019H\u00e8ctor Parra s\u2019impose comme une rencontre saisissante entre la radicalit\u00e9 po\u00e9tique de Pier Paolo Pasolini et la modernit\u00e9 lyrique du compositeur catalan. Adapt\u00e9 de la premi\u00e8re pi\u00e8ce de th\u00e9\u00e2tre de Pasolini \u00e9crite en 1968, &#8220;Orgia&#8221; plonge dans l\u2019intimit\u00e9 d\u2019un huis clos o\u00f9 la violence des rapports humains, la question du mal et la monstruosit\u00e9 sont expos\u00e9es sans fard, dans une soci\u00e9t\u00e9 que Pasolini juge d\u00e9shumanis\u00e9e par le consum\u00e9risme et les r\u00e9surgences du fascisme. H\u00e8ctor Parra revient sur son int\u00e9r\u00eat pour ce texte f\u00e9roce et les enjeux de son adaptation pour l\u2019op\u00e9ra, qui sera mis en sc\u00e8ne le 22 novembre par Calixto Bieito.<\/p>\n","protected":false},"author":185,"featured_media":29856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-29855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","concert-eic-friends-orgia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u2009H\u00e8ctor Parra : conf\u00e9rer \u00e0 &quot;Orgia&quot; une tonalit\u00e9 ancestrale.\u2009 - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2009H\u00e8ctor Parra : conf\u00e9rer \u00e0 &quot;Orgia&quot; une tonalit\u00e9 ancestrale.\u2009 - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"L&#039;op\u00e9ra &quot;Orgia&quot; d\u2019H\u00e8ctor Parra s\u2019impose comme une rencontre saisissante entre la radicalit\u00e9 po\u00e9tique de Pier Paolo Pasolini et la modernit\u00e9 lyrique du compositeur catalan. Adapt\u00e9 de la premi\u00e8re pi\u00e8ce de th\u00e9\u00e2tre de Pasolini \u00e9crite en 1968, &quot;Orgia&quot; plonge dans l\u2019intimit\u00e9 d\u2019un huis clos o\u00f9 la violence des rapports humains, la question du mal et la monstruosit\u00e9 sont expos\u00e9es sans fard, dans une soci\u00e9t\u00e9 que Pasolini juge d\u00e9shumanis\u00e9e par le consum\u00e9risme et les r\u00e9surgences du fascisme. H\u00e8ctor Parra revient sur son int\u00e9r\u00eat pour ce texte f\u00e9roce et les enjeux de son adaptation pour l\u2019op\u00e9ra, qui sera mis en sc\u00e8ne le 22 novembre par Calixto Bieito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-31T13:14:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T11:05:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Christoffel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Christoffel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2025\\\/10\\\/conferer-a-orgia-une-tonalite-ancestrale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2025\\\/10\\\/conferer-a-orgia-une-tonalite-ancestrale\\\/\"},\"author\":{\"name\":\"David Christoffel\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/2e67daa38438119a1f45e83d76278daf\"},\"headline\":\"\u2009H\u00e8ctor Parra : conf\u00e9rer \u00e0 &#8220;Orgia&#8221; une tonalit\u00e9 ancestrale.\u2009\",\"datePublished\":\"2025-10-31T13:14:27+00:00\",\"dateModified\":\"2025-11-05T11:05:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2025\\\/10\\\/conferer-a-orgia-une-tonalite-ancestrale\\\/\"},\"wordCount\":1228,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2025\\\/10\\\/conferer-a-orgia-une-tonalite-ancestrale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2025\\\/10\\\/orgia-ensayo-general-28-scaled.jpg\",\"articleSection\":[\"Entretien\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2025\\\/10\\\/conferer-a-orgia-une-tonalite-ancestrale\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2025\\\/10\\\/conferer-a-orgia-une-tonalite-ancestrale\\\/\",\"name\":\"\u2009H\u00e8ctor Parra : conf\u00e9rer \u00e0 \\\"Orgia\\\" une tonalit\u00e9 ancestrale.\u2009 - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2025\\\/10\\\/conferer-a-orgia-une-tonalite-ancestrale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2025\\\/10\\\/conferer-a-orgia-une-tonalite-ancestrale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2025\\\/10\\\/orgia-ensayo-general-28-scaled.jpg\",\"datePublished\":\"2025-10-31T13:14:27+00:00\",\"dateModified\":\"2025-11-05T11:05:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/2e67daa38438119a1f45e83d76278daf\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2025\\\/10\\\/conferer-a-orgia-une-tonalite-ancestrale\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2025\\\/10\\\/conferer-a-orgia-une-tonalite-ancestrale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2025\\\/10\\\/conferer-a-orgia-une-tonalite-ancestrale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2025\\\/10\\\/orgia-ensayo-general-28-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2025\\\/10\\\/orgia-ensayo-general-28-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"ORGIA EG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/2025\\\/10\\\/conferer-a-orgia-une-tonalite-ancestrale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u2009H\u00e8ctor Parra : conf\u00e9rer \u00e0 &#8220;Orgia&#8221; une tonalit\u00e9 ancestrale.\u2009\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/2e67daa38438119a1f45e83d76278daf\",\"name\":\"David Christoffel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454b223c8bd809ef49629a11274adb432a1f36c277297eff0a4b632610c4d520?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454b223c8bd809ef49629a11274adb432a1f36c277297eff0a4b632610c4d520?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/454b223c8bd809ef49629a11274adb432a1f36c277297eff0a4b632610c4d520?s=96&d=mm&r=g\",\"caption\":\"David Christoffel\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/author\\\/david-christofell\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2009H\u00e8ctor Parra : conf\u00e9rer \u00e0 \"Orgia\" une tonalit\u00e9 ancestrale.\u2009 - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/","og_locale":"en_US","og_type":"article","og_title":"\u2009H\u00e8ctor Parra : conf\u00e9rer \u00e0 \"Orgia\" une tonalit\u00e9 ancestrale.\u2009 - Ensemble intercontemporain","og_description":"L'op\u00e9ra \"Orgia\" d\u2019H\u00e8ctor Parra s\u2019impose comme une rencontre saisissante entre la radicalit\u00e9 po\u00e9tique de Pier Paolo Pasolini et la modernit\u00e9 lyrique du compositeur catalan. Adapt\u00e9 de la premi\u00e8re pi\u00e8ce de th\u00e9\u00e2tre de Pasolini \u00e9crite en 1968, \"Orgia\" plonge dans l\u2019intimit\u00e9 d\u2019un huis clos o\u00f9 la violence des rapports humains, la question du mal et la monstruosit\u00e9 sont expos\u00e9es sans fard, dans une soci\u00e9t\u00e9 que Pasolini juge d\u00e9shumanis\u00e9e par le consum\u00e9risme et les r\u00e9surgences du fascisme. H\u00e8ctor Parra revient sur son int\u00e9r\u00eat pour ce texte f\u00e9roce et les enjeux de son adaptation pour l\u2019op\u00e9ra, qui sera mis en sc\u00e8ne le 22 novembre par Calixto Bieito.","og_url":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2025-10-31T13:14:27+00:00","article_modified_time":"2025-11-05T11:05:19+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-scaled.jpg","type":"image\/jpeg"}],"author":"David Christoffel","twitter_card":"summary_large_image","twitter_misc":{"Written by":"David Christoffel","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/"},"author":{"name":"David Christoffel","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/2e67daa38438119a1f45e83d76278daf"},"headline":"\u2009H\u00e8ctor Parra : conf\u00e9rer \u00e0 &#8220;Orgia&#8221; une tonalit\u00e9 ancestrale.\u2009","datePublished":"2025-10-31T13:14:27+00:00","dateModified":"2025-11-05T11:05:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/"},"wordCount":1228,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-scaled.jpg","articleSection":["Entretien"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/","url":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/","name":"\u2009H\u00e8ctor Parra : conf\u00e9rer \u00e0 \"Orgia\" une tonalit\u00e9 ancestrale.\u2009 - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-scaled.jpg","datePublished":"2025-10-31T13:14:27+00:00","dateModified":"2025-11-05T11:05:19+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/2e67daa38438119a1f45e83d76278daf"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-scaled.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2025\/10\/orgia-ensayo-general-28-scaled.jpg","width":2560,"height":1707,"caption":"ORGIA EG"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/2025\/10\/conferer-a-orgia-une-tonalite-ancestrale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u2009H\u00e8ctor Parra : conf\u00e9rer \u00e0 &#8220;Orgia&#8221; une tonalit\u00e9 ancestrale.\u2009"}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/2e67daa38438119a1f45e83d76278daf","name":"David Christoffel","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/454b223c8bd809ef49629a11274adb432a1f36c277297eff0a4b632610c4d520?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/454b223c8bd809ef49629a11274adb432a1f36c277297eff0a4b632610c4d520?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/454b223c8bd809ef49629a11274adb432a1f36c277297eff0a4b632610c4d520?s=96&d=mm&r=g","caption":"David Christoffel"},"url":"https:\/\/www.ensembleintercontemporain.com\/en\/author\/david-christofell\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/29855\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/users\/185\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/comments\/?post=29855"}],"version-history":[{"count":7,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/29855\/revisions\/"}],"predecessor-version":[{"id":29892,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/29855\/revisions\/29892\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/29856\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/?parent=29855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/categories\/?post=29855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/tags\/?post=29855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}