{"id":17445,"date":"2019-08-29T13:18:44","date_gmt":"2019-08-29T11:18:44","guid":{"rendered":"https:\/\/www.ensembleintercontemporain.com\/?p=17445"},"modified":"2019-09-11T11:40:50","modified_gmt":"2019-09-11T09:40:50","slug":"de-haut-vol-entretien-avec-elizabeth-streb","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/en\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/","title":{"rendered":"De haut vol. Entretien avec Elizabeth Streb."},"content":{"rendered":"<p><strong><span style=\"font-size: 14pt; color: #003366;\"> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17554\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/07\/streb_ioulex_3031913-ec-1.jpg\" alt=\"\" width=\"1920\" height=\"1278\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/07\/streb_ioulex_3031913-ec-1.jpg 1920w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/07\/streb_ioulex_3031913-ec-1-300x200.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/07\/streb_ioulex_3031913-ec-1-768x511.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/07\/streb_ioulex_3031913-ec-1-1024x682.jpg 1024w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/span><\/strong><\/p>\n<p><strong><span style=\"font-size: 14pt; color: #003366;\">Des sauts dans le vide \u00e0 dix m\u00e8tres du sol, des machines qui mettent les corps en apesanteur\u2026 Avec sa compagnie Streb Extreme Action, bas\u00e9e \u00e0 New York, la chor\u00e9graphe am\u00e9ricaine Elizabeth Streb r\u00e9v\u00e8le l\u2019incroyable potentiel des corps. Pour la <a href=\"https:\/\/www.ensembleintercontemporain.com\/fr\/concert\/parade-2019-09-13-20h00-paris\/\">r\u00e9ouverture du Th\u00e9\u00e2tre du Ch\u00e2telet, le 13 septembre<\/a>, elle cr\u00e9e <em>Parade<\/em>, hommage au ballet d\u2019Erik Satie avec une musique du compositeur fran\u00e7ais Pierre-Yves Mac\u00e9.<\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"font-size: 14pt;\">Elizabeth, d\u2019o\u00f9 vient votre approche atypique de la chor\u00e9graphie ?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">Je me suis toujours demand\u00e9 pourquoi les danseurs passaient leur temps \u00e0 faire semblant de d\u00e9fier la gravit\u00e9, alors que celle qu\u2019ils affrontent est tr\u00e8s faible. En revanche, quand vous vous laissez tomber de dix m\u00e8tres de haut, vous sentez une vraie force qui vous attire. Si vous ne l\u2019affrontez pas, alors selon moi, vous n\u2019\u00eates pas profond\u00e9ment dans le mouvement, dans l\u2019action. Vous \u00eates un danseur qui fait semblant. Ce que j\u2019essaie de cr\u00e9er, c\u2019est une sorte de danse non pr\u00e9dictive. Le public ne doit pas pouvoir anticiper ce qui se passe devant lui. La question centrale, c\u2019est de r\u00e9aliser des mouvements sinc\u00e8res dans la situation artificielle qu\u2019est la th\u00e9\u00e2tralit\u00e9.<\/span><\/p>\n<p><strong><span style=\"font-size: 14pt;\">Ce que vous faites avec votre compagnie est-il dangereux ?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">Oui. Mais c\u2019est n\u00e9cessaire. \u00c0 mon avis, nous affrontons simplement notre condition physique d\u2019\u00eatre humain sur terre. Je ne comprends pas pourquoi les gens trouvent que ce que je fais est violent. Les danseurs de Streb Extreme Action sont d\u2019accord pour se faire un peu mal, mais mon but n\u2019est pas la souffrance. \u00c0 force de r\u00e9p\u00e9titions, ils savent comprendre en une fraction de seconde quoi faire pour \u00e9viter les blessures graves.<\/span><\/p>\n<p><strong><span style=\"font-size: 14pt;\">Comment recrutez-vous vos performeurs ?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">Nous leur faisons passer une audition de trois jours, sans rien de vraiment dangereux. Il faut que leurs mouvements soient beaux mais aussi qu\u2019ils soient curieux de ce qui meut leur corps. Savent-ils ouvrir leur cage pour en faire sortir l\u2019animal sauvage ? C\u2019est cela que je cherche. Il faut bien s\u00fbr qu\u2019ils soient tr\u00e8s costauds. Leur constitution doit leur permettre d\u2019\u00e9viter les blessures. Ils doivent aussi \u00eatre d\u2019une nature \u00e0 s\u2019amuser dans leur travail. S\u2019accroupir, tomber dans les airs et atterrir sur le ventre doit les faire sourire, pas grimacer.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17583\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1466.jpg\" alt=\"\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1466.jpg 1920w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1466-300x200.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1466-768x512.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1466-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p><strong><span style=\"font-size: 14pt;\">Mais ce sont des super h\u00e9ros !<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">C\u2019est exactement cela. D\u2019ailleurs, dans l\u2019\u00e9cole que j\u2019ai cr\u00e9\u00e9e, o\u00f9 les danseurs de la compagnie enseignent, les enfants ont tous leur pr\u00e9f\u00e9r\u00e9. Ils ont cr\u00e9\u00e9 des emojis de super h\u00e9ros pour chacun d\u2019entre eux. Les vendredis et samedis nous organisons des spectacles. Chaque danseur est accueilli par les acclamations de ses supporters !<\/span><\/p>\n<p><strong><span style=\"font-size: 14pt;\">Parlez-nous de cette \u00e9cole\u2026<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">Je l\u2019ai ouverte il y a seize ans, et aujourd\u2019hui elle accueille environ 600 enfants par semaine, r\u00e9partis en soixante cours. Les plus petits ont 18 mois. Les enfants sont des participants fondamentaux \u00e0 notre exp\u00e9rience. Ils ne font pas semblant quand ils bougent, cela les rend joyeux. Apr\u00e8s seize ans de ce programme, les danseurs de la compagnie se sont appropri\u00e9s les mouvements des enfants. Comme eux, ils jouent.<\/span><\/p>\n<p><strong><span style=\"font-size: 14pt;\">Qu\u2019est-ce que vous voulez apprendre en premier lieu \u00e0 ces enfants et \u00e0 vos performeurs ?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">\u00c0 voler.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"font-size: 14pt;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17579\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1347.jpg\" alt=\"\" width=\"1920\" height=\"1281\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1347.jpg 1920w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1347-300x200.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1347-768x512.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1347-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/span><\/strong><\/p>\n<p><strong><span style=\"font-size: 14pt;\">Vous utilisez des machines impressionnantes dans vos chor\u00e9graphies. Comment sont-elles mises au point ?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">Des ing\u00e9nieurs travaillent avec nous, au c\u0153ur de la compagnie. Nous les laissons d\u00e9couvrir notre univers, comprendre nos enjeux, afin qu\u2019ils mettent au point un mat\u00e9riel qui ne nous trahira pas. Pour Parade au Th\u00e9\u00e2tre du Ch\u00e2telet, nous inaugurons une nouvelle machine, unique au monde : la molinete (photo ci-dessus). C\u2019est une sorte de tube mont\u00e9 sur tr\u00e9pied qui tourne \u00e0 360 degr\u00e9s, o\u00f9 trois danseurs peuvent s\u2019accrocher gr\u00e2ce \u00e0 des bottes sp\u00e9ciales.<\/span><\/p>\n<p><strong><span style=\"font-size: 14pt;\">Quel est le r\u00f4le de ces machines dans votre recherche ?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">Elles permettent d\u2019inventer un vocabulaire nouveau. Nous cr\u00e9ons nos \u00e9quipements un peu de la mani\u00e8re dont les instruments de musique ont \u00e9t\u00e9 invent\u00e9s : \u00e0 l\u2019aube de l\u2019humanit\u00e9, on s\u2019est aper\u00e7u que la voix humaine n\u2019\u00e9tait pas suffisante pour repr\u00e9senter tous les sons qui existent sur terre. C\u2019est ce que nous faisons dans le domaine de la danse : nous d\u00e9cidons que le corps humain au sol n\u2019est pas suffisant et nous inventons des machines pour aller plus haut, plus vite, plus fort.<\/span><\/p>\n<p><strong><span style=\"font-size: 14pt;\">Vous n\u2019avez pas voulu conna\u00eetre la musique de Pierre-Yves Mac\u00e9, inspir\u00e9e par <em>Parade<\/em>, avant les premi\u00e8res r\u00e9p\u00e9titions. Pourquoi ?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">Je n\u2019ai pas besoin d\u2019entendre la musique car la musique ne me guide pas. Je b\u00e2tis avec les performeurs une structure sans musicalit\u00e9. C\u2019est la perception du public qui relie mouvement et musique. Cela n\u2019emp\u00eache pas la musique de nous \u00e9mouvoir quand nous bougeons mais je consid\u00e8re musique et chor\u00e9graphie comme deux univers distincts.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17585\" src=\"http:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1589.jpg\" alt=\"\" width=\"1920\" height=\"2880\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1589.jpg 1920w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1589-200x300.jpg 200w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1589-768x1152.jpg 768w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/08\/dscf1589-683x1024.jpg 683w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Photos (de haut en bas) : \u00a9 Ioulex \/\u00a0<em> Tilt<\/em> \u00a9 Streb Extreme Action ; autres photos \u00a9 EIC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des sauts dans le vide \u00e0 dix m\u00e8tres du sol, des machines qui mettent les corps en apesanteur\u2026 Avec sa compagnie Streb Extreme Action, bas\u00e9e \u00e0 New York, la chor\u00e9graphe am\u00e9ricaine Elizabeth Streb r\u00e9v\u00e8le l\u2019incroyable potentiel des corps. Pour la r\u00e9ouverture du Th\u00e9\u00e2tre du Ch\u00e2telet, le 13 septembre, elle cr\u00e9e Parade, hommage au ballet d\u2019Erik Satie avec une musique du compositeur fran\u00e7ais Pierre-Yves Mac\u00e9.<\/p>\n","protected":false},"author":150,"featured_media":17554,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[60,61,1068,179,1069],"class_list":["post-17445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-creation","tag-creation-musicale","tag-elizabeth-streb","tag-performance","tag-theatre-du-chatelet","concert-parade"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De haut vol. Entretien avec Elizabeth Streb. - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/en\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De haut vol. Entretien avec Elizabeth Streb. - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"Des sauts dans le vide \u00e0 dix m\u00e8tres du sol, des machines qui mettent les corps en apesanteur\u2026 Avec sa compagnie Streb Extreme Action, bas\u00e9e \u00e0 New York, la chor\u00e9graphe am\u00e9ricaine Elizabeth Streb r\u00e9v\u00e8le l\u2019incroyable potentiel des corps. Pour la r\u00e9ouverture du Th\u00e9\u00e2tre du Ch\u00e2telet, le 13 septembre, elle cr\u00e9e Parade, hommage au ballet d\u2019Erik Satie avec une musique du compositeur fran\u00e7ais Pierre-Yves Mac\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-29T11:18:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-11T09:40:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/07\/streb_ioulex_3031913-ec-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Axelle Corty\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Axelle Corty\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/08\\\/de-haut-vol-entretien-avec-elizabeth-streb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/08\\\/de-haut-vol-entretien-avec-elizabeth-streb\\\/\"},\"author\":{\"name\":\"Axelle Corty\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/b39aa84988c55394ebbb9a98242ecdbb\"},\"headline\":\"De haut vol. Entretien avec Elizabeth Streb.\",\"datePublished\":\"2019-08-29T11:18:44+00:00\",\"dateModified\":\"2019-09-11T09:40:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/08\\\/de-haut-vol-entretien-avec-elizabeth-streb\\\/\"},\"wordCount\":870,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/08\\\/de-haut-vol-entretien-avec-elizabeth-streb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2019\\\/07\\\/streb_ioulex_3031913-ec-1.jpg\",\"keywords\":[\"cr\u00e9ation\",\"cr\u00e9ation musicale\",\"elizabeth streb\",\"performance\",\"Th\u00e9\u00e2tre du ch\u00e2telet\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/08\\\/de-haut-vol-entretien-avec-elizabeth-streb\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/08\\\/de-haut-vol-entretien-avec-elizabeth-streb\\\/\",\"name\":\"De haut vol. Entretien avec Elizabeth Streb. - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/08\\\/de-haut-vol-entretien-avec-elizabeth-streb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/08\\\/de-haut-vol-entretien-avec-elizabeth-streb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2019\\\/07\\\/streb_ioulex_3031913-ec-1.jpg\",\"datePublished\":\"2019-08-29T11:18:44+00:00\",\"dateModified\":\"2019-09-11T09:40:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/b39aa84988c55394ebbb9a98242ecdbb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/08\\\/de-haut-vol-entretien-avec-elizabeth-streb\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/08\\\/de-haut-vol-entretien-avec-elizabeth-streb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/08\\\/de-haut-vol-entretien-avec-elizabeth-streb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2019\\\/07\\\/streb_ioulex_3031913-ec-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2019\\\/07\\\/streb_ioulex_3031913-ec-1.jpg\",\"width\":1920,\"height\":1278},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2019\\\/08\\\/de-haut-vol-entretien-avec-elizabeth-streb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De haut vol. Entretien avec Elizabeth Streb.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/b39aa84988c55394ebbb9a98242ecdbb\",\"name\":\"Axelle Corty\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f15daa85f845c869d6e24507b28d428b84be8522b6b1fcb141f2f7c6bc0ac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f15daa85f845c869d6e24507b28d428b84be8522b6b1fcb141f2f7c6bc0ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee7f15daa85f845c869d6e24507b28d428b84be8522b6b1fcb141f2f7c6bc0ac?s=96&d=mm&r=g\",\"caption\":\"Axelle Corty\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/author\\\/acorty\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De haut vol. Entretien avec Elizabeth Streb. - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/en\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/","og_locale":"en_US","og_type":"article","og_title":"De haut vol. Entretien avec Elizabeth Streb. - Ensemble intercontemporain","og_description":"Des sauts dans le vide \u00e0 dix m\u00e8tres du sol, des machines qui mettent les corps en apesanteur\u2026 Avec sa compagnie Streb Extreme Action, bas\u00e9e \u00e0 New York, la chor\u00e9graphe am\u00e9ricaine Elizabeth Streb r\u00e9v\u00e8le l\u2019incroyable potentiel des corps. Pour la r\u00e9ouverture du Th\u00e9\u00e2tre du Ch\u00e2telet, le 13 septembre, elle cr\u00e9e Parade, hommage au ballet d\u2019Erik Satie avec une musique du compositeur fran\u00e7ais Pierre-Yves Mac\u00e9.","og_url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2019-08-29T11:18:44+00:00","article_modified_time":"2019-09-11T09:40:50+00:00","og_image":[{"width":1920,"height":1278,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/07\/streb_ioulex_3031913-ec-1.jpg","type":"image\/jpeg"}],"author":"Axelle Corty","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Axelle Corty","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/"},"author":{"name":"Axelle Corty","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/b39aa84988c55394ebbb9a98242ecdbb"},"headline":"De haut vol. Entretien avec Elizabeth Streb.","datePublished":"2019-08-29T11:18:44+00:00","dateModified":"2019-09-11T09:40:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/"},"wordCount":870,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/07\/streb_ioulex_3031913-ec-1.jpg","keywords":["cr\u00e9ation","cr\u00e9ation musicale","elizabeth streb","performance","Th\u00e9\u00e2tre du ch\u00e2telet"],"articleSection":["Entretien"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/","url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/","name":"De haut vol. Entretien avec Elizabeth Streb. - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/07\/streb_ioulex_3031913-ec-1.jpg","datePublished":"2019-08-29T11:18:44+00:00","dateModified":"2019-09-11T09:40:50+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/b39aa84988c55394ebbb9a98242ecdbb"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/07\/streb_ioulex_3031913-ec-1.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2019\/07\/streb_ioulex_3031913-ec-1.jpg","width":1920,"height":1278},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2019\/08\/de-haut-vol-entretien-avec-elizabeth-streb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/en\/"},{"@type":"ListItem","position":2,"name":"De haut vol. Entretien avec Elizabeth Streb."}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/b39aa84988c55394ebbb9a98242ecdbb","name":"Axelle Corty","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ee7f15daa85f845c869d6e24507b28d428b84be8522b6b1fcb141f2f7c6bc0ac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ee7f15daa85f845c869d6e24507b28d428b84be8522b6b1fcb141f2f7c6bc0ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ee7f15daa85f845c869d6e24507b28d428b84be8522b6b1fcb141f2f7c6bc0ac?s=96&d=mm&r=g","caption":"Axelle Corty"},"url":"https:\/\/www.ensembleintercontemporain.com\/en\/author\/acorty\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/17445\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/users\/150\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/comments\/?post=17445"}],"version-history":[{"count":14,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/17445\/revisions\/"}],"predecessor-version":[{"id":17587,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/17445\/revisions\/17587\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/17554\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/?parent=17445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/categories\/?post=17445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/tags\/?post=17445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}