{"id":1727,"date":"2008-01-15T10:04:10","date_gmt":"2008-01-15T08:04:10","guid":{"rendered":"http:\/\/www.ensembleinter.com\/accents-online\/?p=1727"},"modified":"2008-01-15T10:04:10","modified_gmt":"2008-01-15T08:04:10","slug":"le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/en\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/","title":{"rendered":"Le fils aim\u00e9 de l\u2019oc\u00e9an (Lautr\u00e9amont) &#8211; entretien avec Philipp Maintz"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1728\" title=\"Maintz\" src=\"http:\/\/www.ensembleinter.com\/accents-online\/wp-content\/uploads\/2010\/05\/Maintz-300x213.jpg\" alt=\"Maintz\" width=\"300\" height=\"213\" srcset=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2010\/05\/Maintz-300x213.jpg 300w, https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2010\/05\/Maintz.jpg 716w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\n<em> <\/em><br \/>\n<em>Pouvez-vous nous dire quel rapport entretiennent vos derni\u00e8res pi\u00e8ces (en particulier <\/em>Gel\u00e4nde\/Zeichnung <em>pour piano et \u00e9lectronique et <\/em>Fluchtlinie<em>, pour baryton et ensemble) avec la pi\u00e8ce \u00e0 venir pour -l\u2019Ensemble intercontemporain<\/em><em> ?<\/em><br \/>\nDans la pi\u00e8ce pour piano et \u00e9lectronique, j\u2019ai essay\u00e9 de trouver du nouveau dans le traitement de l\u2019\u00e9lectronique. C\u2019\u00e9tait ma troisi\u00e8me pi\u00e8ce pour instrument et \u00e9lectronique, apr\u00e8s <em>LIED<\/em>(<em>geborsten<\/em>), pour ensemble et \u00e9lectronique et une petite \u00e9tude pour l\u2019Ircam en 2005, pour violon et \u00e9lectronique, qui ne m\u2019a pas vraiment convaincu, disons, mais je l\u2019ai bien cach\u00e9. Je peux maintenant recourir \u00e0 la musique avec \u00e9lectronique\u202f; cette pi\u00e8ce est d\u2019une certaine mani\u00e8re une \u00e9tude pour devenir plus familier avec l\u2019\u00e9lectronique.<br \/>\nEn ce qui concerne l\u2019autre pi\u00e8ce, pour -baryton et ensemble\u202f: si on \u00e9crit une pi\u00e8ce purement instrumentale, on peut utiliser une forme bien d\u00e9velopp\u00e9e, presque synth\u00e9tique. Mais le texte a une dramaturgie propre, qui peut tout \u00e0 fait se d\u00e9velopper dans une toute autre direction\u202f; il y a parfois des envies diff\u00e9rentes. Lorsque j\u2019ai \u00e9crit ma premi\u00e8re pi\u00e8ce pour une voix et un instrument, <em>septemberalbum\/acht<\/em>, pour voix et piano (2006), j\u2019ai fait l\u2019exp\u00e9rience qu\u2019on ne peut pas mettre une voix dans une forme compl\u00e8tement synth\u00e9tique. Il m\u2019a fallu changer mes techniques compositionnelles dans une direction beaucoup plus \u2013\u202fje ne veux pas dire improvis\u00e9e\u202f\u2013 mais beaucoup plus libre. Cette pi\u00e8ce pour baryton \u00e9tait importante pour d\u00e9velopper un certain r\u00e9pertoire de gestes, d\u2019atmosph\u00e8res, et pour mieux appr\u00e9hender la fa\u00e7on que j\u2019aurais d\u2019\u00e9crire pour une voix.<br \/>\n<em>Ce sont les deux directions que j\u2019esp\u00e9rais<\/em><em> : l\u2019\u00e9lectronique que vous avez envie de ma\u00eetriser, \u00e0 chaque fois avec une exp\u00e9rience un peu diff\u00e9rente, et la probl\u00e9matique de la voix<\/em><em> : vous dites qu\u2019on ne peut pas fabriquer un syst\u00e8me formel trop contraignant avec un texte. Or, la pi\u00e8ce qu\u2019on va entendre de l\u2019Ensemble intercontemporain est une pi\u00e8ce avec voix, \u00e9lectronique et un ensemble. D\u2019abord, de qui est le texte<\/em><em> ?<\/em><br \/>\nJ\u2019ai d\u00e9couvert, il y a quelques ann\u00e9es, les <em>Chants de Maldoror<\/em> de Lautr\u00e9amont, qui m\u2019ont \u00e9voqu\u00e9, quand je les ai lus, une -atmosph\u00e8re tr\u00e8s musicale. J\u2019avais d\u00e9j\u00e0 imagin\u00e9 en le lisant comment une musique pourrait se fondre avec ce texte. J\u2019ai toujours refus\u00e9 l\u2019id\u00e9e que \u00e7a pourrait \u00eatre un sujet pour un op\u00e9ra. Finalement, malgr\u00e9 le fait de rejeter l\u2019id\u00e9e, j\u2019ai d\u00e9couvert que c\u2019\u00e9tait bien pour l\u2019op\u00e9ra. Cette pi\u00e8ce sera sur le m\u00eame sujet de Maldoror.<br \/>\n<em>Cette pi\u00e8ce est une sc\u00e8ne de l\u2019op\u00e9ra ou bien quelque chose emprunt\u00e9 aux <\/em>Chants de Maldoror <em>qui ne sera pas dans l\u2019op\u00e9ra<\/em><em> ?<\/em><br \/>\nCette pi\u00e8ce deviendra une partie de la premi\u00e8re sc\u00e8ne de l\u2019op\u00e9ra.<br \/>\n<em>C\u2019est emprunt\u00e9 \u00e0 quel Chant ?<\/em><br \/>\nIl y a une grande partie des <em>Chants de Maldoror<\/em> autour de l\u2019oc\u00e9an\u202f; j\u2019ai un dramaturge avec qui nous avons travaill\u00e9 ce Chant et nous avons essay\u00e9 de le condenser pour le raccourcir. Ce sera dans la premi\u00e8re sc\u00e8ne de l\u2019op\u00e9ra\u202f: il y aura une soprano, sorte de m\u00e9lange entre une Cassandra et la Reine de la Nuit, qui a vraiment l\u2019air d\u2019\u00eatre m\u00e9chante, suffisante, arrogante, mais aussi sentimentale, en train de commenter l\u2019humanit\u00e9.<br \/>\n<em>Quelle direction prenez-vous lorsque vous r\u00e9duisez les six <\/em>Chants de Maldoror <em>pour en faire un op\u00e9ra et comment travaillez-vous avec votre dramaturge<\/em><em> ?<\/em><br \/>\nNous avons travaill\u00e9 de mani\u00e8re tr\u00e8s allemande, je pense. D\u2019abord, nous avons fait un plan, une sorte de r\u00e9sum\u00e9. Apr\u00e8s \u00e7a, nous avons essay\u00e9 de trouver des corr\u00e8lations entre les divers chants et leurs strophes. Ensuite, nous avons pu voir comment les <em>Chants de Maldoror<\/em> \u00e9taient structur\u00e9s. Nous avons essay\u00e9 de voir comment on pourrait connecter, associer les diverses sc\u00e8nes. Enfin, nous sommes arriv\u00e9s \u00e0 une sorte de sch\u00e9ma. Finalement, il y a quelque chose comme un livret pr\u00e9liminaire, que j\u2019utilise en composant, mais que je condense encore.<br \/>\n<em>Conservez-vous l\u2019ambigu\u00eft\u00e9 entre le personnage qui dit le texte, disons le po\u00e8te, et Maldoror lui-m\u00eame, ou bien l\u2019abandonnez-vous<\/em><em> ?<\/em><br \/>\nIl y a un Maldoror avec une autre personne, une sorte d\u2019alter-ego\u202f; on a quelque chose comme deux Maldoror sur la sc\u00e8ne.<br \/>\n<em>Dans quel genre de sc\u00e8ne pensez-vous tout de suite \u00e0 recourir \u00e0 l\u2019\u00e9lectronique et pourquoi<\/em><em> ? <\/em><br \/>\nCa m\u2019\u00e9voque beaucoup l\u2019id\u00e9e d\u2019un certain son, et aussi l\u2019id\u00e9e qu\u2019il y a quelque chose comme des fant\u00f4mes de son qui circulent dans tout l\u2019espace, y compris dans le public. Peut-\u00eatre laisser tout cela appara\u00eetre de fa\u00e7on un peu, disons, surr\u00e9aliste. Concernant cela, j\u2019ai une image en t\u00eate qui est assez simple. Pendant mes \u00e9tudes, j\u2019ai travaill\u00e9 dans une agence de voyage qui \u00e9tait situ\u00e9e pr\u00e8s de l\u2019a\u00e9roport de Tegel \u00e0 Berlin. Quand j\u2019y allais le matin, il fallait changer de bus et attendre \u00e0 un endroit o\u00f9 des avions arrivaient \u00e0 l\u2019a\u00e9roport. Quand les avions passaient, on pouvait entendre les turbulences dans l\u2019air qui arrivaient beaucoup plus tard. C\u2019\u00e9taient des sortes de voix qui venaient comme des fant\u00f4mes, sans qu\u2019on puisse compl\u00e8tement localiser d\u2019o\u00f9 \u00e7a venait. C\u2019\u00e9tait tr\u00e8s court, mais c\u2019est une image que j\u2019ai en t\u00eate \u00e0 propos de l\u2019utilisation de l\u2019\u00e9lectronique dans l\u2019op\u00e9ra.<br \/>\n<em>Gardez-vous la langue originale fran\u00e7aise ou le faites-vous en Allemand<\/em><em> ?<\/em><br \/>\nNon, je le fais en Fran\u00e7ais. La pi\u00e8ce que j\u2019ai faite pour baryton et ensemble, en Allemand, c\u2019\u00e9tait simplement une des contraintes de la commande.<br \/>\n<em>En ce qui concerne la mani\u00e8re de dire le texte, est-ce qu\u2019il y a des mod\u00e8les auxquels vous vous r\u00e9f\u00e9rez dans l\u2019histoire de la musique, ou au contraire des mod\u00e8les dont vous ne voulez absolument pas vous inspirer<\/em><em> ?<\/em><br \/>\nDisons que je n\u2019ai pas trouv\u00e9 une solution g\u00e9n\u00e9rale pour ces questions.<br \/>\n<em>Si vous me disiez le contraire, je me dirais \u00ab<\/em><em> il est fou<\/em><em> \u00bb. Personne n\u2019a trouv\u00e9 de solution bien s\u00fbr, c\u2019est pour \u00e7a qu\u2019on continue.<\/em><br \/>\nLors d\u2019un entracte d\u2019un concert, ici \u00e0 Paris, j\u2019\u00e9tais en train de parler de \u00e7a avec Lowrens Langevoort qui m\u2019a dit\u202f: \u00ab\u2009ach\u00e8te toi <em>Il trovatore<\/em> et lis \u00e7a un apr\u00e8s-midi. Et demande-toi simplement ce qu\u2019il veut, ce qui se passe l\u00e0.\u2009\u00bb Je l\u2019ai donc fait, et il avait vraiment raison.<br \/>\n<em>Il a raison mais <\/em>Il trovatore<em> est en Italien, et vous allez vous battre avec le Fran\u00e7ais&#8230;<\/em><br \/>\nC\u2019est vrai, mais peut-\u00eatre je suis un peu na\u00eff.<br \/>\n<em>Non, vous \u00eates fou, puisque vous commencez un op\u00e9ra<\/em><em> !<\/em><br \/>\nOui, j\u2019ai d\u00e9couvert que c\u2019\u00e9tait compl\u00e8tement fou.<br \/>\n<em>Je crois que vous \u00eates organiste de formation<\/em><em> ; y aura t-il de l\u2019orgue dans <\/em>Maldoror<em> ?<\/em><br \/>\nNon. Quand Peter Ruzicka m\u2019a demand\u00e9 si j\u2019aimerais \u00e9crire un op\u00e9ra, j\u2019ai dit \u00ab\u2009oui, pourquoi pas\u2009\u00bb. C\u2019est seulement plus tard que j\u2019ai r\u00e9alis\u00e9 avoir dit oui. Il voulait que j\u2019\u00e9crive un op\u00e9ra de chambre. En d\u00e9veloppant diff\u00e9rents plans sur ce que pouvait \u00eatre un op\u00e9ra, j\u2019ai \u00e9tendu l\u2019id\u00e9e de d\u00e9part et l\u2019effectif. Finalement, ce sera un v\u00e9ritable orchestre de cinquante musiciens. Il va me tirer les oreilles si je veux encore faire dans l\u2019exc\u00e8s comme \u00e0 Salzburg. Si en plus, j\u2019arrive avec -l\u2019orgue&#8230;<br \/>\n<em>Pour finir, de qui vous sentez-vous -proche<\/em><em> ?<\/em><br \/>\nJ\u2019aime beaucoup la musique de Pascal Dusapin. j\u2019admire aussi beaucoup les premi\u00e8res \u0153uvres publi\u00e9es de Hanspeter Kyburz que je trouve tr\u00e8s int\u00e9ressantes, tr\u00e8s bien faites. J\u2019ai essay\u00e9 deux fois d\u2019\u00e9tudier avec lui, mais malheureusement \u00e7a ne s\u2019est jamais fait. C\u2019est vraiment dommage parce que j\u2019ai eu l\u2019impression que je pourrais apprendre beaucoup chez lui.<br \/>\n<em>Propos recueillis par Jean-Pierre Derrien<br \/>\nExtrait d\u2019Accents n\u00b0 34<\/em><em> &#8211; janvier-mars 2007<\/em><br \/>\n<em>Photo : Philipp Maintz \u00a9 Nicolas Havette<br \/>\n<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pouvez-vous nous dire quel rapport entretiennent vos derni\u00e8res pi\u00e8ces (en particulier Gel\u00e4nde\/Zeichnung pour piano et \u00e9lectronique et Fluchtlinie, pour baryton et ensemble) avec la pi\u00e8ce \u00e0 venir pour -l\u2019Ensemble intercontemporain ? Dans la pi\u00e8ce pour piano et \u00e9lectronique, j\u2019ai essay\u00e9 de trouver du nouveau dans le traitement de l\u2019\u00e9lectronique. C\u2019\u00e9tait ma troisi\u00e8me pi\u00e8ce pour instrument [&hellip;]<\/p>\n","protected":false},"author":44,"featured_media":3578,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[306,307,97,145],"class_list":["post-1727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-accents-n34","tag-chants-de-maldoror","tag-opera","tag-philipp-maintz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le fils aim\u00e9 de l\u2019oc\u00e9an (Lautr\u00e9amont) - entretien avec Philipp Maintz - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/en\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le fils aim\u00e9 de l\u2019oc\u00e9an (Lautr\u00e9amont) - entretien avec Philipp Maintz - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"Pouvez-vous nous dire quel rapport entretiennent vos derni\u00e8res pi\u00e8ces (en particulier Gel\u00e4nde\/Zeichnung pour piano et \u00e9lectronique et Fluchtlinie, pour baryton et ensemble) avec la pi\u00e8ce \u00e0 venir pour -l\u2019Ensemble intercontemporain ? Dans la pi\u00e8ce pour piano et \u00e9lectronique, j\u2019ai essay\u00e9 de trouver du nouveau dans le traitement de l\u2019\u00e9lectronique. C\u2019\u00e9tait ma troisi\u00e8me pi\u00e8ce pour instrument [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2008-01-15T08:04:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2010\/05\/maintz34.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"464\" \/>\n\t<meta property=\"og:image:height\" content=\"237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean-Pierre Derrien\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean-Pierre Derrien\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2008\\\/01\\\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2008\\\/01\\\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\\\/\"},\"author\":{\"name\":\"Jean-Pierre Derrien\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/e007c9439ad786ee60c828c663f6dca9\"},\"headline\":\"Le fils aim\u00e9 de l\u2019oc\u00e9an (Lautr\u00e9amont) &#8211; entretien avec Philipp Maintz\",\"datePublished\":\"2008-01-15T08:04:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2008\\\/01\\\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\\\/\"},\"wordCount\":1426,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2008\\\/01\\\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2010\\\/05\\\/maintz34.jpg\",\"keywords\":[\"Accents n\u00b034\",\"Chants de Maldoror\",\"op\u00e9ra\",\"philipp maintz\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2008\\\/01\\\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2008\\\/01\\\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\\\/\",\"name\":\"Le fils aim\u00e9 de l\u2019oc\u00e9an (Lautr\u00e9amont) - entretien avec Philipp Maintz - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2008\\\/01\\\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2008\\\/01\\\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2010\\\/05\\\/maintz34.jpg\",\"datePublished\":\"2008-01-15T08:04:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/e007c9439ad786ee60c828c663f6dca9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2008\\\/01\\\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2008\\\/01\\\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2008\\\/01\\\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2010\\\/05\\\/maintz34.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2010\\\/05\\\/maintz34.jpg\",\"width\":464,\"height\":237},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2008\\\/01\\\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le fils aim\u00e9 de l\u2019oc\u00e9an (Lautr\u00e9amont) &#8211; entretien avec Philipp Maintz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/e007c9439ad786ee60c828c663f6dca9\",\"name\":\"Jean-Pierre Derrien\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c30fdbb289611b2e7586c40edf78ac3fefd4bbb9ae6b3a42fdae4c7818832139?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c30fdbb289611b2e7586c40edf78ac3fefd4bbb9ae6b3a42fdae4c7818832139?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c30fdbb289611b2e7586c40edf78ac3fefd4bbb9ae6b3a42fdae4c7818832139?s=96&d=mm&r=g\",\"caption\":\"Jean-Pierre Derrien\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/author\\\/jean-pierre-derrien\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le fils aim\u00e9 de l\u2019oc\u00e9an (Lautr\u00e9amont) - entretien avec Philipp Maintz - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/en\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/","og_locale":"en_US","og_type":"article","og_title":"Le fils aim\u00e9 de l\u2019oc\u00e9an (Lautr\u00e9amont) - entretien avec Philipp Maintz - Ensemble intercontemporain","og_description":"Pouvez-vous nous dire quel rapport entretiennent vos derni\u00e8res pi\u00e8ces (en particulier Gel\u00e4nde\/Zeichnung pour piano et \u00e9lectronique et Fluchtlinie, pour baryton et ensemble) avec la pi\u00e8ce \u00e0 venir pour -l\u2019Ensemble intercontemporain ? Dans la pi\u00e8ce pour piano et \u00e9lectronique, j\u2019ai essay\u00e9 de trouver du nouveau dans le traitement de l\u2019\u00e9lectronique. C\u2019\u00e9tait ma troisi\u00e8me pi\u00e8ce pour instrument [&hellip;]","og_url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2008-01-15T08:04:10+00:00","og_image":[{"width":464,"height":237,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2010\/05\/maintz34.jpg","type":"image\/jpeg"}],"author":"Jean-Pierre Derrien","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jean-Pierre Derrien","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/"},"author":{"name":"Jean-Pierre Derrien","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/e007c9439ad786ee60c828c663f6dca9"},"headline":"Le fils aim\u00e9 de l\u2019oc\u00e9an (Lautr\u00e9amont) &#8211; entretien avec Philipp Maintz","datePublished":"2008-01-15T08:04:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/"},"wordCount":1426,"commentCount":0,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2010\/05\/maintz34.jpg","keywords":["Accents n\u00b034","Chants de Maldoror","op\u00e9ra","philipp maintz"],"articleSection":["Entretien"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/","url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/","name":"Le fils aim\u00e9 de l\u2019oc\u00e9an (Lautr\u00e9amont) - entretien avec Philipp Maintz - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2010\/05\/maintz34.jpg","datePublished":"2008-01-15T08:04:10+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/e007c9439ad786ee60c828c663f6dca9"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2010\/05\/maintz34.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2010\/05\/maintz34.jpg","width":464,"height":237},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2008\/01\/le-fils-aime-de-locean-lautreamont-entretien-avec-philipp-maintz-par-jean-pierre-derrien-accents-n-34\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/en\/"},{"@type":"ListItem","position":2,"name":"Le fils aim\u00e9 de l\u2019oc\u00e9an (Lautr\u00e9amont) &#8211; entretien avec Philipp Maintz"}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/e007c9439ad786ee60c828c663f6dca9","name":"Jean-Pierre Derrien","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c30fdbb289611b2e7586c40edf78ac3fefd4bbb9ae6b3a42fdae4c7818832139?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c30fdbb289611b2e7586c40edf78ac3fefd4bbb9ae6b3a42fdae4c7818832139?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c30fdbb289611b2e7586c40edf78ac3fefd4bbb9ae6b3a42fdae4c7818832139?s=96&d=mm&r=g","caption":"Jean-Pierre Derrien"},"url":"https:\/\/www.ensembleintercontemporain.com\/en\/author\/jean-pierre-derrien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/1727\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/users\/44\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/comments\/?post=1727"}],"version-history":[{"count":0,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/1727\/revisions\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/3578\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/?parent=1727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/categories\/?post=1727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/tags\/?post=1727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}