{"id":11572,"date":"2018-11-12T11:37:43","date_gmt":"2018-11-12T09:37:43","guid":{"rendered":"http:\/\/www.accentsonline.fr\/?p=11572"},"modified":"2019-02-12T18:32:03","modified_gmt":"2019-02-12T17:32:03","slug":"bal-musette-et-creation-entretien-avec-melody-louledjian-soprano","status":"publish","type":"post","link":"https:\/\/www.ensembleintercontemporain.com\/en\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/","title":{"rendered":"Bal musette et cr\u00e9ation \u2014 Entretien avec Melody Louledjian, soprano"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"http:\/\/www.accentsonline.fr\/wp-content\/uploads\/2018\/10\/ML-8.jpg\" alt=\"\" width=\"492\" height=\"330\" \/><\/p>\n<p><span style=\"font-size: 12pt;\"><strong><span style=\"color: #003366;\">Melody Louledjian est une soprano pour le moins atypique. La jeune chanteuse, que l\u2019EIC accompagnera le 16 novembre prochain dans <em>Quatre Chants pour franchir le seuil<\/em>\u00a0de G\u00e9rard Grisey, \u00e9tonne autant par sa souplesse vocale que par sa personnalit\u00e9 p\u00e9tulante et l\u2019\u00e9clectisme de son r\u00e9pertoire\u2026 Rencontre.<\/span><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"font-size: 12pt;\">Melody, votre activit\u00e9 de musicienne se d\u00e9cline de mani\u00e8re surprenante\u00a0: d\u2019un c\u00f4t\u00e9, vous \u00eates soprano \u00e0 l\u2019op\u00e9ra, vous manifestez un enthousiaste certain pour les musiques d\u2019aujourd\u2019hui, et de l\u2019autre vous poussez la chansonnette des ann\u00e9es 1930 et donnez des bals musette, votre accord\u00e9on en bandouli\u00e8re\u2026<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">J\u2019ai grandi dans un environnement ou la musique et les instruments \u00e9taient tr\u00e8s pr\u00e9sents m\u00eame si mes parents ne sont \u00ab\u00a0qu\u2019amateurs\u00a0\u00bb. J\u2019ai tout de m\u00eame commenc\u00e9 tr\u00e8s t\u00f4t (je savais lire la musique avant de lire le fran\u00e7ais), par le piano, mon premier amour. Mon adolescence a \u00e9t\u00e9 marqu\u00e9e par un penchant prononc\u00e9 pour la musique romantique et post romantique\u00a0: je ne vivais que pour Chopin, Rachmaninov et Scriabine. Si je chantais d\u00e9j\u00e0 \u00e0 tue-t\u00eate la vari\u00e9t\u00e9 fran\u00e7aise depuis des ann\u00e9es \u2014\u00a0et \u00e7a m\u2019est rest\u00e9, comme vous le soulignez \u2014, ce n\u2019est qu\u2019assez tardivement que je me suis mise au chant lyrique, lorsque j\u2019ai d\u00e9couvert l\u2019op\u00e9ra vers l\u2019\u00e2ge de 16 ans.<\/span><br \/>\n<span style=\"font-size: 14pt;\">Ma premi\u00e8re professeure au Conservatoire de Nice m\u2019a imm\u00e9diatement communiqu\u00e9 l\u2019amour du chant, et tout ce que cela suppose\u00a0: jeu th\u00e9\u00e2tral, pr\u00e9sence corporelle\u2026 C\u2019\u00e9tait ludique, joyeux, passionnant\u00a0: ce cours repr\u00e9sentait pour moi une parenth\u00e8se de folie, une bouff\u00e9e d\u2019oxyg\u00e8ne, une r\u00e9cr\u00e9ation dans mes semaines tr\u00e8s studieuses.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"http:\/\/www.accentsonline.fr\/wp-content\/uploads\/2018\/10\/ML-5-2.jpg\" alt=\"\" width=\"492\" height=\"410\" \/><\/p>\n<p><span style=\"font-size: 14pt;\">Concernant la musique contemporaine, je m\u2019y int\u00e9ressais avant m\u00eame de me mettre s\u00e9rieusement au chant\u00a0: c\u2019\u00e9tait \u00e0 l\u2019occasion d\u2019un examen de piano, avec une \u0153uvre impos\u00e9e de G\u00e9rard Gastinel. J\u2019\u00e9tais enchant\u00e9e de d\u00e9couvrir cette partition si diff\u00e9rente des \u0153uvres classiques, qui a imm\u00e9diatement titill\u00e9 mon imagination\u00a0: j\u2019ai instantan\u00e9ment trouv\u00e9 dans ces musiques d\u2019aujourd\u2019hui une aire de jeu (et de \u00ab\u00a0je\u00a0\u00bb) infinie. C\u2019est un r\u00e9pertoire qui exige n\u00e9cessairement un travail et une m\u00e9thodologie efficaces (ce que j\u2019ai d\u00e9velopp\u00e9 gr\u00e2ce au solide bagage musical et \u00e0 la capacit\u00e9 pour le d\u00e9chiffrage acquis au cours de mes ann\u00e9es de piano) mais, une fois cette \u00e9tape pass\u00e9e, j\u2019y trouve une libert\u00e9 d\u2019une autre saveur, une\u00a0libert\u00e9 infinie.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"font-size: 12pt;\">Quelles \u0153uvres contemporaines aimez-vous plus particuli\u00e8rement\u00a0?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">J\u2019ai ador\u00e9 chanter les \u0153uvres (et en particulier les op\u00e9ras) de Peter E\u00f6tv\u00f6s, principalement parce qu\u2019il parvient \u00e0 des lignes de chant tr\u00e8s agr\u00e9ables \u00e0 chanter\u00a0\u2014\u00a0c\u2019est aussi le cas d\u2019un Boesmans, d\u2019un Carter ou d\u2019un Harvey\u2026 La notion de \u00ab\u00a0confort\u00a0\u00bb ou \u00ab\u00a0d\u2019agr\u00e9able \u00e0 chanter\u00a0\u00bb est pour moi tr\u00e8s importante\u00a0: notre instrument est vivant, fragile, et un passage qui ne serait pas agr\u00e9able \u00e0 chanter devient rapidement un supplice. Je ne pense\u00a0pas que la musique doive se vivre et se d\u00e9fendre dans la douleur \u2014 \u00e0 moins bien s\u00fbr que cela soit une intention d\u00e9lib\u00e9r\u00e9e du compositeur afin d\u2019obtenir une expressivit\u00e9 particuli\u00e8re, et, m\u00eame dans ce cas, je pense que c\u2019est \u00e0 employer avec parcimonie. Je ne parle bien s\u00fbr pas des difficult\u00e9s techniques, que l\u2019on trouve dans tous les r\u00e9pertoires, et qui peuvent \u00eatre palli\u00e9es par le travail et le m\u00e9tier. Selon moi, l\u2019artiste a sur sc\u00e8ne un potentiel de \u00ab\u00a0contamination\u00a0\u00bb surdimensionn\u00e9\u00a0: s\u2019il prend du plaisir, le public en prendra aussi. Mais le contraire est vrai aussi.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"http:\/\/www.accentsonline.fr\/wp-content\/uploads\/2018\/10\/ML-4-le-balcon.jpg\" alt=\"\" width=\"492\" height=\"320\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"font-size: 12pt;\">Quels sont vos plus grands souvenirs de collaboration avec des compositeurs\u00a0?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">Je parlais \u00e0 l\u2019instant de la musique de Peter E\u00f6tv\u00f6s\u00a0: il se trouve que j\u2019ai eu la chance de le rencontrer \u00e0 l\u2019Op\u00e9ra de Bordeaux \u2014 une exp\u00e9rience marquante. Tout comme mes collaborations \u00e9troites avec des compositeurs comme Yves Prin, Stefano Gervasoni ou G\u00e9rard Pesson, qui se sont d\u00e9roul\u00e9es dans des conditions id\u00e9ales\u00a0: au fil de l\u2019\u00e9laboration de l\u2019\u0153uvre, ils me demandaient des d\u00e9tails de tessitures, de phras\u00e9s ou d\u2019essayer des choses, afin de s\u2019assurer que les lignes projet\u00e9es \u00e9taient r\u00e9alisables, confortables\u2026 L\u2019interpr\u00e8te a dans ces circonstances le sentiment d\u2019apporter sa toute petite pierre \u00e0 l\u2019\u00e9difice\u00a0\u2014 pierre qui sera alors de taille lors de l\u2019ex\u00e9cution et l\u2019interpr\u00e9tation.<\/span><\/p>\n<p><strong><span style=\"font-size: 12pt;\">Vous avez d\u00e9j\u00e0 chant\u00e9 les\u00a0<em>Quatre Chants pour franchir le seuil<\/em> de G\u00e9rard Grisey, que vous chanterez \u00e0 nouveau le 16 novembre avec l\u2019EIC : quelle est votre vision de cette \u0153uvre\u00a0?<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\">Grisey y a mis quelque chose de si intime, de si personnel et en m\u00eame temps de si universel (le rapport de l\u2019homme \u00e0 la mort)\u00a0: il est important que l\u2019interpr\u00e8te y trouve, au cours du travail, une r\u00e9sonance avec sa propre intimit\u00e9. Il n\u2019est pas n\u00e9cessaire de pouvoir tout nommer\u00a0: cela peut n\u2019\u00eatre qu\u2019une \u00ab\u00a0impression\u00a0\u00bb, comme on en a souvent dans la vie. De ce point de vue, l\u2019\u0153uvre est pour moi travers\u00e9e de nombreuses impressions impalpables.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"http:\/\/www.accentsonline.fr\/wp-content\/uploads\/2018\/10\/ML-2.jpg\" alt=\"\" width=\"492\" height=\"328\" \/><\/p>\n<p><span style=\"font-size: 14pt;\">Vocalement, Grisey alterne entre une \u00e9criture que l\u2019on pourrait qualifier de tr\u00e8s vocale (comme ces magnifiques phrases qu\u2019il d\u00e9ploie dans le deuxi\u00e8me num\u00e9ro) et une \u00e9criture quasi animale, r\u00e9actionnelle, automatique. La respiration et ses diff\u00e9rentes utilisations jouent un r\u00f4le cl\u00e9\u00a0: hal\u00e8tements, respirations inspir\u00e9es de rituels de transes, et m\u00eame de larges passages en quasi-apn\u00e9e, afin d\u2019acc\u00e9der \u00e0 un effet de d\u00e9luges ou d\u2019extase\u2026 C\u2019est\u00a0gr\u00e2ce \u00e0 ces \u00ab\u00a0modes\u00a0\u00bb de respiration que l\u2019on acc\u00e8de \u00e0 l\u2019\u00e9motion du texte, au \u00ab\u00a0fond\u00a0\u00bb de l\u2019\u0153uvre, au-del\u00e0 du dicible, du verbal.<\/span><br \/>\n<span style=\"font-size: 14pt;\">Ce qui est stup\u00e9fiant, c\u2019est que Grisey ne pouvait pas imaginer une seconde que cette \u0153uvre serait terriblement pr\u00e9monitoire (m\u00eame si on peut l\u00e9gitimement se demander si, en son for int\u00e9rieur, il ne l\u2019avait pas pressenti), puisqu\u2019il mourra brutalement tr\u00e8s peu de temps apr\u00e8s son ach\u00e8vement. Cela semble un d\u00e9tail, mais je ne pense pas qu\u2019on puisse le n\u00e9gliger lorsqu\u2019on consid\u00e8re l\u2019\u0153uvre, et la profondeur de son discours.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Photos 1 et 4 \u00a9 Miguel Barreto \/ Autres photos \u00a9 DR<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Melody Louledjian est une soprano pour le moins atypique. La jeune chanteuse, que l\u2019EIC accompagnera le 16 novembre prochain dans <em>Quatre Chants pour franchir le seuil <\/em>\u00a0de G\u00e9rard Grisey, \u00e9tonne autant par sa souplesse vocale que par sa personnalit\u00e9 p\u00e9tulante et l\u2019\u00e9clectisme de son r\u00e9pertoire\u2026 Rencontre.<\/p>\n","protected":false},"author":5,"featured_media":11587,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[356,796,103],"class_list":["post-11572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretiens","tag-chant","tag-melody-louledjian","tag-quatre-chants-pour-franchir-le-seuil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bal musette et cr\u00e9ation \u2014 Entretien avec Melody Louledjian, soprano - Ensemble intercontemporain<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ensembleintercontemporain.com\/en\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bal musette et cr\u00e9ation \u2014 Entretien avec Melody Louledjian, soprano - Ensemble intercontemporain\" \/>\n<meta property=\"og:description\" content=\"Melody Louledjian est une soprano pour le moins atypique. La jeune chanteuse, que l\u2019EIC accompagnera le 16 novembre prochain dans Quatre Chants pour franchir le seuil \u00a0de G\u00e9rard Grisey, \u00e9tonne autant par sa souplesse vocale que par sa personnalit\u00e9 p\u00e9tulante et l\u2019\u00e9clectisme de son r\u00e9pertoire\u2026 Rencontre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/\" \/>\n<meta property=\"og:site_name\" content=\"Ensemble intercontemporain\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-12T09:37:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-12T17:32:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2018\/10\/ML-une-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"464\" \/>\n\t<meta property=\"og:image:height\" content=\"237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\u00e9remie Szpirglas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\u00e9remie Szpirglas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2018\\\/11\\\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2018\\\/11\\\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\\\/\"},\"author\":{\"name\":\"J\u00e9remie Szpirglas\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/439a7dd5cd8a167c34c931d7cc900214\"},\"headline\":\"Bal musette et cr\u00e9ation \u2014 Entretien avec Melody Louledjian, soprano\",\"datePublished\":\"2018-11-12T09:37:43+00:00\",\"dateModified\":\"2019-02-12T17:32:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2018\\\/11\\\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\\\/\"},\"wordCount\":1114,\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2018\\\/11\\\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2018\\\/10\\\/ML-une-2.jpg\",\"keywords\":[\"chant\",\"Melody Louledjian\",\"Quatre chants pour franchir le Seuil\"],\"articleSection\":[\"Entretien\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2018\\\/11\\\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\\\/\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2018\\\/11\\\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\\\/\",\"name\":\"Bal musette et cr\u00e9ation \u2014 Entretien avec Melody Louledjian, soprano - Ensemble intercontemporain\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2018\\\/11\\\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2018\\\/11\\\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2018\\\/10\\\/ML-une-2.jpg\",\"datePublished\":\"2018-11-12T09:37:43+00:00\",\"dateModified\":\"2019-02-12T17:32:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/439a7dd5cd8a167c34c931d7cc900214\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2018\\\/11\\\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2018\\\/11\\\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2018\\\/11\\\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2018\\\/10\\\/ML-une-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/content\\\/uploads\\\/2018\\\/10\\\/ML-une-2.jpg\",\"width\":464,\"height\":237},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/fr\\\/2018\\\/11\\\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bal musette et cr\u00e9ation \u2014 Entretien avec Melody Louledjian, soprano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/\",\"name\":\"Ensemble intercontemporain\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/#\\\/schema\\\/person\\\/439a7dd5cd8a167c34c931d7cc900214\",\"name\":\"J\u00e9remie Szpirglas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g\",\"caption\":\"J\u00e9remie Szpirglas\"},\"url\":\"https:\\\/\\\/www.ensembleintercontemporain.com\\\/en\\\/author\\\/benjamin-szpirglas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bal musette et cr\u00e9ation \u2014 Entretien avec Melody Louledjian, soprano - Ensemble intercontemporain","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ensembleintercontemporain.com\/en\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/","og_locale":"en_US","og_type":"article","og_title":"Bal musette et cr\u00e9ation \u2014 Entretien avec Melody Louledjian, soprano - Ensemble intercontemporain","og_description":"Melody Louledjian est une soprano pour le moins atypique. La jeune chanteuse, que l\u2019EIC accompagnera le 16 novembre prochain dans Quatre Chants pour franchir le seuil \u00a0de G\u00e9rard Grisey, \u00e9tonne autant par sa souplesse vocale que par sa personnalit\u00e9 p\u00e9tulante et l\u2019\u00e9clectisme de son r\u00e9pertoire\u2026 Rencontre.","og_url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/","og_site_name":"Ensemble intercontemporain","article_published_time":"2018-11-12T09:37:43+00:00","article_modified_time":"2019-02-12T17:32:03+00:00","og_image":[{"width":464,"height":237,"url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2018\/10\/ML-une-2.jpg","type":"image\/jpeg"}],"author":"J\u00e9remie Szpirglas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"J\u00e9remie Szpirglas","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/#article","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/"},"author":{"name":"J\u00e9remie Szpirglas","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/439a7dd5cd8a167c34c931d7cc900214"},"headline":"Bal musette et cr\u00e9ation \u2014 Entretien avec Melody Louledjian, soprano","datePublished":"2018-11-12T09:37:43+00:00","dateModified":"2019-02-12T17:32:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/"},"wordCount":1114,"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2018\/10\/ML-une-2.jpg","keywords":["chant","Melody Louledjian","Quatre chants pour franchir le Seuil"],"articleSection":["Entretien"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/","url":"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/","name":"Bal musette et cr\u00e9ation \u2014 Entretien avec Melody Louledjian, soprano - Ensemble intercontemporain","isPartOf":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/#primaryimage"},"image":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2018\/10\/ML-une-2.jpg","datePublished":"2018-11-12T09:37:43+00:00","dateModified":"2019-02-12T17:32:03+00:00","author":{"@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/439a7dd5cd8a167c34c931d7cc900214"},"breadcrumb":{"@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/#primaryimage","url":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2018\/10\/ML-une-2.jpg","contentUrl":"https:\/\/www.ensembleintercontemporain.com\/content\/uploads\/2018\/10\/ML-une-2.jpg","width":464,"height":237},{"@type":"BreadcrumbList","@id":"https:\/\/www.ensembleintercontemporain.com\/fr\/2018\/11\/bal-musette-et-creation-entretien-avec-melody-louledjian-soprano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ensembleintercontemporain.com\/en\/"},{"@type":"ListItem","position":2,"name":"Bal musette et cr\u00e9ation \u2014 Entretien avec Melody Louledjian, soprano"}]},{"@type":"WebSite","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#website","url":"https:\/\/www.ensembleintercontemporain.com\/en\/","name":"Ensemble intercontemporain","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ensembleintercontemporain.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.ensembleintercontemporain.com\/en\/#\/schema\/person\/439a7dd5cd8a167c34c931d7cc900214","name":"J\u00e9remie Szpirglas","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51406c8ec861211e1bd97cfab9a482b48101946652a6a78f911670a9a593f3ed?s=96&d=mm&r=g","caption":"J\u00e9remie Szpirglas"},"url":"https:\/\/www.ensembleintercontemporain.com\/en\/author\/benjamin-szpirglas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/11572\/"}],"collection":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/users\/5\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/comments\/?post=11572"}],"version-history":[{"count":6,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/11572\/revisions\/"}],"predecessor-version":[{"id":15682,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/posts\/11572\/revisions\/15682\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/11587\/"}],"wp:attachment":[{"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/media\/?parent=11572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/categories\/?post=11572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ensembleintercontemporain.com\/en\/wp-json\/wp\/v2\/tags\/?post=11572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}